{"id":9843,"date":"2019-04-12T16:47:50","date_gmt":"2019-04-12T14:47:50","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=9843"},"modified":"2019-04-12T16:48:31","modified_gmt":"2019-04-12T14:48:31","slug":"reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/","title":{"rendered":"Reddito di cittadinanza: Ciociaria prima per numero di domande"},"content":{"rendered":"<p>Reddito di cittadinanza:<strong> tra le cinque province del Lazio quella di Frosinone \u00e8 la prima<\/strong> per il maggior numero di domande. A rivelarlo i dati pubblicati oggi, relativi al numero di richieste presentate in Italia.<\/p>\n<p><strong>Nel Lazio, ogni 1.000 abitanti sono 16,32 le domande presentate in provincia di Frosinone<\/strong>; seguita subito dopo dalla provincia di Rieti (15,02) e da quella di Latina con 14,56. Penultima la provincia di Viterbo, dove ogni mille abitanti vengono presentate in media 13,45 domande e, infine, Roma che presenta il valore pi\u00f9 basso con 11,67 domande.<\/p>\n<h2>L\u2019analisi di Danilo Magliocchetti<\/h2>\n<p>&#8220;Al di l\u00e0 dell\u2019opportunit\u00e0 che, comunque, offre il reddito di cittadinanza per molti, &#8211; sottolinea il <strong>consigliere comunale di Frosinone, Danilo Magliocchetti<\/strong> &#8211; il numero delle domande presentate in provincia di Frosinone, credo testimoniano, concretamente e senza dubbio, il <strong>momento di grande difficolt\u00e0 economica<\/strong> che stanno attraversando tante, troppe famiglie&#8221;.<\/p>\n<p>&#8220;Si tratta ormai di una crisi strutturale e prolungata, determinata in larga parte dalla mancanza di lavoro, in seguito alla <strong>chiusura di tantissimi insediamenti produttivi<\/strong>, che non hanno avuto alcun genere di ricambio occupazionale in altri settori. <strong>Si tratta di un vero e proprio dramma sociale<\/strong>, testimoniato dai numeri, del quale bisogna prendere una volta per tutte consapevolezza&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_3330\" aria-describedby=\"caption-attachment-3330\" style=\"width: 621px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3330 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/danilo-magliocchetti.jpg\" alt=\"danilo magliocchetti frosinone ciociaria\" width=\"621\" height=\"434\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/danilo-magliocchetti.jpg 621w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/danilo-magliocchetti-300x210.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/danilo-magliocchetti-500x349.jpg 500w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/danilo-magliocchetti-130x90.jpg 130w\" sizes=\"auto, (max-width: 621px) 100vw, 621px\" \/><figcaption id=\"caption-attachment-3330\" class=\"wp-caption-text\">Il consigliere comunale di Frosinone Danilo Magliocchetti<\/figcaption><\/figure>\n<h2>Ancora nessuna occasione dall&#8217;Area di crisi<\/h2>\n<p>&#8220;<strong>Il riconoscimento di area di crisi industriale complessa<\/strong> della zona nord della provincia, &#8211; conclude Magliocchetti &#8211; per quanto importante, non ha ancora prodotto un solo posto di lavoro, come nessuna opportunit\u00e0 ha ancora creato il necessario, ma ancora lontano, processo di bonifica della Valle del Sacco, e questo la dice lunga di come anche una burocrazia elefantiaca, stia contribuendo letteralmente a massacrare il territorio&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Reddito di cittadinanza: tra le cinque province del Lazio quella di Frosinone \u00e8 la prima per il maggior numero di<\/p>\n","protected":false},"author":18,"featured_media":9848,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[580,94,155,858,930,93,279,2433,3609],"class_list":["post-9843","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-economia","tag-area-di-crisi","tag-ciociaria","tag-crisi","tag-danilo-magliocchetti","tag-domande","tag-frosinone","tag-lavoro","tag-province","tag-reddito-di-cittadinanza"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Reddito di cittadinanza: Ciociaria prima per numero di domande - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Tra le cinque province del Lazio quella di Frosinone risulta essere al primo posto per domande sul reddito di cittadinanza: l&#039;analisi di Magliocchetti\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reddito di cittadinanza: Ciociaria prima per numero di domande\" \/>\n<meta property=\"og:description\" content=\"Tra le cinque province del Lazio quella di Frosinone risulta essere al primo posto per domande sul reddito di cittadinanza: l&#039;analisi di Magliocchetti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-12T14:47:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-12T14:48:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/reddito-cittadinanza-e1555080256658.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"431\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/12\\\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/12\\\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Reddito di cittadinanza: Ciociaria prima per numero di domande\",\"datePublished\":\"2019-04-12T14:47:50+00:00\",\"dateModified\":\"2019-04-12T14:48:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/12\\\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\\\/\"},\"wordCount\":294,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/12\\\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/reddito-cittadinanza-e1555080256658.jpg\",\"keywords\":[\"area di crisi\",\"Ciociaria\",\"crisi\",\"danilo magliocchetti\",\"domande\",\"Frosinone\",\"lavoro\",\"Province\",\"reddito di cittadinanza\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/12\\\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/12\\\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\\\/\",\"name\":\"Reddito di cittadinanza: Ciociaria prima per numero di domande - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/12\\\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/12\\\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/reddito-cittadinanza-e1555080256658.jpg\",\"datePublished\":\"2019-04-12T14:47:50+00:00\",\"dateModified\":\"2019-04-12T14:48:31+00:00\",\"description\":\"Tra le cinque province del Lazio quella di Frosinone risulta essere al primo posto per domande sul reddito di cittadinanza: l'analisi di Magliocchetti\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/12\\\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/12\\\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/12\\\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/reddito-cittadinanza-e1555080256658.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/reddito-cittadinanza-e1555080256658.jpg\",\"width\":632,\"height\":431,\"caption\":\"reddito cittadinanza il corriere della provincia\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/12\\\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reddito di cittadinanza: Ciociaria prima per numero di domande\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/12\\\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/12\\\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/12\\\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Reddito di cittadinanza: Ciociaria prima per numero di domande - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Tra le cinque province del Lazio quella di Frosinone risulta essere al primo posto per domande sul reddito di cittadinanza: l'analisi di Magliocchetti","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/","og_locale":"it_IT","og_type":"article","og_title":"Reddito di cittadinanza: Ciociaria prima per numero di domande","og_description":"Tra le cinque province del Lazio quella di Frosinone risulta essere al primo posto per domande sul reddito di cittadinanza: l'analisi di Magliocchetti","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-04-12T14:47:50+00:00","article_modified_time":"2019-04-12T14:48:31+00:00","og_image":[{"width":632,"height":431,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/reddito-cittadinanza-e1555080256658.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Reddito di cittadinanza: Ciociaria prima per numero di domande","datePublished":"2019-04-12T14:47:50+00:00","dateModified":"2019-04-12T14:48:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/"},"wordCount":294,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/reddito-cittadinanza-e1555080256658.jpg","keywords":["area di crisi","Ciociaria","crisi","danilo magliocchetti","domande","Frosinone","lavoro","Province","reddito di cittadinanza"],"articleSection":["*PRIMO PIANO*","Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/","name":"Reddito di cittadinanza: Ciociaria prima per numero di domande - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/reddito-cittadinanza-e1555080256658.jpg","datePublished":"2019-04-12T14:47:50+00:00","dateModified":"2019-04-12T14:48:31+00:00","description":"Tra le cinque province del Lazio quella di Frosinone risulta essere al primo posto per domande sul reddito di cittadinanza: l'analisi di Magliocchetti","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/reddito-cittadinanza-e1555080256658.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/reddito-cittadinanza-e1555080256658.jpg","width":632,"height":431,"caption":"reddito cittadinanza il corriere della provincia"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Reddito di cittadinanza: Ciociaria prima per numero di domande"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/12\/reddito-di-cittadinanza-nel-lazio-ciociaria-prima-per-numero-di-domande\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/9843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=9843"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/9843\/revisions"}],"predecessor-version":[{"id":9851,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/9843\/revisions\/9851"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/9848"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=9843"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=9843"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=9843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}