{"id":9607,"date":"2019-04-08T19:14:34","date_gmt":"2019-04-08T17:14:34","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=9607"},"modified":"2019-04-08T19:14:34","modified_gmt":"2019-04-08T17:14:34","slug":"massimiliano-quadrini-rieletti-limpegno-e-la-concretezza","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/","title":{"rendered":"Massimiliano Quadrini: rieletti l\u2019impegno e la concretezza"},"content":{"rendered":"<p>Anche il <strong>capogruppo di maggioranza di Isola del Liri<\/strong> e <strong>candidato sindaco alle amministrative<\/strong> del 26 maggio, <strong>Massimiliano Quadrini<\/strong>, \u00e8 stato rieletto nel consiglio provinciale di Frosinone. L\u2019esponente del Partito Democratico incassa dunque, il placet del territorio ciociaro e mantiene, di fatto, la citt\u00e0 di Isola del Liri rappresentata nell\u2019Ente guidato da Antonio Pompeo.<\/p>\n<h2>Le dichiarazioni<\/h2>\n<p>&#8220;Ringrazio i consiglieri comunali e i sindaci che mi hanno sostenuto anche in questa tornata, per la terza volta consecutiva\u00a0 \u2013 ha detto Massimiliano Quadrini \u2013 <strong>Ad essere \u2018promossa\u2019, ne sono convinto, \u00e8 la politica messa in campo finora<\/strong>, fatta di impegno e concretezza. \u00c8 un risultato importante che mi sprona a fare sempre meglio. \u00c8 motivo di orgoglio continuare a vedere rappresentata la mia citt\u00e0, Isola del Liri che \u2013 ha aggiunto ancora Quadrini &#8211; ha uno dei <strong>4 seggi conquistati dal Partito Democratico<\/strong>, insieme a Frosinone (2) e Veroli&#8221;.<\/p>\n<h2>&#8220;Il Pd resta ancora un partito credibile&#8221;<\/h2>\n<p>&#8220;Il Partito Democratico in provincia di Frosinone si riconferma forte e credibile nonostante una flessione a livello nazionale che si ripercuote inevitabilmente anche qui. Sono pi\u00f9 che soddisfatto \u2013 ha aggiunto Massimiliano Quadrini \u2013 e ringrazio ancora i consiglieri\u00a0 e i sindaciche mi hanno sostenuto. C\u2019\u00e8 tanto da fare, per la provincia di Frosinone e per Isola del Liri, la mia citt\u00e0, dove concorro per la carica di sindaco. L\u2019impegno resta massimo&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche il capogruppo di maggioranza di Isola del Liri e candidato sindaco alle amministrative del 26 maggio, Massimiliano Quadrini, \u00e8<\/p>\n","protected":false},"author":18,"featured_media":9608,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[1018,260,1775,1191,3509,2783],"class_list":["post-9607","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-consiglio-provinciale","tag-isola-del-liri","tag-massimiliano-quadrini","tag-partito-democratico","tag-rielezione","tag-seggi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Massimiliano Quadrini: rieletti l\u2019impegno e la concretezza - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Anche il capogruppo di maggioranza di Isola del Liri e candidato sindaco, Massimiliano Quadrini, \u00e8 stato rieletto nel consiglio provinciale\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Massimiliano Quadrini: rieletti l\u2019impegno e la concretezza\" \/>\n<meta property=\"og:description\" content=\"Anche il capogruppo di maggioranza di Isola del Liri e candidato sindaco, Massimiliano Quadrini, \u00e8 stato rieletto nel consiglio provinciale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-08T17:14:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/massimiliano-quadrini-e1554743602451.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"421\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/08\\\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/08\\\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Massimiliano Quadrini: rieletti l\u2019impegno e la concretezza\",\"datePublished\":\"2019-04-08T17:14:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/08\\\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\\\/\"},\"wordCount\":225,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/08\\\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/massimiliano-quadrini-e1554743602451.jpg\",\"keywords\":[\"consiglio provinciale\",\"isola del liri\",\"massimiliano quadrini\",\"partito democratico\",\"rielezione\",\"seggi\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/08\\\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/08\\\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\\\/\",\"name\":\"Massimiliano Quadrini: rieletti l\u2019impegno e la concretezza - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/08\\\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/08\\\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/massimiliano-quadrini-e1554743602451.jpg\",\"datePublished\":\"2019-04-08T17:14:34+00:00\",\"description\":\"Anche il capogruppo di maggioranza di Isola del Liri e candidato sindaco, Massimiliano Quadrini, \u00e8 stato rieletto nel consiglio provinciale\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/08\\\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/08\\\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/08\\\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/massimiliano-quadrini-e1554743602451.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/massimiliano-quadrini-e1554743602451.jpg\",\"width\":632,\"height\":421,\"caption\":\"Massimiliano Quadrini\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/08\\\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Massimiliano Quadrini: rieletti l\u2019impegno e la concretezza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/08\\\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/08\\\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/08\\\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Massimiliano Quadrini: rieletti l\u2019impegno e la concretezza - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Anche il capogruppo di maggioranza di Isola del Liri e candidato sindaco, Massimiliano Quadrini, \u00e8 stato rieletto nel consiglio provinciale","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/","og_locale":"it_IT","og_type":"article","og_title":"Massimiliano Quadrini: rieletti l\u2019impegno e la concretezza","og_description":"Anche il capogruppo di maggioranza di Isola del Liri e candidato sindaco, Massimiliano Quadrini, \u00e8 stato rieletto nel consiglio provinciale","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-04-08T17:14:34+00:00","og_image":[{"width":632,"height":421,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/massimiliano-quadrini-e1554743602451.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Massimiliano Quadrini: rieletti l\u2019impegno e la concretezza","datePublished":"2019-04-08T17:14:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/"},"wordCount":225,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/massimiliano-quadrini-e1554743602451.jpg","keywords":["consiglio provinciale","isola del liri","massimiliano quadrini","partito democratico","rielezione","seggi"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/","name":"Massimiliano Quadrini: rieletti l\u2019impegno e la concretezza - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/massimiliano-quadrini-e1554743602451.jpg","datePublished":"2019-04-08T17:14:34+00:00","description":"Anche il capogruppo di maggioranza di Isola del Liri e candidato sindaco, Massimiliano Quadrini, \u00e8 stato rieletto nel consiglio provinciale","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/massimiliano-quadrini-e1554743602451.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/massimiliano-quadrini-e1554743602451.jpg","width":632,"height":421,"caption":"Massimiliano Quadrini"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Massimiliano Quadrini: rieletti l\u2019impegno e la concretezza"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/08\/massimiliano-quadrini-rieletti-limpegno-e-la-concretezza\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/9607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=9607"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/9607\/revisions"}],"predecessor-version":[{"id":9609,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/9607\/revisions\/9609"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/9608"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=9607"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=9607"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=9607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}