{"id":950,"date":"2018-11-02T14:59:00","date_gmt":"2018-11-02T13:59:00","guid":{"rendered":"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=950"},"modified":"2018-11-05T14:59:05","modified_gmt":"2018-11-05T13:59:05","slug":"sondaggi-salvini-il-piu-amato-dagli-italiani","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/","title":{"rendered":"Sondaggi, Salvini \u00e8 il pi\u00f9 amato dagli italiani"},"content":{"rendered":"<p><strong>Il primo partito <\/strong>nelle intenzioni di voto degli italiani<strong> \u00e8 la Lega che,<\/strong> continua a gravitare intorno a quota 30 per cento. Matteo Salvini il lader pi\u00f9 amato, M5S in calo.<\/p>\n<p>Sono i risultati del sondaggio realizzato da Demos per <em>la Repubblica<\/em>, secondo cui a cinque mesi dalle politiche del 4 marzo<strong> il Carroccio \u00e8 l\u2019unico partito che cresce, fagocitando gli altri.<\/strong> <strong>Anche il Movimento 5 stelle, sceso nella rilevazione al 27,6%, cinque punti sotto il risultato delle urne<\/strong>. Allo stesso modo<strong> Salvini \u00e8 il leader pi\u00f9 gradito dagli intervistati: 60%<\/strong>.<\/p>\n<h2><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-951 size-full\" src=\"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/sondaggi-elettorali-Demos-partiti.jpg\" alt=\"\" width=\"600\" height=\"539\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/sondaggi-elettorali-Demos-partiti.jpg 600w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/sondaggi-elettorali-Demos-partiti-300x270.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/sondaggi-elettorali-Demos-partiti-500x449.jpg 500w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/h2>\n<h2>Il pi\u00f9 amato dagli italiani<\/h2>\n<p>Il ministro dell\u2019Interno si conferma come il <strong>\u201ccapo percepito\u201d<\/strong> nella coalizione. Pi\u00f9 di un italiano su due crede che sia lui a comandare. In generale per\u00f2, a cinque mesi dall\u2019avvio dell\u2019esecutivo gialloverde, il gradimento verso il governo resta altissimo: rispetto a settembre, c\u2019\u00e8 comunque una leggera flessione dal 62 al 58 per cento. Un po\u2019 pi\u00f9 incerti i giudizi sulla manovra: pi\u00f9 di un italiano su due ritiene almeno \u201cutile\u201d il reddito di cittadinanza, ma in generale i voti positivi e negativi sulla legge di bilancio si equivalgono.<\/p>\n<p>Se oggi si tornasse alle urne, <strong>uno su tre degli intervistati da Demos sceglierebbe la Lega<\/strong>. Continua invece la flessione del M5s, distante due e punti mezzo dal Carroccio e in calo anche rispetto al 29,4% di un mese fa. Ma <strong>perdono anche tutti gli altri partiti: il Pd \u00e8 stimato al 16,5%<\/strong> e non riesce ad arginare la perdita di consenso che l\u2019ha portato ora due punti percentuali sotto il risultato, gi\u00e0 disastroso, del 4 marzo. Cos\u00ec come <strong>continua ad assottigliarsi la base di voti di Forza Italia, scesa fino al 9,4%<\/strong> secondo Demos.<strong> Al 3,1% ci sono Liberi e uguali e Fratelli d\u2019Italia<\/strong> che per\u00f2 erano andati entrambi meglio alle politiche, cos\u00ec come <strong>Pi\u00f9 Europa stimata al 2,3 per cento<\/strong>. Cresce invece <strong>Potere al Popolo, stimato al 2,3%<\/strong>: sarebbe il doppio del risultato ottenuto il 4 marzo.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_952\" aria-describedby=\"caption-attachment-952\" style=\"width: 318px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-952 size-full\" src=\"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/zingaretti-Nicola.jpg\" alt=\"\" width=\"318\" height=\"159\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/zingaretti-Nicola.jpg 318w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/zingaretti-Nicola-300x150.jpg 300w\" sizes=\"auto, (max-width: 318px) 100vw, 318px\" \/><figcaption id=\"caption-attachment-952\" class=\"wp-caption-text\">Nicola Zingaretti<\/figcaption><\/figure>\n<h3>Segreteria del Pd, Zingaretti al 40%<\/h3>\n<p>Anche il premier<strong> Conte per\u00f2 \u00e8 apprezzato dal 59<\/strong>% degli intervistati da Demos, cos\u00ec come <strong>raccoglie il 58% dei voti positivi anche il presidente della Bce, Mario Draghi<\/strong>. Chi lo ha attaccato per le sue ultime dichiarazioni, <strong>Luigi Di Maio, \u00e8 invece sceso al 53% degli apprezzamenti rispetto al 57% di settembre<\/strong>. Rimango livelli di gradimento elevati rispetto a quelli degli altri leader, tra cui si difendono solo l\u2019ex premier Paolo Gentiloni con il 48% ed Emma Bonino con il 46%.<strong> Per trovare i prossimi candidati alla segreteria Pd<\/strong> bisogna invece scendere <strong>al 40% di Nicola Zingaretti<\/strong> o al 38% di Marco Minniti. Fanalini di coda della classifica, dietro anche ad <strong>Antonio Tajani<\/strong>, Alessandro Di Battista e Maurizio Martina, ci sono coloro che fino a pochi anni fa erano i leader dei tre poli politici italiani: terzultimo Silvio Berlusconi (30%), penultimo Beppe Grillo (26%) e<strong> fanalino di coda Matteo Renzi, con appena il 24% dei voti positivi.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il primo partito nelle intenzioni di voto degli italiani \u00e8 la Lega che, continua a gravitare intorno a quota 30<\/p>\n","protected":false},"author":3,"featured_media":956,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,28],"tags":[294,295,297,296,293],"class_list":["post-950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-politica","tag-demos","tag-lega","tag-partito","tag-primo","tag-sondaggio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sondaggi, Salvini \u00e8 il pi\u00f9 amato dagli italiani - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Sono i risultati del sondaggio realizzato da Demos secondo cui a cinque mesi dalle politiche del 4 marzo il Carroccio \u00e8 l\u2019unico partito che cresce.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sondaggi, Salvini \u00e8 il pi\u00f9 amato dagli italiani\" \/>\n<meta property=\"og:description\" content=\"Sono i risultati del sondaggio realizzato da Demos secondo cui a cinque mesi dalle politiche del 4 marzo il Carroccio \u00e8 l\u2019unico partito che cresce.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/TuNews24\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-02T13:59:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-05T13:59:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/matteo-salvini-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"597\" \/>\n\t<meta property=\"og:image:height\" content=\"336\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Trento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Trento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/02\\\/sondaggi-salvini-il-piu-amato-dagli-italiani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/02\\\/sondaggi-salvini-il-piu-amato-dagli-italiani\\\/\"},\"author\":{\"name\":\"Gianluca Trento\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\"},\"headline\":\"Sondaggi, Salvini \u00e8 il pi\u00f9 amato dagli italiani\",\"datePublished\":\"2018-11-02T13:59:00+00:00\",\"dateModified\":\"2018-11-05T13:59:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/02\\\/sondaggi-salvini-il-piu-amato-dagli-italiani\\\/\"},\"wordCount\":479,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/02\\\/sondaggi-salvini-il-piu-amato-dagli-italiani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/matteo-salvini-1.jpg\",\"keywords\":[\"Demos\",\"Lega\",\"Partito\",\"Primo\",\"Sondaggio\"],\"articleSection\":[\"*SLIDE*\",\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/02\\\/sondaggi-salvini-il-piu-amato-dagli-italiani\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/02\\\/sondaggi-salvini-il-piu-amato-dagli-italiani\\\/\",\"name\":\"Sondaggi, Salvini \u00e8 il pi\u00f9 amato dagli italiani - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/02\\\/sondaggi-salvini-il-piu-amato-dagli-italiani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/02\\\/sondaggi-salvini-il-piu-amato-dagli-italiani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/matteo-salvini-1.jpg\",\"datePublished\":\"2018-11-02T13:59:00+00:00\",\"dateModified\":\"2018-11-05T13:59:05+00:00\",\"description\":\"Sono i risultati del sondaggio realizzato da Demos secondo cui a cinque mesi dalle politiche del 4 marzo il Carroccio \u00e8 l\u2019unico partito che cresce.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/02\\\/sondaggi-salvini-il-piu-amato-dagli-italiani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/02\\\/sondaggi-salvini-il-piu-amato-dagli-italiani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/02\\\/sondaggi-salvini-il-piu-amato-dagli-italiani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/matteo-salvini-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/11\\\/matteo-salvini-1.jpg\",\"width\":597,\"height\":336,\"caption\":\"Matteo Salvini\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/02\\\/sondaggi-salvini-il-piu-amato-dagli-italiani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sondaggi, Salvini \u00e8 il pi\u00f9 amato dagli italiani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/02\\\/sondaggi-salvini-il-piu-amato-dagli-italiani\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/02\\\/sondaggi-salvini-il-piu-amato-dagli-italiani\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\",\"name\":\"Gianluca Trento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"caption\":\"Gianluca Trento\"},\"description\":\"Giornalista dei quotidiani online \\\"LaProvinciaQuotidiano.it\\\" e \\\"TuNews24.it\\\" e del settimanale cartaceo \\\"Tu News\\\". In passato \u00e8 stato anche Direttore Editoriale de \\\"La Provincia\\\", Direttore Responsabile del quotidiano \\\"Ciociaria Oggi\\\", Condirettore de \\\"Il quotidiano della Ciociaria\\\", giornalista di \\\"Paese Sera\\\", del settimanale \\\"L\u2019Inchiesta\\\" e del quotidiano online \\\"Il Corriere della Provincia\\\".\",\"sameAs\":[\"https:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/TuNews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/gianluca\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/11\\\/02\\\/sondaggi-salvini-il-piu-amato-dagli-italiani\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sondaggi, Salvini \u00e8 il pi\u00f9 amato dagli italiani - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Sono i risultati del sondaggio realizzato da Demos secondo cui a cinque mesi dalle politiche del 4 marzo il Carroccio \u00e8 l\u2019unico partito che cresce.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/","og_locale":"it_IT","og_type":"article","og_title":"Sondaggi, Salvini \u00e8 il pi\u00f9 amato dagli italiani","og_description":"Sono i risultati del sondaggio realizzato da Demos secondo cui a cinque mesi dalle politiche del 4 marzo il Carroccio \u00e8 l\u2019unico partito che cresce.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/TuNews24","article_published_time":"2018-11-02T13:59:00+00:00","article_modified_time":"2018-11-05T13:59:05+00:00","og_image":[{"width":597,"height":336,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/matteo-salvini-1.jpg","type":"image\/jpeg"}],"author":"Gianluca Trento","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Gianluca Trento","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/"},"author":{"name":"Gianluca Trento","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd"},"headline":"Sondaggi, Salvini \u00e8 il pi\u00f9 amato dagli italiani","datePublished":"2018-11-02T13:59:00+00:00","dateModified":"2018-11-05T13:59:05+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/"},"wordCount":479,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/matteo-salvini-1.jpg","keywords":["Demos","Lega","Partito","Primo","Sondaggio"],"articleSection":["*SLIDE*","Evidenza"],"inLanguage":"it-IT","copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/","name":"Sondaggi, Salvini \u00e8 il pi\u00f9 amato dagli italiani - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/matteo-salvini-1.jpg","datePublished":"2018-11-02T13:59:00+00:00","dateModified":"2018-11-05T13:59:05+00:00","description":"Sono i risultati del sondaggio realizzato da Demos secondo cui a cinque mesi dalle politiche del 4 marzo il Carroccio \u00e8 l\u2019unico partito che cresce.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/matteo-salvini-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/matteo-salvini-1.jpg","width":597,"height":336,"caption":"Matteo Salvini"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Sondaggi, Salvini \u00e8 il pi\u00f9 amato dagli italiani"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd","name":"Gianluca Trento","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","caption":"Gianluca Trento"},"description":"Giornalista dei quotidiani online \"LaProvinciaQuotidiano.it\" e \"TuNews24.it\" e del settimanale cartaceo \"Tu News\". In passato \u00e8 stato anche Direttore Editoriale de \"La Provincia\", Direttore Responsabile del quotidiano \"Ciociaria Oggi\", Condirettore de \"Il quotidiano della Ciociaria\", giornalista di \"Paese Sera\", del settimanale \"L\u2019Inchiesta\" e del quotidiano online \"Il Corriere della Provincia\".","sameAs":["https:\/\/www.tunews24.it","http:\/\/www.facebook.com\/TuNews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/gianluca\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/11\/02\/sondaggi-salvini-il-piu-amato-dagli-italiani\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=950"}],"version-history":[{"count":5,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/950\/revisions"}],"predecessor-version":[{"id":1061,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/950\/revisions\/1061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/956"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}