{"id":9458,"date":"2019-04-07T08:00:10","date_gmt":"2019-04-07T06:00:10","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=9458"},"modified":"2019-04-07T08:28:26","modified_gmt":"2019-04-07T06:28:26","slug":"consiglio-provinciale-oggi-scatta-la-sfida","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/","title":{"rendered":"Consiglio provinciale, oggi la sfida. Tutti i candidati"},"content":{"rendered":"<p><strong>Sei le formazioni che oggi si sfideranno per il rinnovo del consiglio provinciale <\/strong>di Frosinone. Sindaci e consiglieri andranno alle urne dalla 8.00 alle 20.00.<\/p>\n<h2>Il saluto di Pompeo<\/h2>\n<p>&#8220;Voglio salutare &#8211; ha evidenziato il presidente della Provincia &#8211; tutti i consiglieri che mi hanno accompagnato in questi due anni, con impegno e responsabilit\u00e0.<strong> Hanno dimostrato di essere amministratori capaci<\/strong>, al servizio del territorio. Da ciascuno di loro ho avuto tanto, in termini di lavoro e di vicinanza. Ma soprattutto sul lato umano, che per me \u00e8 fondamentale. A loro va il mio grazie&#8221;.<\/p>\n<h2><strong>Il Pd in campo con una lista \u2018pura\u2019<\/strong><\/h2>\n<p>Cos\u00ec come chiesto espressamente dal segretario provinciale, Domenico Alfieri, i candidati del Pd sono scesi in campo con simbolo e nome del partito.<\/p>\n<p>Questi i candidati: <strong>Vincenzo Savo <\/strong>di Frosinone, <strong>Domenico Alfieri <\/strong>di Paliano, <strong>Germano Caperna<\/strong> di Veroli, <strong>Ermelinda Costa <\/strong>di Piedimonte San Germano, <strong>Alessandro D\u2019Alessandro<\/strong> di Vallemaio<strong>,<\/strong><strong>Antonio Di Nota <\/strong>di Colle San Magno, <strong>Fiorella Gazzellone <\/strong>di Terelle, <strong>Massimiliano Quadrini <\/strong>di Isola del Liri, <strong>Tommasina Raponi <\/strong>di Alatri, <strong>Alessandra Sardellitti<\/strong> di Frosinone,<strong> Ausilia Vitti <\/strong>di Settefrati e <strong>Gianfranco Volante d<\/strong>i Gallinaro.<\/p>\n<h2>FdI e FI in ticket: \u2018Provincia Protagonista\u2019<\/h2>\n<p>Come preannunciato, gli azzurri di Silvio Berlusconi hanno fatto squadra con il partito di Giorgia Meloni e hanno presentato una lista unica per le provinciali.<\/p>\n<p>Sette uomini, cinque donne e 7 su 12 sono under 40. Ecco chi sono i candidati: <strong>Gioacchino Ferdinandi di <\/strong>Piedimonte San Germano,<strong> Fernando Carnevale <\/strong>di Pontecorvo, <strong>Luca Zaccari <\/strong>di Ferentino,\u00a0<strong>Sergio Iannetta d<\/strong>i Belmonte Castello, <strong>Riccardo Ambrosetti<\/strong> di Anagni, <strong>Daniele Maura<\/strong> di Giuliano di Roma, <strong>Lorella Biordi <\/strong>di Monte San Giovanni Campano, <strong>Lorena De Carolis <\/strong>di Fumone, <strong>Elvira Corsetti<\/strong> di San Giorgio a Liri, <strong>Angelo Cervi <\/strong>di Alvito, <strong>Paula Andreucci <\/strong>di Picinisco e <strong>Stefania Furtivo <\/strong>di Pofi.<\/p>\n<h2>La Lega corre da sola<\/h2>\n<p>Sono 9, invece, i componenti della lista presentata dalla Lega del coordinatore provinciale Carmelo Palombo. I candidati sono: <strong>Michelina Bevilacqua <\/strong>di Esperia<strong>, Sara Bruni <\/strong>di Frosinone<strong>, Andrea Campioni d<\/strong>i Frosinone<strong>, Angelo Costantini <\/strong>di Morolo<strong>, Sarah Di Pucchio\u00a0<\/strong>di Vicalvi<strong>, Maria Giovanna Evangelista\u00a0<\/strong>di Pignataro Interamna<strong>,<\/strong> <strong>Elvio Giovannelli Protani <\/strong>di Anagni<strong>, Igino Guglielmi<\/strong> di Frosinone<strong> e Gianluca Ludovici <\/strong>di Fiuggi.<\/p>\n<h2>\u00a0ll \u2018Progetto Futuro\u2019 di Gianluca Quadrini<\/h2>\n<p>Anche il presidente della XV Comunit\u00e0 montana \u2018Valle del Liri\u2019 di Arce e consigliere provinciale uscente, <strong>Gianluca Quadrini<\/strong>, ha presentato una propria formazione. Oltre a lui come capolista, ci sono<strong> Maria Palleschi <\/strong>di Castelliri<strong>, Simona Valente <\/strong>di Cervaro<strong>, Diego Lancia <\/strong>di Colfelice<strong>, Ornella Iafrate <\/strong>di Fontana Liri<strong>, Francesco Trina <\/strong>di Frosinone<strong> e Danilo Tuffi <\/strong>di Anagni.<\/p>\n<h2>Lista civica per Luigi Vacana: \u2018Provincia in comune\u2019<\/h2>\n<p>Ecco l\u2019elenco dei suoi compagni di squadra: <strong>Ginevra Veglianti <\/strong>di Collepardo<strong>, Martina Bocconi <\/strong>di Boville Ernica<strong>, Francesca Bonanni <\/strong>di Trivigliano<strong>, Massimo Calicchia <\/strong>di Frosinon<strong>e, Eugenio Colacicco <\/strong>di Ausonia<strong>, Luc<\/strong><strong>ia Mastronicola <\/strong>di Castrocielo<strong>e Augusto Vinciguerra <\/strong>di Sora.<\/p>\n<h2>La squadra di Pallone \u2018Per la Provincia di Frosinone\u2019<\/h2>\n<p>Anche l\u2019ex eurodeputato Pallone ha schierato una sua lista di riferimento chiamata \u2018Per la Provincia di Frosinone\u2019 della quale fanno parte: <strong>Rossana Carnevale <\/strong>di Pico<strong>, Elisabetta Fantini <\/strong>di Piglio<strong>, Angela Lieghio <\/strong>di Casalattico<strong>, Marco Corsi <\/strong>di Ceccano<strong>, Gianluigi Ferretti <\/strong>di Anagni<strong>, Luciano Iaconelli di San Biagio<\/strong> Saracinisco,<strong> Oreste Quatrana <\/strong>di Trivigliano <strong>e Stefano Belli <\/strong>di Patrica.<\/p>\n<h2>I Comuni sono divisi in cinque fasce demografiche<\/h2>\n<p>La <strong>prima fascia <\/strong>(scheda di colore azzurro) comprende Comuni fino a 3.000 abitanti. L\u2019indice d ponderazione \u00e8 pari a 35.<\/p>\n<p>La <strong>seconda fascia <\/strong>(scheda di colore arancione), quella dei \u00a0Comuni con popolazione compresa tra 3.001 e 5.000 abitanti. L\u2019indice di ponderazione \u00e8 pari a 71.<\/p>\n<p><strong>Terza fascia <\/strong>(scheda grigia), quella dei Comuni da 5001 a 10.000 abitanti. L\u2019indice di ponderazione \u00e8 di 135<\/p>\n<p><strong>Quarta fascia <\/strong>(scheda rossa): Comuni con popolazione superiore a 10.000 abitanti e fino a 30.000. L\u2019indice di ponderazione arriva a 228.<\/p>\n<p><strong>Quinta fascia<\/strong> ( comuni superiori a 30.000 abitanti): la scheda \u00e8 verde. L\u2019indice di ponderazione \u00e8 337.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sei le formazioni che oggi si sfideranno per il rinnovo del consiglio provinciale di Frosinone. Sindaci e consiglieri andranno alle<\/p>\n","protected":false},"author":18,"featured_media":9484,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41],"tags":[3457,3436,1018,1280,1109,93,1251,295,883,98,83,1865],"class_list":["post-9458","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","tag-alfredo-pallone","tag-antonio-pomeo","tag-consiglio-provinciale","tag-domenico-alfieri","tag-forza-italia","tag-frosinone","tag-gianluca-quadrini","tag-lega","tag-luigi-vacana","tag-pd","tag-provincia","tag-voto"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Consiglio provinciale, oggi la sfida. Tutti i candidati - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Sindaci e consiglieri andranno alle urne dalle 8 alle 20. Sei le liste in campo per il rinnovo dell&#039;assise provinciale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Consiglio provinciale, oggi la sfida. Tutti i candidati\" \/>\n<meta property=\"og:description\" content=\"Sindaci e consiglieri andranno alle urne dalle 8 alle 20. Sei le liste in campo per il rinnovo dell&#039;assise provinciale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-04-07T06:00:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-04-07T06:28:26+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/consiglio-provinciale-ex.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"340\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/07\\\/consiglio-provinciale-oggi-scatta-la-sfida\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/07\\\/consiglio-provinciale-oggi-scatta-la-sfida\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Consiglio provinciale, oggi la sfida. Tutti i candidati\",\"datePublished\":\"2019-04-07T06:00:10+00:00\",\"dateModified\":\"2019-04-07T06:28:26+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/07\\\/consiglio-provinciale-oggi-scatta-la-sfida\\\/\"},\"wordCount\":628,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/07\\\/consiglio-provinciale-oggi-scatta-la-sfida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/consiglio-provinciale-ex.jpg\",\"keywords\":[\"Alfredo Pallone\",\"Antonio Pomeo\",\"consiglio provinciale\",\"domenico alfieri\",\"forza italia\",\"Frosinone\",\"Gianluca Quadrini\",\"Lega\",\"luigi vacana\",\"Pd\",\"provincia\",\"voto\"],\"articleSection\":[\"*SLIDE*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/07\\\/consiglio-provinciale-oggi-scatta-la-sfida\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/07\\\/consiglio-provinciale-oggi-scatta-la-sfida\\\/\",\"name\":\"Consiglio provinciale, oggi la sfida. Tutti i candidati - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/07\\\/consiglio-provinciale-oggi-scatta-la-sfida\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/07\\\/consiglio-provinciale-oggi-scatta-la-sfida\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/consiglio-provinciale-ex.jpg\",\"datePublished\":\"2019-04-07T06:00:10+00:00\",\"dateModified\":\"2019-04-07T06:28:26+00:00\",\"description\":\"Sindaci e consiglieri andranno alle urne dalle 8 alle 20. Sei le liste in campo per il rinnovo dell'assise provinciale.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/07\\\/consiglio-provinciale-oggi-scatta-la-sfida\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/07\\\/consiglio-provinciale-oggi-scatta-la-sfida\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/07\\\/consiglio-provinciale-oggi-scatta-la-sfida\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/consiglio-provinciale-ex.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/consiglio-provinciale-ex.jpg\",\"width\":720,\"height\":340,\"caption\":\"cof\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/07\\\/consiglio-provinciale-oggi-scatta-la-sfida\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Consiglio provinciale, oggi la sfida. Tutti i candidati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/07\\\/consiglio-provinciale-oggi-scatta-la-sfida\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/07\\\/consiglio-provinciale-oggi-scatta-la-sfida\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/04\\\/07\\\/consiglio-provinciale-oggi-scatta-la-sfida\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Consiglio provinciale, oggi la sfida. Tutti i candidati - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Sindaci e consiglieri andranno alle urne dalle 8 alle 20. Sei le liste in campo per il rinnovo dell'assise provinciale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/","og_locale":"it_IT","og_type":"article","og_title":"Consiglio provinciale, oggi la sfida. Tutti i candidati","og_description":"Sindaci e consiglieri andranno alle urne dalle 8 alle 20. Sei le liste in campo per il rinnovo dell'assise provinciale.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-04-07T06:00:10+00:00","article_modified_time":"2019-04-07T06:28:26+00:00","og_image":[{"width":720,"height":340,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/consiglio-provinciale-ex.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Consiglio provinciale, oggi la sfida. Tutti i candidati","datePublished":"2019-04-07T06:00:10+00:00","dateModified":"2019-04-07T06:28:26+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/"},"wordCount":628,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/consiglio-provinciale-ex.jpg","keywords":["Alfredo Pallone","Antonio Pomeo","consiglio provinciale","domenico alfieri","forza italia","Frosinone","Gianluca Quadrini","Lega","luigi vacana","Pd","provincia","voto"],"articleSection":["*SLIDE*"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/","name":"Consiglio provinciale, oggi la sfida. Tutti i candidati - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/consiglio-provinciale-ex.jpg","datePublished":"2019-04-07T06:00:10+00:00","dateModified":"2019-04-07T06:28:26+00:00","description":"Sindaci e consiglieri andranno alle urne dalle 8 alle 20. Sei le liste in campo per il rinnovo dell'assise provinciale.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/consiglio-provinciale-ex.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/consiglio-provinciale-ex.jpg","width":720,"height":340,"caption":"cof"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Consiglio provinciale, oggi la sfida. Tutti i candidati"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/04\/07\/consiglio-provinciale-oggi-scatta-la-sfida\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/9458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=9458"}],"version-history":[{"count":7,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/9458\/revisions"}],"predecessor-version":[{"id":9487,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/9458\/revisions\/9487"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/9484"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=9458"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=9458"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=9458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}