{"id":8487,"date":"2019-03-23T09:44:58","date_gmt":"2019-03-23T08:44:58","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=8487"},"modified":"2019-03-23T09:52:31","modified_gmt":"2019-03-23T08:52:31","slug":"al-via-lviii-festival-della-dottrina-sociale-della-chiesa","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/","title":{"rendered":"Al via l&#8217;VIII Festival della dottrina sociale della Chiesa"},"content":{"rendered":"<p><strong>La Bellezza splendore della verit\u00e0<\/strong>: vivere la libert\u00e0, vincendo il silenzio degli innocenti. E\u2019 questo il suggestivo\u00a0titolo della VIII edizione del Festival della Dottrina Sociale della Chiesa che, anche quest\u2019anno, viene promosso\u00a0dal Comitato Sale (Sviluppo Associazionismo Laicale) e che si terr\u00e0 luned\u00ec 25 e marted\u00ec 26 marzo nell\u2019aula\u00a0Salerno del Campus Folcara dell\u2019Universit\u00e0 di Cassino.<\/p>\n<h2>Il programma<\/h2>\n<p>Come da tradizione, ci saranno due sessioni per ciascuna giornata, una mattutina e una pomeridiana.\u00a0<strong>Nella giornata di lunedi<\/strong> si rifletter\u00e0 su \u201cReligione e societ\u00e0: famiglia produzione, cultura\u201d e, nel pomeriggio, subito dopo\u00a0la Cerimonia di inaugurazione, in programma alle ore 15.00, si rifletter\u00e0 sul tema: \u201cLavoro, piena occupazione \u2013 terzo\u00a0settore \u2013 relazioni \u2013 dignit\u00e0 del lavoratore\u201d.<strong>\u00a0Martedi 26 marzo<\/strong> le due sessioni si occuperanno di \u201cSistema Educativo \u201c e di \u201cPopolo e democrazia\u201d, con un\u00a0particolare focus sulla partecipazione e l\u2019impegno socio-politico culturale dei cattolici.\u00a0Tante le personalit\u00e0 presenti, gli studiosi, gli accademici che offriranno il loro contributo.\u00a0Il Festival si inserisce nel protocollo di collaborazione <strong>tra l\u2019Universit\u00e0 di Cassino e la Diocesi di Sora Cassino\u00a0Aquino Pontecorvo ed \u00e8 realizzato con la collaborazione della Banca Popolare del Cassinate<\/strong> che, sin dalla sua\u00a0prima edizione, ha sostenuto l\u2019evento.<\/p>\n<h2>I ringraziamenti di Rabotti<\/h2>\n<p>Il Presidente del Comitato Sale, l\u2019Avvocato Francesco Rabotti, dichiara: \u201cIl Festival \u00e8 ormai una felice tradizione consolidata e\u00a0per questo ringraziamo la diocesi, il Vescovo<strong> Monsignor Gerardo Antonazzo, l\u2019Universit\u00e0 e il rettore Giovanni Betta, la Banca\u00a0Popolare del Cassinate, con il suo presidente, Donato Formisano, e il Vice presidente, Vincenzo Formisano,<\/strong> perch\u00e9 insieme si riesce\u00a0a costruire qualcosa di importante e significativo. Il festival, iniziato otto anni fa, cresce grazie a questa partnership e a questa\u00a0sinergia, che consente a ciascuno di dare il proprio contributo. Ogni anon vediamo crescere l\u2019autorevolezza del Festival, grazie a\u00a0relatori competenti e preparati, che, con generosit\u00e0, partecipano ai lavori. Abbiamo anche quest\u2019anno un parterre di relatori\u00a0autorevolissimi, ai quali sin da ora va il nostro grazie. Speriamo vivamente che in tanti possano partecipare a questo evento che, come\u00a0sempre, rivolge un\u2019attenzione particolare anche ai giovani e agli studenti, ma anche agli insegnanti, ai docenti universitari, a tutti\u00a0coloro, cristiani e non, che condividono l\u2019impegno sociale e sentono l\u2019urgenza di dover costruire un mondo pi\u00f9 giusto e solidale\u201d.<\/p>\n<h2>L&#8217;obiettivo<\/h2>\n<p>Il Festival vuole essere <strong>un\u2019occasione e per diffondere gli insegnamenti della Dottrina Sociale della Chiesa<\/strong>, che\u00a0rappresentano degli strumenti preziosi per una migliore comprensione della nostra societ\u00e0 e del nostro tempo.\u00a0L\u2019appuntamento \u00e8 per luned\u00ec e marted\u00ec, a partire dalle 10 del mattino, presso l\u2019Universit\u00e0 di Cassino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Bellezza splendore della verit\u00e0: vivere la libert\u00e0, vincendo il silenzio degli innocenti. E\u2019 questo il suggestivo\u00a0titolo della VIII edizione<\/p>\n","protected":false},"author":18,"featured_media":8488,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,14],"tags":[3095,3094,718,3097,2827,1917],"class_list":["post-8487","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cultura","tag-banca-popolare-cassinate","tag-festival-dottrina-sociale-della-chiesa","tag-formisano","tag-francesco-rabotti","tag-giovanni-betta","tag-universita-cassino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Al via l&#039;VIII Festival della dottrina sociale della Chiesa - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Come da tradizione, ci saranno due sessioni per ciascuna giornata, una mattutina e una pomeridiana.\u00a0Nella giornata di lunedi e marted\u00ec.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Al via l&#039;VIII Festival della dottrina sociale della Chiesa\" \/>\n<meta property=\"og:description\" content=\"Come da tradizione, ci saranno due sessioni per ciascuna giornata, una mattutina e una pomeridiana.\u00a0Nella giornata di lunedi e marted\u00ec.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-23T08:44:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-23T08:52:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/festival-dottrina-sociale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"810\" \/>\n\t<meta property=\"og:image:height\" content=\"537\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Al via l&#8217;VIII Festival della dottrina sociale della Chiesa\",\"datePublished\":\"2019-03-23T08:44:58+00:00\",\"dateModified\":\"2019-03-23T08:52:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\\\/\"},\"wordCount\":439,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/festival-dottrina-sociale.jpg\",\"keywords\":[\"Banca popolare Cassinate\",\"Festival dottrina sociale della chiesa\",\"Formisano\",\"Francesco Rabotti\",\"giovanni betta\",\"universit\u00e0 cassino\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cultura e Spettacolo\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\\\/\",\"name\":\"Al via l'VIII Festival della dottrina sociale della Chiesa - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/festival-dottrina-sociale.jpg\",\"datePublished\":\"2019-03-23T08:44:58+00:00\",\"dateModified\":\"2019-03-23T08:52:31+00:00\",\"description\":\"Come da tradizione, ci saranno due sessioni per ciascuna giornata, una mattutina e una pomeridiana.\u00a0Nella giornata di lunedi e marted\u00ec.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/festival-dottrina-sociale.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/festival-dottrina-sociale.jpg\",\"width\":810,\"height\":537,\"caption\":\"festival dottrina sociale il corriere della provincia cassino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Al via l&#8217;VIII Festival della dottrina sociale della Chiesa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Al via l'VIII Festival della dottrina sociale della Chiesa - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Come da tradizione, ci saranno due sessioni per ciascuna giornata, una mattutina e una pomeridiana.\u00a0Nella giornata di lunedi e marted\u00ec.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/","og_locale":"it_IT","og_type":"article","og_title":"Al via l'VIII Festival della dottrina sociale della Chiesa","og_description":"Come da tradizione, ci saranno due sessioni per ciascuna giornata, una mattutina e una pomeridiana.\u00a0Nella giornata di lunedi e marted\u00ec.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-03-23T08:44:58+00:00","article_modified_time":"2019-03-23T08:52:31+00:00","og_image":[{"width":810,"height":537,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/festival-dottrina-sociale.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Al via l&#8217;VIII Festival della dottrina sociale della Chiesa","datePublished":"2019-03-23T08:44:58+00:00","dateModified":"2019-03-23T08:52:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/"},"wordCount":439,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/festival-dottrina-sociale.jpg","keywords":["Banca popolare Cassinate","Festival dottrina sociale della chiesa","Formisano","Francesco Rabotti","giovanni betta","universit\u00e0 cassino"],"articleSection":["*PRIMO PIANO*","Cultura e Spettacolo"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/","name":"Al via l'VIII Festival della dottrina sociale della Chiesa - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/festival-dottrina-sociale.jpg","datePublished":"2019-03-23T08:44:58+00:00","dateModified":"2019-03-23T08:52:31+00:00","description":"Come da tradizione, ci saranno due sessioni per ciascuna giornata, una mattutina e una pomeridiana.\u00a0Nella giornata di lunedi e marted\u00ec.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/festival-dottrina-sociale.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/festival-dottrina-sociale.jpg","width":810,"height":537,"caption":"festival dottrina sociale il corriere della provincia cassino"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Al via l&#8217;VIII Festival della dottrina sociale della Chiesa"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/al-via-lviii-festival-della-dottrina-sociale-della-chiesa\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/8487","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=8487"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/8487\/revisions"}],"predecessor-version":[{"id":8491,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/8487\/revisions\/8491"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/8488"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=8487"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=8487"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=8487"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}