{"id":8482,"date":"2019-03-23T09:26:04","date_gmt":"2019-03-23T08:26:04","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=8482"},"modified":"2019-03-25T13:30:04","modified_gmt":"2019-03-25T12:30:04","slug":"fermata-tav-protocollo-dintesa","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/","title":{"rendered":"Fermata Tav, protocollo d&#8217;intesa"},"content":{"rendered":"<p><strong>Un protocollo d\u2019intesa tra Cosilam, Provincia di Frosinone, Comune di Roccasecca e Universit\u00e0 per la\u00a0<\/strong><strong>creazione della Fermata in linea dell\u2019Alta Velocit\u00e0 del Lazio meridionale<\/strong> cuore dell\u2019Italia Centrale. Si \u00e8\u00a0svolta \u00a0nella sede del Cosilam l\u2019incontro che ha visto la presenza, tra gli altri, del\u00a0Presidente del Consorzio industriale Mario Abbruzzese, del Direttore Generale Annalisa\u00a0D\u2019Aguanno, del Sindaco di Roccasecca Giuseppe Sacco, del Magnifico Rettore dell\u2019Universit\u00e0 degli\u00a0Studi di Cassino e del Lazio Meridionale professor Giovanni Betta e in rappresentanza della Provincia di\u00a0Frosinone il Presidente del Consiglio Provinciale Luigi Vacana.<\/p>\n<h2>La riunione<\/h2>\n<p>L\u2019incontro ha messo in luce, ancora una volta, la forte necessit\u00e0 di quest\u2019opera strategica per tutto il\u00a0territorio del Lazio meridionale. Attualmente <strong>sulla tratta Roma-Napoli c\u2019\u00e8 un\u2019utenza quotidiana di\u00a0<\/strong><strong>42.000 persone<\/strong> che viaggia per diverse esigenze (studio, lavoro, salute etc.). I tempi di percorrenza\u00a0arrivano a superare anche le due ore. Al contrario con una fermata Tav in linea si consentirebbe a tutti i\u00a0cittadini di poter raggiungere Roma o Napoli in soli 35 minuti, e il progetto per la creazione della\u00a0Fermata in linea dell\u2019Alta Velocit\u00e0 del Lazio meridionale cuore dell\u2019Italia Centrale rispecchia\u00a0esattamente il \u201cmodello\u201d di Reggio Emilia dove gi\u00e0 \u00e8 stato realizzato un progetto analogo essendo gi\u00e0\u00a0presenti le infrastrutture necessarie che consentono una forte riduzione della quota d\u2019investimento.\u00a0Un\u2019opera strategica gi\u00e0 inserita nel Piano Industriale del Cosilam approvato a settembre 2018.<\/p>\n<h2>L&#8217;intervento di Abbruzzese<\/h2>\n<p>\u201c\u00c8 un progetto strategico e di assoluta importanza per tutto il territorio provinciale \u2013 ha affermato il\u00a0Presidente del Cosilam Mario Abbruzzese \u2013 <strong>La creazione di una fermata dell\u2019alta velocit\u00e0\u00a0<\/strong><strong>avrebbe effetti positivi sotto numerosi punti di vista<\/strong>: ambientale riducendo le emissioni di co2 generate\u00a0attualmente alla linea FL6, un contrasto all\u2019effetto migratorio con il cosiddetto &#8216;spopolamento&#8217; dei\u00a0piccoli centri. Raggiungere le grandi citt\u00e0 in poco pi\u00f9 di mezz\u2019ora porterebbe a un ritorno di molte\u00a0persone che, oggi, per diverse ragioni, hanno lasciato le proprie abitazioni nei paesi d\u2019origine&#8221;.<\/p>\n<h2>Gli obiettivi<\/h2>\n<p>&#8220;Non\u00a0ultimo, bisogna ricordare che quest\u2019opera sorgerebbe a ridosso del Distretto Industriale Automotive\u2013FCA e del Distretto della Ceramica economia circolare permettendo una nuova forma di collegamento\u00a0fondamentale tra il territorio e i grandi centri urbani. Ma per raggiungere l\u2019obiettivo oc<strong>corre portare\u00a0<\/strong><strong>avanti un attento gioco di squadra<\/strong> che si \u00e8 concretizzato nel protocollo d\u2019intesa tra gli enti presenti oggi\u00a0al tavolo che sono parte attiva di questa progettualit\u00e0. Un\u2019opera che, come ho ribadito in diverse\u00a0occasioni, non serve ad un solo comune ma a tutto il territorio provinciale e dell\u2019Italia centrale. Sono\u00a0sicuro che se si giocher\u00e0 in squadra e per il solo interesse dei cittadini riusciremo a raggiungere un\u00a0risultato epocale e di straordinaria importanza\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un protocollo d\u2019intesa tra Cosilam, Provincia di Frosinone, Comune di Roccasecca e Universit\u00e0 per la\u00a0creazione della Fermata in linea dell\u2019Alta<\/p>\n","protected":false},"author":18,"featured_media":8483,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[3093,3092,216,359,2827,2413,883,1226,1599,2115,1917],"class_list":["post-8482","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-alta-velocita","tag-annalisa-daguanno","tag-cassino","tag-cosilam","tag-giovanni-betta","tag-giuseppe-sacco","tag-luigi-vacana","tag-mario-abbruzzese","tag-roccasecca","tag-tav","tag-universita-cassino"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fermata Tav, protocollo d&#039;intesa - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fermata Tav, protocollo d&#039;intesa\" \/>\n<meta property=\"og:description\" content=\"Un protocollo d\u2019intesa tra Cosilam, Provincia di Frosinone, Comune di Roccasecca e Universit\u00e0 per la\u00a0creazione della Fermata in linea dell\u2019Alta\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-23T08:26:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-25T12:30:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Riunione-Tav-2-1-3.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/fermata-tav-protocollo-dintesa\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/fermata-tav-protocollo-dintesa\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Fermata Tav, protocollo d&#8217;intesa\",\"datePublished\":\"2019-03-23T08:26:04+00:00\",\"dateModified\":\"2019-03-25T12:30:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/fermata-tav-protocollo-dintesa\\\/\"},\"wordCount\":458,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/fermata-tav-protocollo-dintesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/Riunione-Tav-2-1-3.jpeg\",\"keywords\":[\"Alta velocit\u00e0\",\"Annalisa D'Aguanno\",\"Cassino\",\"cosilam\",\"giovanni betta\",\"Giuseppe Sacco\",\"luigi vacana\",\"mario abbruzzese\",\"Roccasecca\",\"tav\",\"universit\u00e0 cassino\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/fermata-tav-protocollo-dintesa\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/fermata-tav-protocollo-dintesa\\\/\",\"name\":\"Fermata Tav, protocollo d'intesa - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/fermata-tav-protocollo-dintesa\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/fermata-tav-protocollo-dintesa\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/Riunione-Tav-2-1-3.jpeg\",\"datePublished\":\"2019-03-23T08:26:04+00:00\",\"dateModified\":\"2019-03-25T12:30:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/fermata-tav-protocollo-dintesa\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/fermata-tav-protocollo-dintesa\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/fermata-tav-protocollo-dintesa\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/Riunione-Tav-2-1-3.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/Riunione-Tav-2-1-3.jpeg\",\"width\":600,\"height\":338,\"caption\":\"Tav Il corriere della provincia ciociaria cassino frosinone cosilam universit\u00e0 cassino roccasecca\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/fermata-tav-protocollo-dintesa\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fermata Tav, protocollo d&#8217;intesa\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/fermata-tav-protocollo-dintesa\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/fermata-tav-protocollo-dintesa\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/23\\\/fermata-tav-protocollo-dintesa\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Fermata Tav, protocollo d'intesa - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/","og_locale":"it_IT","og_type":"article","og_title":"Fermata Tav, protocollo d'intesa","og_description":"Un protocollo d\u2019intesa tra Cosilam, Provincia di Frosinone, Comune di Roccasecca e Universit\u00e0 per la\u00a0creazione della Fermata in linea dell\u2019Alta","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-03-23T08:26:04+00:00","article_modified_time":"2019-03-25T12:30:04+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Riunione-Tav-2-1-3.jpeg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Fermata Tav, protocollo d&#8217;intesa","datePublished":"2019-03-23T08:26:04+00:00","dateModified":"2019-03-25T12:30:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/"},"wordCount":458,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Riunione-Tav-2-1-3.jpeg","keywords":["Alta velocit\u00e0","Annalisa D'Aguanno","Cassino","cosilam","giovanni betta","Giuseppe Sacco","luigi vacana","mario abbruzzese","Roccasecca","tav","universit\u00e0 cassino"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/","name":"Fermata Tav, protocollo d'intesa - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Riunione-Tav-2-1-3.jpeg","datePublished":"2019-03-23T08:26:04+00:00","dateModified":"2019-03-25T12:30:04+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Riunione-Tav-2-1-3.jpeg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Riunione-Tav-2-1-3.jpeg","width":600,"height":338,"caption":"Tav Il corriere della provincia ciociaria cassino frosinone cosilam universit\u00e0 cassino roccasecca"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Fermata Tav, protocollo d&#8217;intesa"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/23\/fermata-tav-protocollo-dintesa\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/8482","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=8482"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/8482\/revisions"}],"predecessor-version":[{"id":8486,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/8482\/revisions\/8486"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/8483"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=8482"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=8482"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=8482"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}