{"id":8275,"date":"2019-03-19T16:30:45","date_gmt":"2019-03-19T15:30:45","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=8275"},"modified":"2019-03-19T16:31:08","modified_gmt":"2019-03-19T15:31:08","slug":"angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/","title":{"rendered":"Angelo Pizzutelli e Antonella D\u2019Emilia nel Pd regionale"},"content":{"rendered":"<p>L\u2019ingresso di Mauro Buschini nella direzione nazionale del Partito Democratico non \u00e8 l\u2019unica soddisfazione per i democratici ciociari. Anche il capogruppo consiliare dem, <strong>Angelo Pizzutelli<\/strong> e il vice segretario del circolo di Frosinone,<strong> Antonella D\u2019Emilia<\/strong>, sono stati chiamati a svolgere incarichi importanti a livello regionale.<\/p>\n<h2>Pizzutelli responsabile del Forum Sport del Pd Lazio<\/h2>\n<p>Il <strong>capogruppo Pd del consiglio comunale di Frosinone<\/strong>, <strong>Angelo Pizzutelli<\/strong>, nei giorni scorsi \u00e8 stato nominato dal segretario regionale, Bruno Astorre, come responsabile del forum Sport del Pd Lazio.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_5034\" aria-describedby=\"caption-attachment-5034\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5034 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/angelo-pizzutelli-frosinone-e1547732033331.jpg\" alt=\"angelo pizzutelli frosinone il corriere della provincia\" width=\"632\" height=\"467\" \/><figcaption id=\"caption-attachment-5034\" class=\"wp-caption-text\">Il consigliere comunale del Pd di Frosinone Angelo Pizzutelli<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&#8220;Come saprai \u2013 si legge nella nota a firma di Astorre \u2013 il gruppo dirigente regionale, insediato con la mia elezione, vuole procedere a strutturare l\u2019elaborazione programmatica del Pd del Lazio attraverso forum tematici che, nelle nostre intenzioni, dovranno costituire la leva del rilancio del rapporto fra il Partito e la societ\u00e0 laziale in tutte le sue complessit\u00e0&#8221;.<\/p>\n<p>&#8220;<strong>Ti chiedo<\/strong>, in questo quadro, &#8211; conclude la missiva di Astorre &#8211; <strong>di impostare il lavoro per rendere operativo il Forum sullo sport<\/strong>, settore fra i pi\u00f9 importanti dove recuperare una nostra presenza e un nostro protagonismo in tutto il territorio laziale\u201d.<\/p>\n<h2>Gli auguri del segretario provinciale Alfieri<\/h2>\n<p>Anche il<strong> segretario provinciale del Pd, Domenico Alfieri<\/strong>, si congratula con Pizzutelli per la nomina che giunge come &#8220;riconoscimento per gli ottimi risultati ottenuti quale assessore allo sport al comune capoluogo nelle giunte di Centrosinistra. Il ruolo cui \u00e8 stato chiamato Angelo Pizzutelli lo impegner\u00e0 a svolgere un lavoro fondamentale con tutte le associazioni sportive della Regione&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_8188\" aria-describedby=\"caption-attachment-8188\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8188 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/lista-pd-foto-e1552915966437.jpg\" alt=\"lista pd provincia il corriere della provincia\" width=\"632\" height=\"364\" \/><figcaption id=\"caption-attachment-8188\" class=\"wp-caption-text\">Da sinistra Alessio Gentile, Andrea Palladino, Angelo Pizzutelli e Domenico Alfieri<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Si unisce al plauso il <strong>segretario cittadino del Pd, Andrea Palladino<\/strong>: &#8220;Sono estremamente soddisfatto per la nomina di Angelo Pizzutelli che aggiunge valore e competenza nel nuovo corso del Partito Democratico&#8221;.<\/p>\n<h2>D\u2019Emilia nella segreteria del Pd regionale<\/h2>\n<p>Durante la Direzione provinciale di sabato scorso, la Federazione del Partito Democratico di Frosinone, nella persona del segretario Alfieri, ha voluto esprimere &#8220;tutto il suo apprezzamento e l\u2019augurio di buon lavoro per la nomina, da parte del segretario regionale Bruno Astorre, del dirigente Pd, <strong>Antonella D\u2019Emilia, quale membro della nuova segreteria del Pd Regionale del Lazio<\/strong>.<\/p>\n<p>Una nomina che premia e valorizza le competenze e l\u2019attivit\u00e0 politica della D\u2019Emilia, sia come vice segretario del Circolo di Frosinone, sia per il suo\u00a0 impegno a livello provinciale&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_8281\" aria-describedby=\"caption-attachment-8281\" style=\"width: 332px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-8281 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/antonella-emilia-pd.png\" alt=\"antonella d'emilia il corriere della provincia\" width=\"332\" height=\"413\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/antonella-emilia-pd.png 332w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/antonella-emilia-pd-241x300.png 241w\" sizes=\"auto, (max-width: 332px) 100vw, 332px\" \/><figcaption id=\"caption-attachment-8281\" class=\"wp-caption-text\">Antonella D&#8217;Emilia<\/figcaption><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019ingresso di Mauro Buschini nella direzione nazionale del Partito Democratico non \u00e8 l\u2019unica soddisfazione per i democratici ciociari. Anche il<\/p>\n","protected":false},"author":18,"featured_media":8284,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[1482,3036,1280,3035,2383,1378,3033,3034],"class_list":["post-8275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-angelo-pizzutelli","tag-antonella-demilia","tag-domenico-alfieri","tag-forum-dello-sport","tag-incarichi","tag-nomine","tag-pd-regionale","tag-segretario-regionale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Angelo Pizzutelli e Antonella D\u2019Emilia nel Pd regionale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Incarichi nel Pd regionale per il capogruppo consiliare dem di Frosinone Angelo Pizzutelli e per il vice segretario del circolo cittadino Antonella D&#039;Emilia\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Angelo Pizzutelli e Antonella D\u2019Emilia nel Pd regionale\" \/>\n<meta property=\"og:description\" content=\"Incarichi nel Pd regionale per il capogruppo consiliare dem di Frosinone Angelo Pizzutelli e per il vice segretario del circolo cittadino Antonella D&#039;Emilia\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-19T15:30:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-19T15:31:08+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/bruno-astorre-pd-regionale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"338\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/19\\\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/19\\\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Angelo Pizzutelli e Antonella D\u2019Emilia nel Pd regionale\",\"datePublished\":\"2019-03-19T15:30:45+00:00\",\"dateModified\":\"2019-03-19T15:31:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/19\\\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\\\/\"},\"wordCount\":429,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/19\\\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/bruno-astorre-pd-regionale.jpg\",\"keywords\":[\"angelo pizzutelli\",\"antonella d'emilia\",\"domenico alfieri\",\"forum dello sport\",\"incarichi\",\"nomine\",\"pd regionale\",\"segretario regionale\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/19\\\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/19\\\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\\\/\",\"name\":\"Angelo Pizzutelli e Antonella D\u2019Emilia nel Pd regionale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/19\\\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/19\\\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/bruno-astorre-pd-regionale.jpg\",\"datePublished\":\"2019-03-19T15:30:45+00:00\",\"dateModified\":\"2019-03-19T15:31:08+00:00\",\"description\":\"Incarichi nel Pd regionale per il capogruppo consiliare dem di Frosinone Angelo Pizzutelli e per il vice segretario del circolo cittadino Antonella D'Emilia\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/19\\\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/19\\\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/19\\\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/bruno-astorre-pd-regionale.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/bruno-astorre-pd-regionale.jpg\",\"width\":600,\"height\":338,\"caption\":\"Il segretario regionale del Pd Bruno Astorre\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/19\\\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Angelo Pizzutelli e Antonella D\u2019Emilia nel Pd regionale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/19\\\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/19\\\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/19\\\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Angelo Pizzutelli e Antonella D\u2019Emilia nel Pd regionale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Incarichi nel Pd regionale per il capogruppo consiliare dem di Frosinone Angelo Pizzutelli e per il vice segretario del circolo cittadino Antonella D'Emilia","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/","og_locale":"it_IT","og_type":"article","og_title":"Angelo Pizzutelli e Antonella D\u2019Emilia nel Pd regionale","og_description":"Incarichi nel Pd regionale per il capogruppo consiliare dem di Frosinone Angelo Pizzutelli e per il vice segretario del circolo cittadino Antonella D'Emilia","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-03-19T15:30:45+00:00","article_modified_time":"2019-03-19T15:31:08+00:00","og_image":[{"width":600,"height":338,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/bruno-astorre-pd-regionale.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Angelo Pizzutelli e Antonella D\u2019Emilia nel Pd regionale","datePublished":"2019-03-19T15:30:45+00:00","dateModified":"2019-03-19T15:31:08+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/"},"wordCount":429,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/bruno-astorre-pd-regionale.jpg","keywords":["angelo pizzutelli","antonella d'emilia","domenico alfieri","forum dello sport","incarichi","nomine","pd regionale","segretario regionale"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/","name":"Angelo Pizzutelli e Antonella D\u2019Emilia nel Pd regionale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/bruno-astorre-pd-regionale.jpg","datePublished":"2019-03-19T15:30:45+00:00","dateModified":"2019-03-19T15:31:08+00:00","description":"Incarichi nel Pd regionale per il capogruppo consiliare dem di Frosinone Angelo Pizzutelli e per il vice segretario del circolo cittadino Antonella D'Emilia","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/bruno-astorre-pd-regionale.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/bruno-astorre-pd-regionale.jpg","width":600,"height":338,"caption":"Il segretario regionale del Pd Bruno Astorre"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Angelo Pizzutelli e Antonella D\u2019Emilia nel Pd regionale"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/19\/angelo-pizzutelli-e-antonella-demilia-nel-pd-regionale\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/8275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=8275"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/8275\/revisions"}],"predecessor-version":[{"id":8286,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/8275\/revisions\/8286"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/8284"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=8275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=8275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=8275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}