{"id":79993,"date":"2022-08-23T19:37:36","date_gmt":"2022-08-23T17:37:36","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=79993"},"modified":"2022-08-23T19:49:18","modified_gmt":"2022-08-23T17:49:18","slug":"video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/","title":{"rendered":"Video Ruberti, Vincenzi e Leonori: Non ci risultano diffusioni in Consiglio regionale"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Il quesito che tutti si pongono sul video relativo alla lite avvenuta in un ristorante di  Frosinone, che ha provocato un vero e proprio terremoto politico all&#8217;interno del Pd,  \u00e8 quali giri abbia fatto prima di approdare alla redazione del Foglio.  C&#8217;\u00e8 chi sostiene che nelle settimane procedenti la pubblicazione sia arrivato alla Pisana.  <strong>Sulla questione intervengono il presidente del Consiglio regionale del Lazio Marco Vincenzi (nella foto) e la capogruppo del Partito democratico Marta Leonori. <\/strong> <br>&#8220;Non ci risulta &#8211; evidenziano &#8211;  che nelle settimane precedenti la pubblicazione ci sia stata alcuna diffusione in Consiglio regionale di video riguardanti Albino Ruberti e Francesco De Angelis<strong>. Se ne fossimo stati a conoscenza  hanno aggiunto &#8211; avremmo denunciato subito il fatto agli organi competenti&#8221;. <\/strong> <br>Intanto le indagini della Procura della Repubblica proseguono senza sosta, proprio per capire cosa sia veramente accaduto nel corso della cena. E soprattutto per verificare se ci siano state davvero proposte illecite. A condurre la delicata inchiesta \u00e8 il sostituto procuratore Adolfo Coletta.  Sotto la lente anche l&#8217;uso che \u00e8 stato fatto del video.  Il sospetto \u00e8 che alla base ci possa essere una vendetta di carattere non solamente politico. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il quesito che tutti si pongono sul video relativo alla lite avvenuta in un ristorante di Frosinone, che ha provocato<\/p>\n","protected":false},"author":26,"featured_media":56260,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[15204,12836,12431],"class_list":["post-79993","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-caso-ruberti","tag-marco-vincenzi","tag-marta-leonori"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Video Ruberti, Vincenzi e Leonori: Non ci risultano diffusioni in Consiglio regionale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Video Ruberti, Vincenzi e Leonori: Non ci risultano diffusioni in Consiglio regionale\" \/>\n<meta property=\"og:description\" content=\"Il quesito che tutti si pongono sul video relativo alla lite avvenuta in un ristorante di Frosinone, che ha provocato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-23T17:37:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-23T17:49:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/marco-vincenzi-e1506088231857.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"931\" \/>\n\t<meta property=\"og:image:height\" content=\"556\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/23\\\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/23\\\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Video Ruberti, Vincenzi e Leonori: Non ci risultano diffusioni in Consiglio regionale\",\"datePublished\":\"2022-08-23T17:37:36+00:00\",\"dateModified\":\"2022-08-23T17:49:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/23\\\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\\\/\"},\"wordCount\":202,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/23\\\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/marco-vincenzi-e1506088231857.jpg\",\"keywords\":[\"caso ruberti\",\"Marco Vincenzi\",\"marta leonori\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/23\\\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/23\\\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\\\/\",\"name\":\"Video Ruberti, Vincenzi e Leonori: Non ci risultano diffusioni in Consiglio regionale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/23\\\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/23\\\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/marco-vincenzi-e1506088231857.jpg\",\"datePublished\":\"2022-08-23T17:37:36+00:00\",\"dateModified\":\"2022-08-23T17:49:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/23\\\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/23\\\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/23\\\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/marco-vincenzi-e1506088231857.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/marco-vincenzi-e1506088231857.jpg\",\"width\":931,\"height\":556},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/23\\\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Video Ruberti, Vincenzi e Leonori: Non ci risultano diffusioni in Consiglio regionale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/23\\\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/23\\\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/23\\\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Video Ruberti, Vincenzi e Leonori: Non ci risultano diffusioni in Consiglio regionale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/","og_locale":"it_IT","og_type":"article","og_title":"Video Ruberti, Vincenzi e Leonori: Non ci risultano diffusioni in Consiglio regionale","og_description":"Il quesito che tutti si pongono sul video relativo alla lite avvenuta in un ristorante di Frosinone, che ha provocato","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-08-23T17:37:36+00:00","article_modified_time":"2022-08-23T17:49:18+00:00","og_image":[{"width":931,"height":556,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/marco-vincenzi-e1506088231857.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Video Ruberti, Vincenzi e Leonori: Non ci risultano diffusioni in Consiglio regionale","datePublished":"2022-08-23T17:37:36+00:00","dateModified":"2022-08-23T17:49:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/"},"wordCount":202,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/marco-vincenzi-e1506088231857.jpg","keywords":["caso ruberti","Marco Vincenzi","marta leonori"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/","name":"Video Ruberti, Vincenzi e Leonori: Non ci risultano diffusioni in Consiglio regionale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/marco-vincenzi-e1506088231857.jpg","datePublished":"2022-08-23T17:37:36+00:00","dateModified":"2022-08-23T17:49:18+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/marco-vincenzi-e1506088231857.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/marco-vincenzi-e1506088231857.jpg","width":931,"height":556},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Video Ruberti, Vincenzi e Leonori: Non ci risultano diffusioni in Consiglio regionale"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/23\/video-ruberti-vincenzi-e-leonori-non-ci-risultano-diffusioni-in-consiglio-regionale\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/79993","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=79993"}],"version-history":[{"count":9,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/79993\/revisions"}],"predecessor-version":[{"id":80003,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/79993\/revisions\/80003"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/56260"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=79993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=79993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=79993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}