{"id":79776,"date":"2022-08-18T19:32:17","date_gmt":"2022-08-18T17:32:17","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=79776"},"modified":"2022-08-18T19:32:46","modified_gmt":"2022-08-18T17:32:46","slug":"coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/","title":{"rendered":"Coldiretti Latina, nubifragio distrugge serre e sradica alberi d&#8217;ulivo: subito stato di calamit\u00e0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ingenti i danni nelle campagne causati dal nubifragio che si \u00e8 abbattuto sull&#8217;intero litorale pontino. Tra i Comuni particolarmente colpiti Sabaudia, Fondi e San Felice, ma anche le aree limitrofe.<br>\u201cLa situazione \u00e8 drammatica &#8211; spiega il direttore di Coldiretti Latina, Carlo Picchi &#8211; al punto tale che chiederemo alla Regione Lazio lo stato di calamit\u00e0 naturale. Le nostre aziende sono in ginocchio\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In queste ore si sta procedendo, anche attraverso gli uffici di zona della federazione provinciale, ad una stima dei danni subiti, che vanno da alberi di ulivo sradicati a causa del forte vento, alle coperture delle serre divelte con strutture fortemente danneggiate. Distrutte anche le coltivazioni, colpite soprattutto le piantagioni di mais e le orticole.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">E danni causati dal maltempo si sono registrati in questi giorni anche a Viterbo, dove a seguito di una violenta grandinata, sono state totalmente distrutte alcune coltivazioni. Tra le pi\u00f9 colpite quelle di fagioli, patate e lenticchie. Coldiretti Lazio ha gi\u00e0 avviato le procedure necessarie per la richiesta alla Regione dello stato di calamit\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLe nostre aziende non fanno in tempo a sollevarsi da un\u2019emergenza &#8211; prosegue Picchi &#8211; che se presenta subito un\u2019altra. Dalla pandemia al conflitto in Ucraina, con le ripercussioni sull\u2019aumento delle materie prime e il caro carburante, fino alla siccit\u00e0 e ora ai danni causati dal maltempo. Le aziende hanno bisogno di un aiuto concreto ed urgente per far fronte all\u2019ennesima difficolt\u00e0\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Le campagne italiane sono gi\u00e0 allo stremo con cali produttivi che vanno dal 45% per il mais e i foraggi che servono all\u2019alimentazione degli animali, al 20% per il latte nelle stalle e 30% per il frumento duro per la pasta di oltre 1\/5 delle produzioni di frumento tenero, fino al 30% del riso, meno 15% frutta ustionata da temperature di 40 gradi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEravamo in attesa della pioggia per combattere la siccit\u00e0 nelle campagne &#8211; conclude Picchi &#8211; ma nubifragi come quello che si \u00e8 abbattuto sul litorale pontino, con tale intensit\u00e0 e violenza, causano solo ulteriori danni, che vanno ad aggiungersi a quelli esistenti. I terreni arsi dalla siccit\u00e0 non riescono ad assorbire l\u2019acqua e il forte vento ha letteralmente sradicato molti alberi e danneggiato culture tipiche di quest\u2019area che rappresentano le nostre eccellenze\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ingenti i danni nelle campagne causati dal nubifragio che si \u00e8 abbattuto sull&#8217;intero litorale pontino. Tra i Comuni particolarmente colpiti<\/p>\n","protected":false},"author":26,"featured_media":56683,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[13426],"class_list":["post-79776","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-coldiretti-latina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Coldiretti Latina, nubifragio distrugge serre e sradica alberi d&#039;ulivo: subito stato di calamit\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Coldiretti Latina, nubifragio distrugge serre e sradica alberi d&#039;ulivo: subito stato di calamit\u00e0\" \/>\n<meta property=\"og:description\" content=\"Ingenti i danni nelle campagne causati dal nubifragio che si \u00e8 abbattuto sull&#8217;intero litorale pontino. Tra i Comuni particolarmente colpiti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-18T17:32:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-18T17:32:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/carlo-picchi-coldiretti-800x445-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/18\\\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/18\\\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Coldiretti Latina, nubifragio distrugge serre e sradica alberi d&#8217;ulivo: subito stato di calamit\u00e0\",\"datePublished\":\"2022-08-18T17:32:17+00:00\",\"dateModified\":\"2022-08-18T17:32:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/18\\\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\\\/\"},\"wordCount\":381,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/18\\\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/carlo-picchi-coldiretti-800x445-1.jpg\",\"keywords\":[\"Coldiretti latina\"],\"articleSection\":[\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/18\\\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/18\\\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\\\/\",\"name\":\"Coldiretti Latina, nubifragio distrugge serre e sradica alberi d'ulivo: subito stato di calamit\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/18\\\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/18\\\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/carlo-picchi-coldiretti-800x445-1.jpg\",\"datePublished\":\"2022-08-18T17:32:17+00:00\",\"dateModified\":\"2022-08-18T17:32:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/18\\\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/18\\\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/18\\\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/carlo-picchi-coldiretti-800x445-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/04\\\/carlo-picchi-coldiretti-800x445-1.jpg\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/18\\\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Coldiretti Latina, nubifragio distrugge serre e sradica alberi d&#8217;ulivo: subito stato di calamit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/18\\\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/18\\\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/18\\\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Coldiretti Latina, nubifragio distrugge serre e sradica alberi d'ulivo: subito stato di calamit\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/","og_locale":"it_IT","og_type":"article","og_title":"Coldiretti Latina, nubifragio distrugge serre e sradica alberi d'ulivo: subito stato di calamit\u00e0","og_description":"Ingenti i danni nelle campagne causati dal nubifragio che si \u00e8 abbattuto sull&#8217;intero litorale pontino. Tra i Comuni particolarmente colpiti","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-08-18T17:32:17+00:00","article_modified_time":"2022-08-18T17:32:46+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/carlo-picchi-coldiretti-800x445-1.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Coldiretti Latina, nubifragio distrugge serre e sradica alberi d&#8217;ulivo: subito stato di calamit\u00e0","datePublished":"2022-08-18T17:32:17+00:00","dateModified":"2022-08-18T17:32:46+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/"},"wordCount":381,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/carlo-picchi-coldiretti-800x445-1.jpg","keywords":["Coldiretti latina"],"articleSection":["News"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/","name":"Coldiretti Latina, nubifragio distrugge serre e sradica alberi d'ulivo: subito stato di calamit\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/carlo-picchi-coldiretti-800x445-1.jpg","datePublished":"2022-08-18T17:32:17+00:00","dateModified":"2022-08-18T17:32:46+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/carlo-picchi-coldiretti-800x445-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/carlo-picchi-coldiretti-800x445-1.jpg","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Coldiretti Latina, nubifragio distrugge serre e sradica alberi d&#8217;ulivo: subito stato di calamit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/18\/coldiretti-latina-nubifragio-distrugge-serre-e-sradica-alberi-dulivo-subito-stato-di-calamita\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/79776","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=79776"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/79776\/revisions"}],"predecessor-version":[{"id":79777,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/79776\/revisions\/79777"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/56683"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=79776"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=79776"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=79776"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}