{"id":79609,"date":"2022-08-11T11:47:47","date_gmt":"2022-08-11T09:47:47","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=79609"},"modified":"2022-08-13T14:26:38","modified_gmt":"2022-08-13T12:26:38","slug":"provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/","title":{"rendered":"Provincia, Consulta delle elette: la presidente Campoli scrive alle amministratrici"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La neo presidente della Consulta delle elette della Provincia di Frosinone, Eleonora Campoli, subito al lavoro per rendere l\u2019organismo quello che ha definito \u201cun luogo di incontro, confronto, aperto e inclusivo, con la collaborazione e i contributi di tutte\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In una lettera, inviata in questi giorni alle colleghe del territorio,<strong> la Campoli ha annunciato che a settembre convocher\u00e0 la prima seduta della Consulta<\/strong>, precisando come, impegnata direttamente nelle tematiche del sociale, di inclusione e parit\u00e0, intenda improntare il percorso dell\u2019organismo provinciale alla massima collaborazione e condivisione con tutte le donne amministratrici della provincia di Frosinone.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa nostra provincia \u2013 sottolinea in un passo della lettera &#8211; ha un tessuto sociale gi\u00e0 molto attivo e tante sono le iniziative messe in campo dalle istituzioni, dalla Asl, dalle associazioni di settore per fare in modo che la parit\u00e0 di genere diventi un diritto non solo acquisito, ma tangibile e concreto <strong>Nonostante ci\u00f2 tanto lavoro c&#8217;\u00e8 ancora da fare, in diversi ambiti e settori della societ\u00e0.<\/strong> Le sfide del futuro sono numerose e rispecchiano i cambiamenti sociali, culturali ed economici del Paese\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quindi la Campoli traccia le finalit\u00e0 della Consulta: favorire politiche inclusive e di parit\u00e0 di genere, facendo da raccordo tra le istituzioni e le associazioni, avendo funzioni consultive e di proposta. \u201cLa Consulta delle elette \u2013 conclude &#8211; sar\u00e0 la Casa Comune in cui poter discutere, proporre, confrontarsi e agire\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cRingrazio Eleonora \u2013 ha detto <strong>il presidente della Provincia, Antonio Pompeo <\/strong>\u2013 per l\u2019entusiasmo e l\u2019energia che sin da subito ha dimostrato nel ricoprire questo incarico. Conoscendo la sua vivacit\u00e0 amministrativa e l\u2019impegno che quotidianamente pone nell\u2019affrontare le delicate tematiche sociali e femminili, sono certo che far\u00e0 un ottimo lavoro di coordinamento e direzione all\u2019interno della Consulta, supportata dalla vicepresidente Angela Mancini e da tutte le donne amministratrici del territorio che non le faranno mancare il loro sostegno\u201d.<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Provincia, Consulta delle elette: la presidente Campoli scrive alle amministratrici<\/p>\n","protected":false},"author":26,"featured_media":79610,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[15176,842,94,2365,1798,12985,93,83],"class_list":["post-79609","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-amministratrici-2","tag-antonio-pompeo","tag-ciociaria","tag-consulta","tag-eleonora-campoli","tag-elette","tag-frosinone","tag-provincia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Provincia, Consulta delle elette: la presidente Campoli scrive alle amministratrici - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Provincia, Consulta delle elette: la presidente Campoli scrive alle amministratrici\" \/>\n<meta property=\"og:description\" content=\"Provincia, Consulta delle elette: la presidente Campoli scrive alle amministratrici\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-11T09:47:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-13T12:26:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/08\/Pompeo-Campoli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"919\" \/>\n\t<meta property=\"og:image:height\" content=\"616\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/11\\\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/11\\\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Provincia, Consulta delle elette: la presidente Campoli scrive alle amministratrici\",\"datePublished\":\"2022-08-11T09:47:47+00:00\",\"dateModified\":\"2022-08-13T12:26:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/11\\\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\\\/\"},\"wordCount\":320,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/11\\\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/08\\\/Pompeo-Campoli.jpg\",\"keywords\":[\"amministratrici\",\"antonio pompeo\",\"Ciociaria\",\"consulta\",\"eleonora campoli\",\"elette\",\"Frosinone\",\"provincia\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/11\\\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/11\\\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\\\/\",\"name\":\"Provincia, Consulta delle elette: la presidente Campoli scrive alle amministratrici - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/11\\\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/11\\\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/08\\\/Pompeo-Campoli.jpg\",\"datePublished\":\"2022-08-11T09:47:47+00:00\",\"dateModified\":\"2022-08-13T12:26:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/11\\\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/11\\\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/11\\\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/08\\\/Pompeo-Campoli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/08\\\/Pompeo-Campoli.jpg\",\"width\":919,\"height\":616},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/11\\\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Provincia, Consulta delle elette: la presidente Campoli scrive alle amministratrici\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/11\\\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/11\\\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/11\\\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Provincia, Consulta delle elette: la presidente Campoli scrive alle amministratrici - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/","og_locale":"it_IT","og_type":"article","og_title":"Provincia, Consulta delle elette: la presidente Campoli scrive alle amministratrici","og_description":"Provincia, Consulta delle elette: la presidente Campoli scrive alle amministratrici","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-08-11T09:47:47+00:00","article_modified_time":"2022-08-13T12:26:38+00:00","og_image":[{"width":919,"height":616,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/08\/Pompeo-Campoli.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Provincia, Consulta delle elette: la presidente Campoli scrive alle amministratrici","datePublished":"2022-08-11T09:47:47+00:00","dateModified":"2022-08-13T12:26:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/"},"wordCount":320,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/08\/Pompeo-Campoli.jpg","keywords":["amministratrici","antonio pompeo","Ciociaria","consulta","eleonora campoli","elette","Frosinone","provincia"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/","name":"Provincia, Consulta delle elette: la presidente Campoli scrive alle amministratrici - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/08\/Pompeo-Campoli.jpg","datePublished":"2022-08-11T09:47:47+00:00","dateModified":"2022-08-13T12:26:38+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/08\/Pompeo-Campoli.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/08\/Pompeo-Campoli.jpg","width":919,"height":616},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Provincia, Consulta delle elette: la presidente Campoli scrive alle amministratrici"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/11\/provincia-consulta-delle-elette-la-presidente-campoli-scrive-alle-amministratrici\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/79609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=79609"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/79609\/revisions"}],"predecessor-version":[{"id":79611,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/79609\/revisions\/79611"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/79610"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=79609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=79609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=79609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}