{"id":7955,"date":"2019-03-12T17:33:49","date_gmt":"2019-03-12T16:33:49","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=7955"},"modified":"2019-03-12T17:38:45","modified_gmt":"2019-03-12T16:38:45","slug":"campo-di-calcio-di-anagni-interviene-lassessore-chiarelli","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/","title":{"rendered":"Campo di calcio di Anagni, interviene l&#8217;assessore Chiarelli"},"content":{"rendered":"<p><strong>Sullo Stadio comunale \u201cRoberto Del Bianco\u201d<\/strong> l\u2019amministrazione comunale sgombera il campo da qualunque illazione e lo fa per bocca dell\u2019assessore allo Sport Jessica Chiarelli.<\/p>\n<h2>L&#8217;intervento<\/h2>\n<p>\u00abL\u2019annullamento in autotutela della Determinazione n. 184\/2018 \u00e8 stato dovuto alla considerazione che il progetto originario dei lavori di manutenzione straordinaria del campo di calcio comunale non prevedeva interventi sulle strutture degli spogliatoi. Il progetto precedentemente approvato infatti aveva preso in considerazione gli standard federali per i campionati dilettantistici minori; con l\u2019Anagni Calcio che milita nel campionato di Serie D gli standard degli stadi sono diversi e bisogna rispondere a particolari richieste della Lega Nazionale Dilettanti&#8221;.<\/p>\n<p>&#8220;<strong>Il mancato adeguamento dei locali spogliatoi avrebbe impedito l\u2019omologazione del \u201cDel Bianco\u201d<\/strong> per le gare di Serie D da parte della Lega Nazionale Dilettanti. Bisogna poi considerare che l\u2019intervento di drenaggio e realizzazione del manto erboso pu\u00f2 essere realizzato senza lo sbancamento ed il trasporto a discarica dell\u2019attuale manto ed i soldi risparmiati potrebbero coprire i costi della ristrutturazione e dell\u2019adeguamento degli attuali spogliatoi&#8221;.<\/p>\n<h2>La decisione<\/h2>\n<p>&#8220;Per tale motivi, che sono di natura tecnica, il funzionario responsabile del Settore Lavori Pubblici dell\u2019Ufficio Tecnico ha ritenuto necessario ricorrere all\u2019annullamento in autotutela della Determinazione n. 184\/2018. Si \u00e8 anche invitato il progettista alla rivisitazione del progetto in funzione di quanto in precedenza detto. Con una rivisitazione rapida del progetto si potrebbe immediatamente passare all\u2019indizione di una nuova gara d\u2019appalto e dunque allo sblocco dei lavori. La citt\u00e0 di Anagni avrebbe cos\u00ec, in breve tempo, il suo campo di calcio a norma secondo gli standard della LND\u00bb.<\/p>\n<p>Per quel che riguarda le polemiche degli ultimi giorni in merito all\u2019annullamento della precedente delibera l\u2019assessore Chiarelli dichiara: \u00abChiaramente su questa scelta chi vuole fare sterile opposizione ci sta marciando sopra, anche facendo illazioni che poco hanno a che fare con la sana dialettica politica. Q<strong>uesta amministrazione non ha intenzione di rispondere alle provocazioni<\/strong> in quanto, se si fosse in buona fede, si potrebbero tranquillamente visionare tutte le carte relative al \u201cDel Bianco\u201d che, essendo atti pubblici, sono a disposizione di tutti i cittadini\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Sullo Stadio comunale \u201cRoberto Del Bianco\u201d l\u2019amministrazione comunale sgombera il campo da qualunque illazione e lo fa per bocca dell\u2019assessore<\/p>\n","protected":false},"author":18,"featured_media":7960,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,1],"tags":[441,2923,1583],"class_list":["post-7955","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-news","tag-anagni","tag-assessore-chiarelli","tag-stadio-comunale"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Campo di calcio di Anagni, interviene l&#039;assessore Chiarelli - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Campo di calcio di Anagni, interviene l&#039;assessore Chiarelli\" \/>\n<meta property=\"og:description\" content=\"Sullo Stadio comunale \u201cRoberto Del Bianco\u201d l\u2019amministrazione comunale sgombera il campo da qualunque illazione e lo fa per bocca dell\u2019assessore\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-12T16:33:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-12T16:38:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Jessica-Chiarelli-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"498\" \/>\n\t<meta property=\"og:image:height\" content=\"331\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/12\\\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/12\\\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Campo di calcio di Anagni, interviene l&#8217;assessore Chiarelli\",\"datePublished\":\"2019-03-12T16:33:49+00:00\",\"dateModified\":\"2019-03-12T16:38:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/12\\\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\\\/\"},\"wordCount\":359,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/12\\\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/Jessica-Chiarelli-1.jpg\",\"keywords\":[\"anagni\",\"Assessore chiarelli\",\"stadio comunale\"],\"articleSection\":[\"Evidenza\",\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/12\\\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/12\\\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\\\/\",\"name\":\"Campo di calcio di Anagni, interviene l'assessore Chiarelli - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/12\\\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/12\\\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/Jessica-Chiarelli-1.jpg\",\"datePublished\":\"2019-03-12T16:33:49+00:00\",\"dateModified\":\"2019-03-12T16:38:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/12\\\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/12\\\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/12\\\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/Jessica-Chiarelli-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/Jessica-Chiarelli-1.jpg\",\"width\":498,\"height\":331,\"caption\":\"Jessica Chiarelli anagni il corriere della provincia ciociaria frosinone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/12\\\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Campo di calcio di Anagni, interviene l&#8217;assessore Chiarelli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/12\\\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/12\\\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/12\\\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Campo di calcio di Anagni, interviene l'assessore Chiarelli - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/","og_locale":"it_IT","og_type":"article","og_title":"Campo di calcio di Anagni, interviene l'assessore Chiarelli","og_description":"Sullo Stadio comunale \u201cRoberto Del Bianco\u201d l\u2019amministrazione comunale sgombera il campo da qualunque illazione e lo fa per bocca dell\u2019assessore","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-03-12T16:33:49+00:00","article_modified_time":"2019-03-12T16:38:45+00:00","og_image":[{"width":498,"height":331,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Jessica-Chiarelli-1.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Campo di calcio di Anagni, interviene l&#8217;assessore Chiarelli","datePublished":"2019-03-12T16:33:49+00:00","dateModified":"2019-03-12T16:38:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/"},"wordCount":359,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Jessica-Chiarelli-1.jpg","keywords":["anagni","Assessore chiarelli","stadio comunale"],"articleSection":["Evidenza","News"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/","name":"Campo di calcio di Anagni, interviene l'assessore Chiarelli - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Jessica-Chiarelli-1.jpg","datePublished":"2019-03-12T16:33:49+00:00","dateModified":"2019-03-12T16:38:45+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Jessica-Chiarelli-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Jessica-Chiarelli-1.jpg","width":498,"height":331,"caption":"Jessica Chiarelli anagni il corriere della provincia ciociaria frosinone"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Campo di calcio di Anagni, interviene l&#8217;assessore Chiarelli"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/12\/campo-di-calcio-di-anagni-interviene-lassessore-chiarelli\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/7955","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=7955"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/7955\/revisions"}],"predecessor-version":[{"id":7959,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/7955\/revisions\/7959"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/7960"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=7955"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=7955"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=7955"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}