{"id":79382,"date":"2022-08-03T16:30:50","date_gmt":"2022-08-03T14:30:50","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=79382"},"modified":"2022-08-04T11:02:39","modified_gmt":"2022-08-04T09:02:39","slug":"ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/","title":{"rendered":"Ciociaria la terza provincia pi\u00f9 anziana del Lazio: i dati della Uil"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">C\u2019\u00e8 Piedimonte San Germano tra i dieci comuni pi\u00f9 giovani del Lazio. E poi c\u2019\u00e8 Terelle tra i dieci pi\u00f9 vecchi. Questo e altro emerge dal dossier che la Uil del Lazio e l\u2019Eures hanno realizzato per osservare le dinamiche demografiche regionali. <strong>Con una popolazione residente pari a 468.438 abitanti e un\u2019et\u00e0 media di 46,5 anni, <\/strong>in Ciociaria vivono 115252 over sessantaquattrenni e 17586 persone con pi\u00f9 di 85 anni. <strong>A livello provinciale il territorio di Frosinone \u00e8 il terzo pi\u00f9 anziano del Lazio, dopo Rieti e Viterbo e prima di Roma e Latina.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cIl declino demografico e il progressivo invecchiamento della popolazione &#8211; dice <strong>Anita Tarquini, segretaria della Uil di Frosinone<\/strong> &#8211; stanno ridisegnando il profilo della nostra provincia, con ricadute sul mercato del lavoro, sulla distribuzione delle risorse economiche, sulla domanda di servizi sociosanitari e sulle politiche dell\u2019inclusione\u201d. Su scala regionale sono pi\u00f9 di 1 milione e 300 mila gli over 64enni, pari al 22,9 per cento della popolazione residente. Di questi, oltre 200 mila (pari al 3,6 per cento dei residenti totali) hanno un\u2019et\u00e0 superiore a 84 anni, sono cio\u00e8 \u201cgrandi anziani\u201d il pi\u00f9 delle volte portatori di bisogni e di assistenza nonch\u00e9 di integrazione sociale, visto che in molti casi si tratta di anziani soli. Tornando alla nostra provincia e analizzando i Comuni pi\u00f9 giovani e pi\u00f9 vecchi, notiamo che i 6299 residenti di Piedimonte San Germano hanno un\u2019et\u00e0 media di 42,7 anni, la popolazione con pi\u00f9 di 65 anni si attesta al 19,4 per cento mentre quella con pi\u00f9 di 85 anni \u00e8 del 2,6 per cento. Numeri che su scala regionale pongono questo paese al sesto posto tra le realt\u00e0 laziali pi\u00f9 giovani. Discorso diverso per Terelle (ottavo tra i paesi \u201cpi\u00f9 vecchi\u201d), dove i 305 residenti raggiungono l\u2019et\u00e0 media di 55,1 anni, il 38,4 per cento \u00e8 over 64, il 9,8 ricade in quella dei \u201cgrandi anziani\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSebbene nel 2020 l\u2019indice di natalit\u00e0 che registra il dossier dell\u2019Eures &#8211; conclude la segretaria Uil &#8211; sia stato tra i pi\u00f9 alti della regione (6,7 nati per mille abitanti), quello di mortalit\u00e0 \u00e8 stato del 12,2 per mille. Questi numeri pretendono una riflessione, perch\u00e9 il ricambio generazionale \u00e8 quasi azzerato e ci\u00f2 \u00e8 stato frutto di politiche poco attente ai giovani e alle famiglie, alla mancanza di lavoro che spinge i giovani a costruire il proprio futuro altrove, magari all\u2019estero e a un welfare considerato erroneamente un peso mentre \u00e8 chiaramente una risorsa\u201d. E per finire, lo scorso anno sono stati 108.435 gli assegni pensionistici erogati in Ciociaria, con un importo medio mensile di 1255 euro.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ciociaria la terza provincia pi\u00f9 anziana del Lazio: i dati della Uil<\/p>\n","protected":false},"author":26,"featured_media":79383,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[3936,94,920,93,2484,871],"class_list":["post-79382","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-anita-tarquini","tag-ciociaria","tag-eures","tag-frosinone","tag-popolazione","tag-uil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ciociaria la terza provincia pi\u00f9 anziana del Lazio: i dati della Uil - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ciociaria la terza provincia pi\u00f9 anziana del Lazio: i dati della Uil\" \/>\n<meta property=\"og:description\" content=\"Ciociaria la terza provincia pi\u00f9 anziana del Lazio: i dati della Uil\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-08-03T14:30:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-08-04T09:02:39+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/08\/anita-tarquini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"985\" \/>\n\t<meta property=\"og:image:height\" content=\"536\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/03\\\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/03\\\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Ciociaria la terza provincia pi\u00f9 anziana del Lazio: i dati della Uil\",\"datePublished\":\"2022-08-03T14:30:50+00:00\",\"dateModified\":\"2022-08-04T09:02:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/03\\\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\\\/\"},\"wordCount\":418,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/03\\\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/08\\\/anita-tarquini.jpg\",\"keywords\":[\"anita tarquini\",\"Ciociaria\",\"Eures\",\"Frosinone\",\"popolazione\",\"Uil\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/03\\\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/03\\\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\\\/\",\"name\":\"Ciociaria la terza provincia pi\u00f9 anziana del Lazio: i dati della Uil - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/03\\\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/03\\\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/08\\\/anita-tarquini.jpg\",\"datePublished\":\"2022-08-03T14:30:50+00:00\",\"dateModified\":\"2022-08-04T09:02:39+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/03\\\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/03\\\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/03\\\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/08\\\/anita-tarquini.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/08\\\/anita-tarquini.jpg\",\"width\":985,\"height\":536,\"caption\":\"Anita Tarquini\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/03\\\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ciociaria la terza provincia pi\u00f9 anziana del Lazio: i dati della Uil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/03\\\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/03\\\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/08\\\/03\\\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ciociaria la terza provincia pi\u00f9 anziana del Lazio: i dati della Uil - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/","og_locale":"it_IT","og_type":"article","og_title":"Ciociaria la terza provincia pi\u00f9 anziana del Lazio: i dati della Uil","og_description":"Ciociaria la terza provincia pi\u00f9 anziana del Lazio: i dati della Uil","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-08-03T14:30:50+00:00","article_modified_time":"2022-08-04T09:02:39+00:00","og_image":[{"width":985,"height":536,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/08\/anita-tarquini.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Ciociaria la terza provincia pi\u00f9 anziana del Lazio: i dati della Uil","datePublished":"2022-08-03T14:30:50+00:00","dateModified":"2022-08-04T09:02:39+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/"},"wordCount":418,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/08\/anita-tarquini.jpg","keywords":["anita tarquini","Ciociaria","Eures","Frosinone","popolazione","Uil"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/","name":"Ciociaria la terza provincia pi\u00f9 anziana del Lazio: i dati della Uil - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/08\/anita-tarquini.jpg","datePublished":"2022-08-03T14:30:50+00:00","dateModified":"2022-08-04T09:02:39+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/08\/anita-tarquini.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/08\/anita-tarquini.jpg","width":985,"height":536,"caption":"Anita Tarquini"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ciociaria la terza provincia pi\u00f9 anziana del Lazio: i dati della Uil"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/08\/03\/ciociaria-la-terza-provincia-piu-anziana-del-lazio-i-dati-della-uil\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/79382","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=79382"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/79382\/revisions"}],"predecessor-version":[{"id":79384,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/79382\/revisions\/79384"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/79383"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=79382"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=79382"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=79382"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}