{"id":79178,"date":"2022-07-29T14:39:58","date_gmt":"2022-07-29T12:39:58","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=79178"},"modified":"2022-07-29T15:54:33","modified_gmt":"2022-07-29T13:54:33","slug":"lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/","title":{"rendered":"Lazio, accordo Anci e Anbi per la creazione di una banca dati catastale"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nei giorni scorsi, il Segretario Generale dell&#8217;Anci Lazio, <strong>Giuseppe De Righi<\/strong> e il Direttore di Anbi Lazio, <strong>Andrea Renna<\/strong>, come previsto dall\u2019apposito protocollo d\u2019intesa siglato nel 2020 dai Presidenti delle due associazioni, hanno sottoscritto il primo accordo operativo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si tratta di un impegno volto alla creazione di una banca dati informatizzata, capace di tenere insieme diverse informazioni oggi in possesso dei singoli Comuni e dei singoli Consorzi di Bonifica, dalle cartografie all&#8217;assetto fondiario con i valori catastali, che saranno l&#8217;ossatura di un portale Web-gis che ospiter\u00e0 un imponente sistema di dati relativi al territorio.&nbsp; Nell&#8217;ambito delle rispettive competenze e prerogative, Anbi Lazio, utilizzando i pi\u00f9 aggiornati software GIS, realizzer\u00e0 la banca dati cartografica dei comprensori consortili grazie al prelievo presso i Comuni associati all\u2019Anci Lazio dei dati catastali che sar\u00e0 integrata con le carte informatizzate in uso consortile. Il portale avr\u00e0 due diversi livelli di accesso, libero ma con informazioni limitate per tutti i cittadini, studenti e professionisti, dedicato per le Amministrazioni pubbliche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>L\u2019accordo con Anbi Lazio<\/em> \u2013 dichiara <strong>Riccardo Varone<\/strong>, Presidente Anci Lazio \u2013 <em>\u00e8 una delle tappe di un percorso che Anci Lazio sta portando avanti ormai da diversi anni, un percorso di sostegno e supporto ai comuni e ai cittadini della nostra regione.<br>La creazione di una banca dati che contenga al suo interno tutte le informazioni relative a queste tematiche non pu\u00f2 che migliorare la qualit\u00e0 dei servizi offerti a coloro i quali hanno necessit\u00e0 di reperire questo genere di dati.<br>Il lavoro di coordinamento e raccolta delle informazioni \u00e8 sicuramente parte fondante di quella che pu\u00f2 essere definita \u201cbuona pratica\u201d.<br>Un ringraziamento va alla Presidente di Anbi Lazio, Sonia Ricci e al suo Direttore, Andrea Renna oltre che al nostro Segretario Generale, Giuseppe De Righi che cos\u00ec bene hanno lavorato per concludere un accordo importante per i nostri territori<\/em>\u201d.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"689\" height=\"424\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/07\/sonia-ricci.jpg\" alt=\"\" class=\"wp-image-78879\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/07\/sonia-ricci.jpg 689w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/07\/sonia-ricci-300x185.jpg 300w\" sizes=\"auto, (max-width: 689px) 100vw, 689px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c<em>Questo primo accordo operativo<\/em> \u2013 spiega <strong>Sonia Ricci<\/strong>, Presidente di Anbi Lazio \u2013 <em>\u00e8 parte di un programma di lavoro nato per rafforzare le attivit\u00e0 di prevenzione e manutenzione del territorio.&nbsp; Sono soprattutto le emergenze derivanti dai cambiamenti climatici che stanno rendendo sempre pi\u00f9 evidente la fragilit\u00e0 del sistema idrogeologico del Lazio e per questa ragione i rapporti tra i Consorzi di bonifica e Comuni non possono pi\u00f9 essere affidati all\u2019episodicit\u00e0, ma devono essere incardinati in un sistema organico di relazioni e collaborazioni che consenta maggiore efficacia per far fronte ai diversi problemi territoriali, risparmi e servizi migliori ai cittadini<\/em>\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nei giorni scorsi, il Segretario Generale dell&#8217;Anci Lazio, Giuseppe De Righi e il Direttore di Anbi Lazio, Andrea Renna, come<\/p>\n","protected":false},"author":26,"featured_media":79179,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[8662,5234,15147,15148,10155],"class_list":["post-79178","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-anbi-lazio-2","tag-andrea-renna","tag-giuseppe-de-righi","tag-riccardo-varrone","tag-sonia-ricci"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Lazio, accordo Anci e Anbi per la creazione di una banca dati catastale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lazio, accordo Anci e Anbi per la creazione di una banca dati catastale\" \/>\n<meta property=\"og:description\" content=\"Nei giorni scorsi, il Segretario Generale dell&#8217;Anci Lazio, Giuseppe De Righi e il Direttore di Anbi Lazio, Andrea Renna, come\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-29T12:39:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-29T13:54:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/07\/andrea-renna-giusepp-de-righi.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"728\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/29\\\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/29\\\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Lazio, accordo Anci e Anbi per la creazione di una banca dati catastale\",\"datePublished\":\"2022-07-29T12:39:58+00:00\",\"dateModified\":\"2022-07-29T13:54:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/29\\\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\\\/\"},\"wordCount\":420,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/29\\\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/07\\\/andrea-renna-giusepp-de-righi.jpg\",\"keywords\":[\"anbi lazio\",\"andrea renna\",\"giuseppe de righi\",\"riccardo varrone\",\"sonia ricci\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/29\\\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/29\\\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\\\/\",\"name\":\"Lazio, accordo Anci e Anbi per la creazione di una banca dati catastale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/29\\\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/29\\\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/07\\\/andrea-renna-giusepp-de-righi.jpg\",\"datePublished\":\"2022-07-29T12:39:58+00:00\",\"dateModified\":\"2022-07-29T13:54:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/29\\\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/29\\\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/29\\\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/07\\\/andrea-renna-giusepp-de-righi.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/07\\\/andrea-renna-giusepp-de-righi.jpg\",\"width\":728,\"height\":560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/29\\\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lazio, accordo Anci e Anbi per la creazione di una banca dati catastale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/29\\\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/29\\\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/29\\\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Lazio, accordo Anci e Anbi per la creazione di una banca dati catastale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/","og_locale":"it_IT","og_type":"article","og_title":"Lazio, accordo Anci e Anbi per la creazione di una banca dati catastale","og_description":"Nei giorni scorsi, il Segretario Generale dell&#8217;Anci Lazio, Giuseppe De Righi e il Direttore di Anbi Lazio, Andrea Renna, come","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-07-29T12:39:58+00:00","article_modified_time":"2022-07-29T13:54:33+00:00","og_image":[{"width":728,"height":560,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/07\/andrea-renna-giusepp-de-righi.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Lazio, accordo Anci e Anbi per la creazione di una banca dati catastale","datePublished":"2022-07-29T12:39:58+00:00","dateModified":"2022-07-29T13:54:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/"},"wordCount":420,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/07\/andrea-renna-giusepp-de-righi.jpg","keywords":["anbi lazio","andrea renna","giuseppe de righi","riccardo varrone","sonia ricci"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/","name":"Lazio, accordo Anci e Anbi per la creazione di una banca dati catastale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/07\/andrea-renna-giusepp-de-righi.jpg","datePublished":"2022-07-29T12:39:58+00:00","dateModified":"2022-07-29T13:54:33+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/07\/andrea-renna-giusepp-de-righi.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/07\/andrea-renna-giusepp-de-righi.jpg","width":728,"height":560},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Lazio, accordo Anci e Anbi per la creazione di una banca dati catastale"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/29\/lazio-accordo-anci-e-anbi-per-la-creazione-di-una-banca-dati-catastale\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/79178","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=79178"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/79178\/revisions"}],"predecessor-version":[{"id":79180,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/79178\/revisions\/79180"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/79179"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=79178"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=79178"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=79178"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}