{"id":78120,"date":"2022-07-06T11:53:54","date_gmt":"2022-07-06T09:53:54","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=78120"},"modified":"2022-07-06T15:58:43","modified_gmt":"2022-07-06T13:58:43","slug":"pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/","title":{"rendered":"Pnrr, la Provincia a supporto dei Comuni associati per il bando sulle Green Communities"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Acqua, boschi, paesaggio. \u00c8 nell\u2019uso consapevole di queste risorse che trova origine il bando del Pnrr sulle \u2018Green Communities\u2019, pubblicato in questi giorni. L\u2019obiettivo \u00e8 quello di favorire lo sviluppo sostenibile e resiliente dei territori rurali e di montagna che vogliono sfruttare in modo equilibrato le ricchezze di cui dispongono: \u00e8 cos\u00ec che si incentiver\u00e0 la nascita e la crescita di comunit\u00e0 locali, anche coordinate e\/o associate (le Green Communities, appunto), dando loro supporto per l\u2019elaborazione, il finanziamento e la realizzazione di piani di sviluppo sostenibili dal punto di vista energetico, ambientale, economico e sociale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Provincia di Frosinone sostiene e supporta gli enti associati (<strong>Unioni dei Comuni, Comunit\u00e0 Montane,&nbsp; Consorzi e Comuni che siano convenzionati tra loro per l\u2019espletamento di determinati servizi<\/strong>) che intendono partecipare al bando, considerata anche la scadenza piuttosto ravvicinata (16 agosto). Una dotazione di<strong> 130 milioni di euro<\/strong> per finanziare 30 associazioni di comuni che intendono realizzare comunit\u00e0 sostenibili.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cIn un momento di grande emergenza ambientale \u2013 sottolinea Pompeo \u2013 in cui anche il nostro territorio sta vivendo le criticit\u00e0 legate alla siccit\u00e0 e al depauperamento delle risorse idriche, avere l\u2019opportunit\u00e0 di ottenere fondi per una gestione consapevole dell\u2019acqua e del patrimonio agro-forestale, per la produzione di energia da fonti rinnovabili e lo sviluppo di un turismo ecosostenibile \u00e8 assolutamente da cogliere. <strong>Dobbiamo sempre pi\u00f9 e sempre pi\u00f9 in fretta adottare misure e comportamenti in linea con il rispetto dell\u2019ambiente e dell\u2019ecosistema<\/strong>: \u2013 continua il presidente della Provincia \u2013 efficientamento energetico, sviluppo di attivit\u00e0 produttive a rifiuti zero, servizi di mobilit\u00e0 integrata e modelli di sviluppo sostenibile sono le direttrici da seguire se vogliamo realmente e concretamente proteggere l\u2019ambiente e garantire un futuro vivibile ai nostri figli. Invito, quindi, le Unioni dei Comuni, le Comunit\u00e0 Montane, i Consorzi e i Comuni convenzionati tra loro per l\u2019espletamento dei servizi a rispondere al bando e ottenere, cos\u00ec, contributi importanti per un settore centrale e imprescindibile dalla crescita e dallo sviluppo sostenibile del territorio\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pnrr, la Provincia a supporto dei Comuni associati per il bando sulle Green Communities<\/p>\n","protected":false},"author":26,"featured_media":76803,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[94,4846,7267,93,15058,13021,83],"class_list":["post-78120","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-ciociaria","tag-comunita-montane","tag-consorzi","tag-frosinone","tag-green-communities","tag-pnrr","tag-provincia"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pnrr, la Provincia a supporto dei Comuni associati per il bando sulle Green Communities - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pnrr, la Provincia a supporto dei Comuni associati per il bando sulle Green Communities\" \/>\n<meta property=\"og:description\" content=\"Pnrr, la Provincia a supporto dei Comuni associati per il bando sulle Green Communities\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-07-06T09:53:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-06T13:58:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/06\/Presidente-Pompeo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"942\" \/>\n\t<meta property=\"og:image:height\" content=\"791\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/06\\\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/06\\\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Pnrr, la Provincia a supporto dei Comuni associati per il bando sulle Green Communities\",\"datePublished\":\"2022-07-06T09:53:54+00:00\",\"dateModified\":\"2022-07-06T13:58:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/06\\\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\\\/\"},\"wordCount\":341,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/06\\\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/06\\\/Presidente-Pompeo.jpg\",\"keywords\":[\"Ciociaria\",\"comunit\u00e0 montane\",\"consorzi\",\"Frosinone\",\"green communities\",\"pnrr\",\"provincia\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/06\\\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/06\\\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\\\/\",\"name\":\"Pnrr, la Provincia a supporto dei Comuni associati per il bando sulle Green Communities - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/06\\\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/06\\\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/06\\\/Presidente-Pompeo.jpg\",\"datePublished\":\"2022-07-06T09:53:54+00:00\",\"dateModified\":\"2022-07-06T13:58:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/06\\\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/06\\\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/06\\\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/06\\\/Presidente-Pompeo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/06\\\/Presidente-Pompeo.jpg\",\"width\":942,\"height\":791,\"caption\":\"Il presidente Antonio Pompeo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/06\\\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pnrr, la Provincia a supporto dei Comuni associati per il bando sulle Green Communities\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/06\\\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/06\\\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/07\\\/06\\\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pnrr, la Provincia a supporto dei Comuni associati per il bando sulle Green Communities - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/","og_locale":"it_IT","og_type":"article","og_title":"Pnrr, la Provincia a supporto dei Comuni associati per il bando sulle Green Communities","og_description":"Pnrr, la Provincia a supporto dei Comuni associati per il bando sulle Green Communities","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-07-06T09:53:54+00:00","article_modified_time":"2022-07-06T13:58:43+00:00","og_image":[{"width":942,"height":791,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/06\/Presidente-Pompeo.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Pnrr, la Provincia a supporto dei Comuni associati per il bando sulle Green Communities","datePublished":"2022-07-06T09:53:54+00:00","dateModified":"2022-07-06T13:58:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/"},"wordCount":341,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/06\/Presidente-Pompeo.jpg","keywords":["Ciociaria","comunit\u00e0 montane","consorzi","Frosinone","green communities","pnrr","provincia"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/","name":"Pnrr, la Provincia a supporto dei Comuni associati per il bando sulle Green Communities - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/06\/Presidente-Pompeo.jpg","datePublished":"2022-07-06T09:53:54+00:00","dateModified":"2022-07-06T13:58:43+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/06\/Presidente-Pompeo.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/06\/Presidente-Pompeo.jpg","width":942,"height":791,"caption":"Il presidente Antonio Pompeo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Pnrr, la Provincia a supporto dei Comuni associati per il bando sulle Green Communities"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/07\/06\/pnrr-la-provincia-a-supporto-dei-comuni-associati-per-il-bando-sulle-green-communities\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/78120","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=78120"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/78120\/revisions"}],"predecessor-version":[{"id":78124,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/78120\/revisions\/78124"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/76803"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=78120"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=78120"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=78120"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}