{"id":7703,"date":"2019-03-07T14:58:53","date_gmt":"2019-03-07T13:58:53","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=7703"},"modified":"2019-03-08T12:21:48","modified_gmt":"2019-03-08T11:21:48","slug":"sin-valle-del-sacco-una-firma-da-53milioni-di-euro","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/","title":{"rendered":"Sin Valle del Sacco, una firma da 53milioni di euro"},"content":{"rendered":"<p><strong>Valle del Sacco,<\/strong> entra finalmente nel vivo la bonifica. Il Presidente della Regione Lazio <strong>Nicola<\/strong> <strong>Zingaretti<\/strong> e il Ministro dell\u2019Ambiente <strong>Sergio Costa<\/strong> hanno siglato, questa mattina in prefettura a Frosinone, il protocollo per la<strong> messa in sicurezza del Sito di Interesse Nazionale.<\/strong> Si tratta di interventi largamente attesi e che sono stati definiti \u201cun passo fondamentale nella pi\u00f9 vasta operazione di recupero di un\u2019area che negli anni ha subito danni ambientali di rilievo\u201d. Con la firma di tale accordo si entra finalmente nel vivo della bonifica e del recupero, \u201callineandosi in questo modo agli obiettivi della Giunta regionale\u201d, \u00e8 stato sottolineato nel corso della conferenza stampa, \u201cper intraprendere una nuova politica ambientale, per uno sviluppo sostenibile, a garanzia del rispetto della salute e della tutela dei cittadini\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7710 aligncenter\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria-tris.jpg\" alt=\"\" width=\"632\" height=\"356\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria-tris.jpg 1008w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria-tris-300x169.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria-tris-768x432.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria-tris-500x281.jpg 500w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/p>\n<h2><\/h2>\n<h2>Il saluto del prefetto<\/h2>\n<p>\u201cSi tratta della fase prodromica \u2013 ha fatto notare<strong> il prefetto Ignazio Portelli<\/strong> \u2013 che permetter\u00e0 di sbloccare i finanziamenti e le opere per il sin del Sacco. Un ringraziamento &#8211; ha evidenziato &#8211; va ai sindaci che in questi anni si sono battuti per risolvere in maniera concreta tale criticit\u00e0\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7707 aligncenter\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria-bis.jpg\" alt=\"\" width=\"632\" height=\"307\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria-bis.jpg 2016w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria-bis-300x146.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria-bis-768x373.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria-bis-1024x498.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria-bis-500x243.jpg 500w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/p>\n<h2><\/h2>\n<h2>L\u2019intervento di Zingaretti<\/h2>\n<p>&#8220;E&#8217; un protocollo che pu\u00f2 segnare un passaggio fondamentale. La Valle Sacco \u2013 ha affermato il governatore del Lazio &#8211; \u00e8 il<strong> terzo sito pi\u00f9 inquinato d&#8217;Italia<\/strong>, ma oggi siamo al punto storico dell&#8217;accordo di programma, che ci auguriamo aiuter\u00e0 a superare tutte le impasse amministrative che hanno fermato gli interventi e che rende parte attiva i Comuni\u201d.\u00a0 Un ringraziamento lo ha riservato a <strong>Mauro Buschini<\/strong>, ex assessore regionale all\u2019Ambiente e attuale capogruppo del Pd alla Pisana, relativamente all\u2019accordo sulla qualit\u00e0 dell\u2019aria, che ha avuto il suo coronamento nella sottoscrizione al Ministero.\u00a0 \u201cIn quattro anni \u2013 ha aggiunto Zingaretti <strong>&#8211; spenderemo 53milioni di euro per una fetta di territorio davvero martoriata<\/strong>. Puntiamo anche \u2013 ha argomentato &#8211; alla riconversione dell\u2019inceneritore di Colleferro, che sar\u00e0 trasformato in un impianto finalizzato al riciclo del materiale. L\u2019obiettivo &#8211; ha concluso \u2013 \u00e8 quello di <strong>trasformare la Valle del Sacco da problema a opportunit\u00e0<\/strong> per quelle aziende che credono nella sostenibilit\u00e0\u201d.<\/p>\n<h2>Le parole del ministro<\/h2>\n<p>&#8220;<strong>L&#8217;accordo \u00e8 innovativo<\/strong>, \u00e8 condiviso ed \u00e8 qualcosa di concreto di estremamente solido. Il cittadino &#8211; ha sottolineato &#8211; si \u00e8 stancato di alchimie politiche e vuole le risposte. Non \u00e8 retorica la mia: per me le cose si devono fare. Sono convinto che alla fine di questi 4 anni, ma gi\u00e0 tra 6 mesi,\u00a0 vedremo i primi risultati. Tutte le istituzioni \u2013 ha proseguito \u2013 si sono messe intorno al tavolo per costruire questo <strong>accordo di programma<\/strong> che gi\u00e0 simbolicamente \u00e8 un gesto molto forte e concretamente l\u2019abbiamo innovato, contingentando i tempi, dando per ogni step un qualcosa da fare. Abbiamo, infatti, costituito un comitato di verifica, individuando alcuni percorsi nuovi, come il monitoraggio complessivo di tutte le acque o la situazione<strong> epidemiologica<\/strong>. Noi crediamo \u2013 ha concluso \u2013 che possa andar bene cos\u00ec e, di conseguenza, lo estenderemo ad altre aree geografiche\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-7705 aligncenter\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/sindaci-prefettura.jpg\" alt=\"sindaci prefettura valle del sacco il corriere della provincia zingaretti sergio costa frosinone ciociaria\" width=\"632\" height=\"307\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/sindaci-prefettura.jpg 847w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/sindaci-prefettura-300x146.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/sindaci-prefettura-768x374.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/sindaci-prefettura-500x243.jpg 500w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\" \/><\/p>\n<h2><\/h2>\n<h2>Cosa prevede il piano<\/h2>\n<p>La Regione Lazio, Ente beneficiario delle risorse, <strong>sar\u00e0 responsabile del controllo e del monitoraggio per la realizzazione degli interventi<\/strong> e potr\u00e0 ricorrere sia alla forma della gestione diretta sia all\u2019affidamento di prestazioni di servizio e di lavori all\u2019esterno, incluse le proprie societ\u00e0 in house nel rispetto delle disposizioni comunitarie e nazionali in materia (tra queste Lazio Ambiente o Arpa Lazio per esempio).<\/p>\n<p>I principali temi dell\u2019Accordo di Programma saranno la messa in sicurezza e bonifica del Sito di Interesse Nazionale Bacino del Fiume Sacco mediante una serie di interventi di immediata attuazione: <strong>messa in sicurezza e caratterizzazione di aree pubbliche o private individuate all\u2019interno del perimetro del Sito di interesse nazionale<\/strong> (ovvero l\u2019area che \u00e8 stata oggetto di perimetrazione poich\u00e9 inquinata); <strong>monitoraggio delle acque per uso potabile, domestico e per uso agricolo<\/strong> per tutte le porzioni di territorio dei vari Comuni interessati che si trovano nel perimetro oggetto dell\u2019intervento.<\/p>\n<p>Inoltre, oggetto dell\u2019Accordo, \u00e8 anche l\u2019avvio in tempi certi e brevi degli interventi relativi alla bonifica del suolo, sottosuolo ed acque sotterranee nell\u2019area del Sito di Bonifica di Interesse Nazionale \u201cBacino del Fiume Sacco\u201d e, nello specifico, degli interventi di natura pubblica presentati e richiesti dalle Amministrazioni Comunali interessate. Infine nell\u2019Accordo \u00e8 prevista l\u2019istituzione di un Comitato tecnico composto da un rappresentante del Ministero dell\u2019Ambiente e della Tutela del Territorio e del Mare, che svolge anche le funzioni di presidente, nonch\u00e9 di tre rappresentanti, rispettivamente, della Regione Lazio, di Ispra e di Arpa Lazio per assicurare massima trasparenza e partecipazione.<\/p>\n<h2>Come saranno distribuite le risorse<\/h2>\n<p>I fondi disponibili ammontano ad <strong>oltre 53 milioni<\/strong>: <strong>16,3 milioni<\/strong> a valere sulle risorse programmate nel Piano Operativo \u201cAmbiente\u201d \u2013 sottopiano \u201cInterventi per la tutela del territorio e delle acque\u201d; <strong>10 milioni<\/strong> a valere sulle risorse di cui all\u2019art. 1, comma 476, della Legge 28 dicembre 2015, n. 208 (Legge di stabilit\u00e0 2016); <strong>16,3 milioni<\/strong> del Patto per il Lazio di cui alla Delibera CIPE n. 56\/2016; <strong>11 milioni<\/strong> a valere sulle risorse dell\u2019ex contabilit\u00e0 speciale dell\u2019Ufficio commissariale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Valle del Sacco, entra finalmente nel vivo la bonifica. Il Presidente della Regione Lazio Nicola Zingaretti e il Ministro dell\u2019Ambiente<\/p>\n","protected":false},"author":3,"featured_media":7706,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236,1],"tags":[1421,1388,1300,918,2851,562,2811,809],"class_list":["post-7703","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","category-news","tag-colleferro","tag-mauro-buschini","tag-ministero-ambiente","tag-nicola-zingaretti","tag-prefetto-portelli","tag-regione-lazio","tag-sergio-costa","tag-valle-del-sacco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sin Valle del Sacco, una firma da 53milioni di euro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Nicola Zingaretti e il Ministro dell\u2019Ambiente Sergio Costa hanno siglato, in prefettura a Frosinone, il protocollo per il Sin.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sin Valle del Sacco, una firma da 53milioni di euro\" \/>\n<meta property=\"og:description\" content=\"Nicola Zingaretti e il Ministro dell\u2019Ambiente Sergio Costa hanno siglato, in prefettura a Frosinone, il protocollo per il Sin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/TuNews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-07T13:58:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-08T11:21:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"706\" \/>\n\t<meta property=\"og:image:height\" content=\"397\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Trento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Trento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/07\\\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/07\\\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\\\/\"},\"author\":{\"name\":\"Gianluca Trento\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\"},\"headline\":\"Sin Valle del Sacco, una firma da 53milioni di euro\",\"datePublished\":\"2019-03-07T13:58:53+00:00\",\"dateModified\":\"2019-03-08T11:21:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/07\\\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\\\/\"},\"wordCount\":826,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/07\\\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria.jpg\",\"keywords\":[\"colleferro\",\"mauro buschini\",\"Ministero Ambiente\",\"nicola zingaretti\",\"Prefetto Portelli\",\"regione lazio\",\"sergio costa\",\"valle del sacco\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\",\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/07\\\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/07\\\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\\\/\",\"name\":\"Sin Valle del Sacco, una firma da 53milioni di euro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/07\\\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/07\\\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria.jpg\",\"datePublished\":\"2019-03-07T13:58:53+00:00\",\"dateModified\":\"2019-03-08T11:21:48+00:00\",\"description\":\"Nicola Zingaretti e il Ministro dell\u2019Ambiente Sergio Costa hanno siglato, in prefettura a Frosinone, il protocollo per il Sin.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/07\\\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/07\\\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/07\\\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria.jpg\",\"width\":706,\"height\":397,\"caption\":\"valle del sacco zingaretti costa portelli il corriere della provincia frosinone ciociaria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/07\\\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sin Valle del Sacco, una firma da 53milioni di euro\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/07\\\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/07\\\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\",\"name\":\"Gianluca Trento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"caption\":\"Gianluca Trento\"},\"description\":\"Giornalista dei quotidiani online \\\"LaProvinciaQuotidiano.it\\\" e \\\"TuNews24.it\\\" e del settimanale cartaceo \\\"Tu News\\\". In passato \u00e8 stato anche Direttore Editoriale de \\\"La Provincia\\\", Direttore Responsabile del quotidiano \\\"Ciociaria Oggi\\\", Condirettore de \\\"Il quotidiano della Ciociaria\\\", giornalista di \\\"Paese Sera\\\", del settimanale \\\"L\u2019Inchiesta\\\" e del quotidiano online \\\"Il Corriere della Provincia\\\".\",\"sameAs\":[\"https:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/TuNews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/gianluca\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/07\\\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sin Valle del Sacco, una firma da 53milioni di euro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Nicola Zingaretti e il Ministro dell\u2019Ambiente Sergio Costa hanno siglato, in prefettura a Frosinone, il protocollo per il Sin.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/","og_locale":"it_IT","og_type":"article","og_title":"Sin Valle del Sacco, una firma da 53milioni di euro","og_description":"Nicola Zingaretti e il Ministro dell\u2019Ambiente Sergio Costa hanno siglato, in prefettura a Frosinone, il protocollo per il Sin.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/TuNews24","article_published_time":"2019-03-07T13:58:53+00:00","article_modified_time":"2019-03-08T11:21:48+00:00","og_image":[{"width":706,"height":397,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria.jpg","type":"image\/jpeg"}],"author":"Gianluca Trento","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Gianluca Trento","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/"},"author":{"name":"Gianluca Trento","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd"},"headline":"Sin Valle del Sacco, una firma da 53milioni di euro","datePublished":"2019-03-07T13:58:53+00:00","dateModified":"2019-03-08T11:21:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/"},"wordCount":826,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria.jpg","keywords":["colleferro","mauro buschini","Ministero Ambiente","nicola zingaretti","Prefetto Portelli","regione lazio","sergio costa","valle del sacco"],"articleSection":["*SLIDE*","Attualit\u00e0","News"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/","name":"Sin Valle del Sacco, una firma da 53milioni di euro - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria.jpg","datePublished":"2019-03-07T13:58:53+00:00","dateModified":"2019-03-08T11:21:48+00:00","description":"Nicola Zingaretti e il Ministro dell\u2019Ambiente Sergio Costa hanno siglato, in prefettura a Frosinone, il protocollo per il Sin.","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/valle-del-sacco-zingaretti-costa-portelli-il-corriere-della-provincia-frosinone-ciociaria.jpg","width":706,"height":397,"caption":"valle del sacco zingaretti costa portelli il corriere della provincia frosinone ciociaria"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Sin Valle del Sacco, una firma da 53milioni di euro"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd","name":"Gianluca Trento","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","caption":"Gianluca Trento"},"description":"Giornalista dei quotidiani online \"LaProvinciaQuotidiano.it\" e \"TuNews24.it\" e del settimanale cartaceo \"Tu News\". In passato \u00e8 stato anche Direttore Editoriale de \"La Provincia\", Direttore Responsabile del quotidiano \"Ciociaria Oggi\", Condirettore de \"Il quotidiano della Ciociaria\", giornalista di \"Paese Sera\", del settimanale \"L\u2019Inchiesta\" e del quotidiano online \"Il Corriere della Provincia\".","sameAs":["https:\/\/www.tunews24.it","http:\/\/www.facebook.com\/TuNews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/gianluca\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/07\/sin-valle-del-sacco-una-firma-da-53milioni-di-euro\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/7703","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=7703"}],"version-history":[{"count":9,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/7703\/revisions"}],"predecessor-version":[{"id":7785,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/7703\/revisions\/7785"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/7706"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=7703"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=7703"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=7703"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}