{"id":7610,"date":"2019-03-05T14:11:23","date_gmt":"2019-03-05T13:11:23","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=7610"},"modified":"2019-03-07T17:14:37","modified_gmt":"2019-03-07T16:14:37","slug":"zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/","title":{"rendered":"Zingaretti alla Saxa Gres. Pompeo: ripartire da temi concreti"},"content":{"rendered":"<div id=\"m_-8312395081121576141gmail-m_-1404371964089049762ydpfaa65223yiv2233885248ymail_android_signature\">\n<p>&#8220;<strong>Nicola Zingaretti<\/strong> ieri sui cantieri della Tav, oggi alla Saxa Gres di Anagni. Bene ripartire dai temi concreti: le infrastrutture, il lavoro, lo sviluppo, la formazione, i territori. Di questo hanno bisogno il nostro Paese<\/p>\n<div id=\"m_-8312395081121576141gmail-m_-1404371964089049762ydpfaa65223yiv2233885248ymail_android_signature\">e la nostra Provincia.\u00a0 Sono le necessit\u00e0 reali dei cittadini, purtroppo uscite dall&#8217;agenda di governo e sostituite dai sentimenti della paura e dell&#8217;odio, che per\u00f2 non generano ricchezza. E&#8217; quanto dichiarato dal Presidente della Provincia di Frosinone <strong>Antonio Pompeo.<\/strong><\/div>\n<\/div>\n<h2>Esempi da seguire<\/h2>\n<div id=\"m_-8312395081121576141gmail-m_-1404371964089049762ydpfaa65223yiv2233885248ymail_android_signature\">\n<div>&#8220;Tocca a noi tornare ad investire sul futuro.<strong> La Saxa Gres di Anagni, insieme alla Saxa Grestone di Roccasecca, sono esempi da prendere a modello<\/strong>: innovazione, coraggio, riscatto, economia circolare. Dalla nostra terra pu\u00f2 arrivare un messaggio importante al centrosinistra. Una terra che, per\u00f2, chiede risposte, rispetto e attenzione. Di questo abbiamo parlato con Nicola, oltre a complimentarmi per la sua straordinaria vittoria, ottenuta anche grazie all&#8217;onda di consensi arrivata dalla nostra provincia&#8221;.<\/div>\n<div id=\"m_-8312395081121576141gmail-m_-1404371964089049762ydpfaa65223yiv2233885248ymail_android_signature\"><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Nicola Zingaretti ieri sui cantieri della Tav, oggi alla Saxa Gres di Anagni. Bene ripartire dai temi concreti: le infrastrutture,<\/p>\n","protected":false},"author":18,"featured_media":7613,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[2823,918,85,562,2822],"class_list":["post-7610","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-economia","tag-borgomeo","tag-nicola-zingaretti","tag-pompeo","tag-regione-lazio","tag-saxa-gres-di-anagni"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Zingaretti alla Saxa Gres. Pompeo: ripartire da temi concreti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Il presidente della Provincia: &quot;ripartire dai temi concreti: le infrastrutture, il lavoro, lo sviluppo, la formazione e i territori&quot;.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zingaretti alla Saxa Gres. Pompeo: ripartire da temi concreti\" \/>\n<meta property=\"og:description\" content=\"Il presidente della Provincia: &quot;ripartire dai temi concreti: le infrastrutture, il lavoro, lo sviluppo, la formazione e i territori&quot;.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-03-05T13:11:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-03-07T16:14:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/pompeo-zingaretti-de-angelis-saxa-gres-bis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"607\" \/>\n\t<meta property=\"og:image:height\" content=\"392\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/05\\\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/05\\\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Zingaretti alla Saxa Gres. Pompeo: ripartire da temi concreti\",\"datePublished\":\"2019-03-05T13:11:23+00:00\",\"dateModified\":\"2019-03-07T16:14:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/05\\\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\\\/\"},\"wordCount\":162,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/05\\\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/pompeo-zingaretti-de-angelis-saxa-gres-bis.jpg\",\"keywords\":[\"Borgomeo\",\"nicola zingaretti\",\"pompeo\",\"regione lazio\",\"Saxa Gres di Anagni\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/05\\\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/05\\\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\\\/\",\"name\":\"Zingaretti alla Saxa Gres. Pompeo: ripartire da temi concreti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/05\\\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/05\\\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/pompeo-zingaretti-de-angelis-saxa-gres-bis.jpg\",\"datePublished\":\"2019-03-05T13:11:23+00:00\",\"dateModified\":\"2019-03-07T16:14:37+00:00\",\"description\":\"Il presidente della Provincia: \\\"ripartire dai temi concreti: le infrastrutture, il lavoro, lo sviluppo, la formazione e i territori\\\".\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/05\\\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/05\\\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/05\\\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/pompeo-zingaretti-de-angelis-saxa-gres-bis.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/pompeo-zingaretti-de-angelis-saxa-gres-bis.jpg\",\"width\":607,\"height\":392,\"caption\":\"pompeo zingaretti de angelis saxa gres\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/05\\\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zingaretti alla Saxa Gres. Pompeo: ripartire da temi concreti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/05\\\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/05\\\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/03\\\/05\\\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Zingaretti alla Saxa Gres. Pompeo: ripartire da temi concreti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Il presidente della Provincia: \"ripartire dai temi concreti: le infrastrutture, il lavoro, lo sviluppo, la formazione e i territori\".","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/","og_locale":"it_IT","og_type":"article","og_title":"Zingaretti alla Saxa Gres. Pompeo: ripartire da temi concreti","og_description":"Il presidente della Provincia: \"ripartire dai temi concreti: le infrastrutture, il lavoro, lo sviluppo, la formazione e i territori\".","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-03-05T13:11:23+00:00","article_modified_time":"2019-03-07T16:14:37+00:00","og_image":[{"width":607,"height":392,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/pompeo-zingaretti-de-angelis-saxa-gres-bis.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Zingaretti alla Saxa Gres. Pompeo: ripartire da temi concreti","datePublished":"2019-03-05T13:11:23+00:00","dateModified":"2019-03-07T16:14:37+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/"},"wordCount":162,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/pompeo-zingaretti-de-angelis-saxa-gres-bis.jpg","keywords":["Borgomeo","nicola zingaretti","pompeo","regione lazio","Saxa Gres di Anagni"],"articleSection":["*PRIMO PIANO*","Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/","name":"Zingaretti alla Saxa Gres. Pompeo: ripartire da temi concreti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/pompeo-zingaretti-de-angelis-saxa-gres-bis.jpg","datePublished":"2019-03-05T13:11:23+00:00","dateModified":"2019-03-07T16:14:37+00:00","description":"Il presidente della Provincia: \"ripartire dai temi concreti: le infrastrutture, il lavoro, lo sviluppo, la formazione e i territori\".","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/pompeo-zingaretti-de-angelis-saxa-gres-bis.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/pompeo-zingaretti-de-angelis-saxa-gres-bis.jpg","width":607,"height":392,"caption":"pompeo zingaretti de angelis saxa gres"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Zingaretti alla Saxa Gres. Pompeo: ripartire da temi concreti"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/03\/05\/zingaretti-alla-saxa-gres-pompeo-ripartire-da-temi-concreti\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/7610","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=7610"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/7610\/revisions"}],"predecessor-version":[{"id":7614,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/7610\/revisions\/7614"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/7613"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=7610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=7610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=7610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}