{"id":76061,"date":"2022-05-27T12:09:50","date_gmt":"2022-05-27T10:09:50","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=76061"},"modified":"2022-05-27T12:09:52","modified_gmt":"2022-05-27T10:09:52","slug":"frosinone-lartista-maria-mansueto-dona-unopera-al-comune","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/","title":{"rendered":"Frosinone, l&#8217;artista Maria Mansueto dona un&#8217;opera al Comune"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Oggi pomeriggio, <strong>alle ore 16.30<\/strong>, nella Sala Consiliare della nuova sede del Comune di Frosinone (Palazzo Munari, via Plebiscito) si terr\u00e0 la cerimonia di acquisizione al patrimonio comunale di un\u2019opera di Maria Mansueto, destinata alla Pinacoteca. Nella stessa occasione, sar\u00e0 inaugurata la personale dell\u2019artista, che vive a Siena, ma che \u00e8 nata in Ciociaria ed \u00e8 molto legata alla sua terra d\u2019origine.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L\u2019opera donata, intitolata<strong> \u2018Come pagine di un libro il territorio\u2019<\/strong>, \u00e8 dedicata al vissuto della gente di Frosinone, per non dimenticare, per tenere viva la memoria e celebrare il coraggio col quale ha saputo attraversare tempi avversi, l\u2019impegno e la tenacia attivati per operare la ricostruzione e la rinascita del territorio. L\u2019opera rappresenta, in moderato astrattismo, Frosinone dopo i feroci bombardamenti della guerra mondiale e le sofferenze della popolazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Maria Mansueto, laureata in pedagogia, Presidente dell\u2019Unicef per la provincia di Siena, ha pubblicato due libri: \u201cLuogo della Luce\u201d e \u201cOltre il Buio\u201d (ed. Le Monnier), e ha curato progetti per l\u2019educazione alla pace, all\u2019intercultura e allo sviluppo, per l\u2019Universit\u00e0 di Siena (ed. Franco Angeli). Accanto all\u2019attivit\u00e0 di docente, ha coltivato l\u2019interesse per l\u2019arte, cominciando la sua ricerca come paesaggista e poi trasformando la sua tecnica in informale-materica.&nbsp; Ha esposto in tutta Italia e in particolare a Siena e provincia, alla Rassegna di Arte Contemporanea e alla Biennale tenutesi a Frosinone, oltre che all\u2019Expo di Dubai-Abu Dhabi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nella sua personale espone opere informali-materiche, come segno di protesta per un mondo impazzito, dove il colore riempie le tele&nbsp; mischiandosi con la luce. Sono molto spesso dominate dall\u2019azzurro della vita e del cielo,&nbsp; dedicate&nbsp; all\u2019Universo (\u201cArmonia Cosmica\u201d, \u201cFatti di Stelle\u201d, \u201cNell\u2019abbraccio l\u2019infinito\u201d, \u201cA riveder le stelle\u201d sono alcuni dei titoli) ma quasi sempre con la presenza del sole come segno di speranza. Una pittura essenziale, colore su colore, che chiede pace per i popoli, fatta di rapide pennellate e di segni decisi per descrivere la natura offesa e abbandonata. Altri dipinti in oro, come \u201cFrontiere\u201d, sono legati alla stessa ricerca dell\u2019opera donata al Comune di Frosinone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frosinone, l&#8217;artista Maria Mansueto dona un&#8217;opera al Comune<\/p>\n","protected":false},"author":26,"featured_media":64593,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14,28],"tags":[14634,94,93,6385],"class_list":["post-76061","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cultura","category-politica","tag-artista","tag-ciociaria","tag-frosinone","tag-opera"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, l&#039;artista Maria Mansueto dona un&#039;opera al Comune - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, l&#039;artista Maria Mansueto dona un&#039;opera al Comune\" \/>\n<meta property=\"og:description\" content=\"Frosinone, l&#039;artista Maria Mansueto dona un&#039;opera al Comune\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-27T10:09:50+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-27T10:09:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/comune-frosinone.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"793\" \/>\n\t<meta property=\"og:image:height\" content=\"529\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/27\\\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/27\\\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Frosinone, l&#8217;artista Maria Mansueto dona un&#8217;opera al Comune\",\"datePublished\":\"2022-05-27T10:09:50+00:00\",\"dateModified\":\"2022-05-27T10:09:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/27\\\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\\\/\"},\"wordCount\":364,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/27\\\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/comune-frosinone.jpg\",\"keywords\":[\"artista\",\"Ciociaria\",\"Frosinone\",\"opera\"],\"articleSection\":[\"Cultura e Spettacolo\",\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/27\\\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/27\\\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\\\/\",\"name\":\"Frosinone, l'artista Maria Mansueto dona un'opera al Comune - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/27\\\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/27\\\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/comune-frosinone.jpg\",\"datePublished\":\"2022-05-27T10:09:50+00:00\",\"dateModified\":\"2022-05-27T10:09:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/27\\\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/27\\\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/27\\\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/comune-frosinone.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/comune-frosinone.jpg\",\"width\":793,\"height\":529},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/27\\\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, l&#8217;artista Maria Mansueto dona un&#8217;opera al Comune\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/27\\\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/27\\\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/27\\\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, l'artista Maria Mansueto dona un'opera al Comune - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, l'artista Maria Mansueto dona un'opera al Comune","og_description":"Frosinone, l'artista Maria Mansueto dona un'opera al Comune","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-05-27T10:09:50+00:00","article_modified_time":"2022-05-27T10:09:52+00:00","og_image":[{"width":793,"height":529,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/comune-frosinone.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Frosinone, l&#8217;artista Maria Mansueto dona un&#8217;opera al Comune","datePublished":"2022-05-27T10:09:50+00:00","dateModified":"2022-05-27T10:09:52+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/"},"wordCount":364,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/comune-frosinone.jpg","keywords":["artista","Ciociaria","Frosinone","opera"],"articleSection":["Cultura e Spettacolo","Evidenza"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/","name":"Frosinone, l'artista Maria Mansueto dona un'opera al Comune - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/comune-frosinone.jpg","datePublished":"2022-05-27T10:09:50+00:00","dateModified":"2022-05-27T10:09:52+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/comune-frosinone.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/comune-frosinone.jpg","width":793,"height":529},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, l&#8217;artista Maria Mansueto dona un&#8217;opera al Comune"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/27\/frosinone-lartista-maria-mansueto-dona-unopera-al-comune\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/76061","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=76061"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/76061\/revisions"}],"predecessor-version":[{"id":76062,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/76061\/revisions\/76062"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/64593"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=76061"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=76061"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=76061"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}