{"id":75649,"date":"2022-05-19T14:04:49","date_gmt":"2022-05-19T12:04:49","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=75649"},"modified":"2022-05-19T14:05:15","modified_gmt":"2022-05-19T12:05:15","slug":"bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/","title":{"rendered":"Bando autismo, Ciacciarelli: la Regione  illude le famiglie  e crea disparit\u00e0"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br>\u201cLa Regione illude le famiglie dei ragazzi con spettro autistico, cambiando le regole del bando per i fondi da erogare per queste cure rispetto allo scorso anno, impedendo di fatto la loro partecipazione. Lo dichiara il consigliere regionale del Lazio Pasquale Ciacciarelli (Lega). &#8220;Questo quanto ho discusso in aula oggi, nel corso del consiglio regionale. Qualche tempo fa mi \u00e8 stata evidenziata una situazione spiacevole accaduta in una Asl pontina che ha emesso un bando per pagare le rette che le famiglie sostengono ogni anno per far seguire ai propri figli terapie adeguate. Ogni seduta costa dalle 40 alle 50 euro, e vanno fatte quasi ogni giorno, una spesa abnorme per un nucleo familiare. A giugno 2021 la circolare che diceva ai genitori di rivolgersi a professionisti inseriti in un elenco. Come si pu\u00f2 in corso d\u2019anno cambiare le regole del gioco, rispetto a quello precedente,senza dare la possibilit\u00e0 di avere le informazioni in tempo!? Ho chiesto all\u2019assessore D\u2019Amato, in aula oggi, spiegazioni su quanto accaduto. La nuova rimodulazione del bando crea disparit\u00e0, difficolt\u00e0 ulteriori alle famiglie di questi ragazzi, gi\u00e0 duramente provate dalla quotidianit\u00e0.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLa Regione illude le famiglie dei ragazzi con spettro autistico, cambiando le regole del bando per i fondi da erogare<\/p>\n","protected":false},"author":26,"featured_media":35445,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[14884,1336,562],"class_list":["post-75649","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-salute","tag-bando-autismo","tag-pasquale-ciacciarelli","tag-regione-lazio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bando autismo, Ciacciarelli: la Regione illude le famiglie e crea disparit\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bando autismo, Ciacciarelli: la Regione illude le famiglie e crea disparit\u00e0\" \/>\n<meta property=\"og:description\" content=\"\u201cLa Regione illude le famiglie dei ragazzi con spettro autistico, cambiando le regole del bando per i fondi da erogare\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-19T12:04:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-19T12:05:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/ciacciarelli-pasquale.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"727\" \/>\n\t<meta property=\"og:image:height\" content=\"554\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/19\\\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/19\\\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Bando autismo, Ciacciarelli: la Regione illude le famiglie e crea disparit\u00e0\",\"datePublished\":\"2022-05-19T12:04:49+00:00\",\"dateModified\":\"2022-05-19T12:05:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/19\\\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\\\/\"},\"wordCount\":196,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/19\\\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/ciacciarelli-pasquale.jpg\",\"keywords\":[\"Bando autismo\",\"pasquale ciacciarelli\",\"regione lazio\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Salute e Benessere\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/19\\\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/19\\\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\\\/\",\"name\":\"Bando autismo, Ciacciarelli: la Regione illude le famiglie e crea disparit\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/19\\\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/19\\\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/ciacciarelli-pasquale.jpg\",\"datePublished\":\"2022-05-19T12:04:49+00:00\",\"dateModified\":\"2022-05-19T12:05:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/19\\\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/19\\\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/19\\\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/ciacciarelli-pasquale.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/ciacciarelli-pasquale.jpg\",\"width\":727,\"height\":554},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/19\\\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bando autismo, Ciacciarelli: la Regione illude le famiglie e crea disparit\u00e0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/19\\\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/19\\\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/19\\\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bando autismo, Ciacciarelli: la Regione illude le famiglie e crea disparit\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/","og_locale":"it_IT","og_type":"article","og_title":"Bando autismo, Ciacciarelli: la Regione illude le famiglie e crea disparit\u00e0","og_description":"\u201cLa Regione illude le famiglie dei ragazzi con spettro autistico, cambiando le regole del bando per i fondi da erogare","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-05-19T12:04:49+00:00","article_modified_time":"2022-05-19T12:05:15+00:00","og_image":[{"width":727,"height":554,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/ciacciarelli-pasquale.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Bando autismo, Ciacciarelli: la Regione illude le famiglie e crea disparit\u00e0","datePublished":"2022-05-19T12:04:49+00:00","dateModified":"2022-05-19T12:05:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/"},"wordCount":196,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/ciacciarelli-pasquale.jpg","keywords":["Bando autismo","pasquale ciacciarelli","regione lazio"],"articleSection":["*PRIMO PIANO*","Salute e Benessere"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/","name":"Bando autismo, Ciacciarelli: la Regione illude le famiglie e crea disparit\u00e0 - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/ciacciarelli-pasquale.jpg","datePublished":"2022-05-19T12:04:49+00:00","dateModified":"2022-05-19T12:05:15+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/ciacciarelli-pasquale.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/ciacciarelli-pasquale.jpg","width":727,"height":554},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Bando autismo, Ciacciarelli: la Regione illude le famiglie e crea disparit\u00e0"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/19\/bando-autismo-ciacciarelli-la-regione-illude-le-famiglie-e-crea-disparita\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/75649","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=75649"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/75649\/revisions"}],"predecessor-version":[{"id":75650,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/75649\/revisions\/75650"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/35445"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=75649"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=75649"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=75649"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}