{"id":75591,"date":"2022-05-18T11:14:19","date_gmt":"2022-05-18T09:14:19","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=75591"},"modified":"2022-05-18T11:14:20","modified_gmt":"2022-05-18T09:14:20","slug":"frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/","title":{"rendered":"Frosinone citt\u00e0 cadio-protetta, il progetto di Stefano Belli"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;Perch\u00e9 i defibrillatori in citta? La morte cardiaca improvvisa \u00e8 una delle maggiori cause di mortalit\u00e0 fra giovani e adulti. Se non si \u00e8 in grado di intervenire in pochi minuti (5\/6 al massimo) con un massaggio cardiaco e una scarica elettrica la morte sopraggiunge. L\u2019unico modo per poter intervenire in un tempo cos\u00ec limitato, \u00e8 quello di avere sul territorio una forte dotazione di defibrillatori da diffondere su suolo pubblico. Lo sostiene Stefano Belli, candidato al consiglio comunale per la lista <strong>\u201cFROSINONE CAPOLUOGO\u201d,<\/strong> nonch\u00e9 gi\u00e0 sindaco di Patrica per tre legislature. \u00a0La presenza di defibrillatori semiautomatici DAE adeguatamente segnalati servono per salvaguardare i cittadini e offrire loro una possibilit\u00e0 in pi\u00f9 di sopravvivenza in caso di arresto cardiaco. L&#8217;obiettivo \u00e8 anche formare attraverso corsi BLS-D (Basic Life Support-Defibrillation) i cittadini che si rendono volontari. Diffondere nella popolazione la cultura del primo soccorso in situazioni di emergenza  &#8211; prosegue Belli &#8211; \u00e8 cosa importantissima e rende una citta all\u2019avanguardia. Inoltre mantenere in perfetto stato di funzionamento i defibrillatori nel tempo, attraverso un adeguato programma di assistenza e manutenzione DAE \u00e8 fondamentale. Tutto ci\u00f2 rende una citt\u00e0 sicura a livello sanitario. Il progetto  &#8211; conclude Belli &#8211; si rivolge principalmente alle Amministrazioni Comunali ma anche ad Associazioni di Volontariato o chiunque voglia contribuire a rendere la sua citt\u00e0 pi\u00f9 sicura, per far si che la vivibilit\u00e0 tra la gente sia notevolmente protetta. Penso che il nuovo sindaco dovr\u00e0 tenere in considerazione questa iniziativa. Belli conclude dicendo: \u201cNessuno meglio del Dott. Riccardo Mastrangeli potr\u00e0 organizzare questo pogetto\u201d<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"718\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/frosinone.capoluogo.jpg\" alt=\"\" class=\"wp-image-75300\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/frosinone.capoluogo.jpg 720w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/frosinone.capoluogo-300x300.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/frosinone.capoluogo-150x150.jpg 150w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Perch\u00e9 i defibrillatori in citta? La morte cardiaca improvvisa \u00e8 una delle maggiori cause di mortalit\u00e0 fra giovani e adulti.<\/p>\n","protected":false},"author":26,"featured_media":75592,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[14730,2033,14706],"class_list":["post-75591","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-frosinone-capoluogo","tag-riccardo-mastrangeli","tag-stefano-belli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone citt\u00e0 cadio-protetta, il progetto di Stefano Belli - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone citt\u00e0 cadio-protetta, il progetto di Stefano Belli\" \/>\n<meta property=\"og:description\" content=\"&#8220;Perch\u00e9 i defibrillatori in citta? La morte cardiaca improvvisa \u00e8 una delle maggiori cause di mortalit\u00e0 fra giovani e adulti.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-18T09:14:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-18T09:14:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/stefano-belli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"689\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/18\\\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/18\\\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Frosinone citt\u00e0 cadio-protetta, il progetto di Stefano Belli\",\"datePublished\":\"2022-05-18T09:14:19+00:00\",\"dateModified\":\"2022-05-18T09:14:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/18\\\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\\\/\"},\"wordCount\":259,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/18\\\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/stefano-belli.jpg\",\"keywords\":[\"frosinone capoluogo\",\"riccardo mastrangeli\",\"stefano belli\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/18\\\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/18\\\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\\\/\",\"name\":\"Frosinone citt\u00e0 cadio-protetta, il progetto di Stefano Belli - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/18\\\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/18\\\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/stefano-belli.jpg\",\"datePublished\":\"2022-05-18T09:14:19+00:00\",\"dateModified\":\"2022-05-18T09:14:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/18\\\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/18\\\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/18\\\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/stefano-belli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/stefano-belli.jpg\",\"width\":689,\"height\":466},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/18\\\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone citt\u00e0 cadio-protetta, il progetto di Stefano Belli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/18\\\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/18\\\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/18\\\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone citt\u00e0 cadio-protetta, il progetto di Stefano Belli - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone citt\u00e0 cadio-protetta, il progetto di Stefano Belli","og_description":"&#8220;Perch\u00e9 i defibrillatori in citta? La morte cardiaca improvvisa \u00e8 una delle maggiori cause di mortalit\u00e0 fra giovani e adulti.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-05-18T09:14:19+00:00","article_modified_time":"2022-05-18T09:14:20+00:00","og_image":[{"width":689,"height":466,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/stefano-belli.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Frosinone citt\u00e0 cadio-protetta, il progetto di Stefano Belli","datePublished":"2022-05-18T09:14:19+00:00","dateModified":"2022-05-18T09:14:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/"},"wordCount":259,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/stefano-belli.jpg","keywords":["frosinone capoluogo","riccardo mastrangeli","stefano belli"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/","name":"Frosinone citt\u00e0 cadio-protetta, il progetto di Stefano Belli - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/stefano-belli.jpg","datePublished":"2022-05-18T09:14:19+00:00","dateModified":"2022-05-18T09:14:20+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/stefano-belli.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/stefano-belli.jpg","width":689,"height":466},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone citt\u00e0 cadio-protetta, il progetto di Stefano Belli"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/18\/frosinone-citta-cadio-protetta-il-progetto-di-stefano-belli\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/75591","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=75591"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/75591\/revisions"}],"predecessor-version":[{"id":75593,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/75591\/revisions\/75593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/75592"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=75591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=75591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=75591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}