{"id":75064,"date":"2022-05-10T12:57:46","date_gmt":"2022-05-10T10:57:46","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=75064"},"modified":"2022-05-10T12:57:48","modified_gmt":"2022-05-10T10:57:48","slug":"un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/","title":{"rendered":"\u2018Un seme per il futuro\u2019, l\u2019Upi sceglie il progetto della Provincia di Frosinone"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Provincia di Frosinone tra le migliori d\u2019Italia grazie all\u2019azione promossa tra i giovani a favore dell\u2019educazione e della sostenibilit\u00e0 ambientale.<strong> Il presidente della Provincia di Frosinone Antonio Pompeo parteciper\u00e0 domani, mercoled\u00ec 11 maggio<\/strong>, all\u2019evento conclusivo che nell\u2019ambito dell\u2019Azione Province Giovani accender\u00e0 i riflettori sui progetti realizzati dalle Province e dalle UPI regionali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il progetto <strong>\u2018Un Seme per il Futuro-In ricordo di Michela Sau\u2019<\/strong>, realizzato dalla Provincia di Frosinone, \u00e8 stato scelto, infatti, per aprire l\u2019evento istituzionale dell\u2019UPI (Unione Province di Italia) e dar\u00e0 la possibilit\u00e0 agli stessi giovani protagonisti di intervenire e raccontare la loro esperienza formativa. Intitolato alla memoria della dottoressa Michela Sau, responsabile del Servizio Civile e Cooperazione Internazionale della Provincia, prematuramente scomparsa nel gennaio del 2021, il progetto parte dal binomio ambiente e futuro con l\u2019obiettivo di mettere a disposizione della futura generazione di cittadini gli strumenti necessari per promuovere azioni nel rispetto e per la tutela dell\u2019ambiente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"621\" height=\"439\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/Michela-Sau.jpg\" alt=\"Michela Sau\" class=\"wp-image-69295\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/Michela-Sau.jpg 621w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/Michela-Sau-300x212.jpg 300w\" sizes=\"auto, (max-width: 621px) 100vw, 621px\" \/><figcaption>Michela Sau<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante questi mesi i ragazzi coinvolti del progetto si sono trovati a seguire un ricco programma di incontri grazie ad un percorso promosso dagli uffici dell\u2019<strong>Azienda Speciale Frosinone Formazione<\/strong> e coordinato dal professor Andrea Crescenzi, ricercatore dell\u2019Istituto di Studi Giuridici Internazionali (Isgi), organo scientifico del CNR. Il lavoro ha coinvolto anche l\u2019Associazione \u2018We Save the Water\u2019 come realt\u00e0 associativa che sul territorio ha lanciato progetti legati alla sostenibilit\u00e0 ambientale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cerimonia prender\u00e0 il via alle 15 all\u2019Hotel Quirinale (Via Nazionale, 7) e sar\u00e0 possibile seguirla anche online al link https:\/\/us02web.zoom.us\/j\/84714789482?pwd=cTU3Q1BRb1Q0YTJTdlUzcDJhbFNoZz09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u2018Un seme per il futuro\u2019, l\u2019Upi sceglie il progetto della Provincia di Frosinone<\/p>\n","protected":false},"author":26,"featured_media":75065,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236,38],"tags":[2407,842,94,93,12281,14815],"class_list":["post-75064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","category-scuola","tag-agenzia-frosinone-formazione","tag-antonio-pompeo","tag-ciociaria","tag-frosinone","tag-michela-sau","tag-province-giovani"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>\u2018Un seme per il futuro\u2019, l\u2019Upi sceglie il progetto della Provincia di Frosinone - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u2018Un seme per il futuro\u2019, l\u2019Upi sceglie il progetto della Provincia di Frosinone\" \/>\n<meta property=\"og:description\" content=\"\u2018Un seme per il futuro\u2019, l\u2019Upi sceglie il progetto della Provincia di Frosinone\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-10T10:57:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-10T10:57:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/province-giovani.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"778\" \/>\n\t<meta property=\"og:image:height\" content=\"513\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/10\\\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/10\\\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"\u2018Un seme per il futuro\u2019, l\u2019Upi sceglie il progetto della Provincia di Frosinone\",\"datePublished\":\"2022-05-10T10:57:46+00:00\",\"dateModified\":\"2022-05-10T10:57:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/10\\\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\\\/\"},\"wordCount\":278,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/10\\\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/province-giovani.jpg\",\"keywords\":[\"agenzia frosinone formazione\",\"antonio pompeo\",\"Ciociaria\",\"Frosinone\",\"michela sau\",\"province giovani\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\",\"Scuola\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/10\\\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/10\\\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\\\/\",\"name\":\"\u2018Un seme per il futuro\u2019, l\u2019Upi sceglie il progetto della Provincia di Frosinone - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/10\\\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/10\\\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/province-giovani.jpg\",\"datePublished\":\"2022-05-10T10:57:46+00:00\",\"dateModified\":\"2022-05-10T10:57:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/10\\\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/10\\\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/10\\\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/province-giovani.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/province-giovani.jpg\",\"width\":778,\"height\":513},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/10\\\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u2018Un seme per il futuro\u2019, l\u2019Upi sceglie il progetto della Provincia di Frosinone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/10\\\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/10\\\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/10\\\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"\u2018Un seme per il futuro\u2019, l\u2019Upi sceglie il progetto della Provincia di Frosinone - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/","og_locale":"it_IT","og_type":"article","og_title":"\u2018Un seme per il futuro\u2019, l\u2019Upi sceglie il progetto della Provincia di Frosinone","og_description":"\u2018Un seme per il futuro\u2019, l\u2019Upi sceglie il progetto della Provincia di Frosinone","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-05-10T10:57:46+00:00","article_modified_time":"2022-05-10T10:57:48+00:00","og_image":[{"width":778,"height":513,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/province-giovani.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"\u2018Un seme per il futuro\u2019, l\u2019Upi sceglie il progetto della Provincia di Frosinone","datePublished":"2022-05-10T10:57:46+00:00","dateModified":"2022-05-10T10:57:48+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/"},"wordCount":278,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/province-giovani.jpg","keywords":["agenzia frosinone formazione","antonio pompeo","Ciociaria","Frosinone","michela sau","province giovani"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0","Scuola"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/","name":"\u2018Un seme per il futuro\u2019, l\u2019Upi sceglie il progetto della Provincia di Frosinone - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/province-giovani.jpg","datePublished":"2022-05-10T10:57:46+00:00","dateModified":"2022-05-10T10:57:48+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/province-giovani.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/province-giovani.jpg","width":778,"height":513},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"\u2018Un seme per il futuro\u2019, l\u2019Upi sceglie il progetto della Provincia di Frosinone"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/10\/un-seme-per-il-futuro-lupi-sceglie-il-progetto-della-provincia-di-frosinone\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/75064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=75064"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/75064\/revisions"}],"predecessor-version":[{"id":75066,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/75064\/revisions\/75066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/75065"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=75064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=75064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=75064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}