{"id":74975,"date":"2022-05-08T10:02:22","date_gmt":"2022-05-08T08:02:22","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=74975"},"modified":"2022-05-09T11:17:32","modified_gmt":"2022-05-09T09:17:32","slug":"frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/","title":{"rendered":"Frosinone, Campagna con Iacovissi: rigeneriamo la citt\u00e0 con nuove idee"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Frosinone ha bisogno di rigenerarsi dal punto di vista ambientale, sociale e politico con l\u2019energia, l\u2019entusiasmo e la competenza di una nuova generazione che sappia guardare avanti, senza nostalgie per il passato<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cos\u00ec <strong>Marco Campagna, candidato alle prossime elezioni comunali di Frosinone nella lista del PSI<\/strong> a sostegno di Vincenzo Iacovissi Sindaco. Trentotto anni, laureato in Marketing e Comunicazione, Campagna per 5 anni ha lavorato presso il Consiglio Regionale del Lazio su diversi dossier legati all\u2019emergenza ambientale della Valle del Sacco e allo sviluppo sostenibile della nostra provincia. <strong>Oggi lavora per un\u2019importante realt\u00e0 del terzo settore<\/strong> del territorio che si prende cura di persone fragili e con un\u2019organizzazione nazionale che sta portando nelle principali citt\u00e0 italiane progetti di integrazione e inclusione sociale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Faccio parte di una generazione che ha visto Frosinone svuotarsi, restare saldamente nelle ultime posizioni per la qualit\u00e0 della vita e non offrire spazi e servizi all\u2019altezza di un capoluogo &#8211; spiega Marco Campagna &#8211; La stessa generazione che troppo spesso, per costruirsi un futuro, \u00e8 stata costretta ad andarsene o ad accontentarsi, mettendo da parte sogni e aspirazioni. <strong>Con queste elezioni abbiamo la possibilit\u00e0 di invertire la rotta con un sindaco trentanovenne che ha un progetto chiaro <\/strong>su cosa deve essere Frosinone: una grande citt\u00e0 dell\u2019innovazione e della sostenibilit\u00e0&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Per il candidato consigliere Campagna, <strong>Frosinone deve diventare una citt\u00e0 capace di attrarre nuove aziende<\/strong> con una mobilit\u00e0 sostenibile, servizi efficienti e spazi per la comunit\u00e0.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Basta interventi spot che non cambiano le cose &#8211; conclude Campagna &#8211; Frosinone ha bisogno di rigenerarsi con una collaborazione attiva tra imprese, istituzioni e cittadini, avendo come primo obiettivo la riduzione dell\u2019inquinamento. Una citt\u00e0 in cui, ponendo fine al degrado, si dovr\u00e0 garantire il bene comune, partendo dall\u2019adozione di una Carta dei servizi minimi, come proposto dal candidato sindaco Iacovissi&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frosinone, Campagna con Iacovissi: rigeneriamo la citt\u00e0 con nuove idee<\/p>\n","protected":false},"author":26,"featured_media":74977,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2236,28],"tags":[4291,94,80,93,14808,1241,4275],"class_list":["post-74975","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-politica","tag-capoluogo","tag-ciociaria","tag-elezioni","tag-frosinone","tag-marco-campagna","tag-psi","tag-vincenzo-iacovissi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, Campagna con Iacovissi: rigeneriamo la citt\u00e0 con nuove idee - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, Campagna con Iacovissi: rigeneriamo la citt\u00e0 con nuove idee\" \/>\n<meta property=\"og:description\" content=\"Frosinone, Campagna con Iacovissi: rigeneriamo la citt\u00e0 con nuove idee\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-08T08:02:22+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-09T09:17:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/Marco-Campagna.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"771\" \/>\n\t<meta property=\"og:image:height\" content=\"514\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/08\\\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/08\\\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Frosinone, Campagna con Iacovissi: rigeneriamo la citt\u00e0 con nuove idee\",\"datePublished\":\"2022-05-08T08:02:22+00:00\",\"dateModified\":\"2022-05-09T09:17:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/08\\\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\\\/\"},\"wordCount\":316,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/08\\\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/Marco-Campagna.jpg\",\"keywords\":[\"capoluogo\",\"Ciociaria\",\"Elezioni\",\"Frosinone\",\"marco campagna\",\"psi\",\"Vincenzo Iacovissi\"],\"articleSection\":[\"Attualit\u00e0\",\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/08\\\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/08\\\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\\\/\",\"name\":\"Frosinone, Campagna con Iacovissi: rigeneriamo la citt\u00e0 con nuove idee - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/08\\\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/08\\\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/Marco-Campagna.jpg\",\"datePublished\":\"2022-05-08T08:02:22+00:00\",\"dateModified\":\"2022-05-09T09:17:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/08\\\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/08\\\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/08\\\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/Marco-Campagna.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/05\\\/Marco-Campagna.jpg\",\"width\":771,\"height\":514,\"caption\":\"Marco Campagna\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/08\\\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, Campagna con Iacovissi: rigeneriamo la citt\u00e0 con nuove idee\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/08\\\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/08\\\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/05\\\/08\\\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, Campagna con Iacovissi: rigeneriamo la citt\u00e0 con nuove idee - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, Campagna con Iacovissi: rigeneriamo la citt\u00e0 con nuove idee","og_description":"Frosinone, Campagna con Iacovissi: rigeneriamo la citt\u00e0 con nuove idee","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-05-08T08:02:22+00:00","article_modified_time":"2022-05-09T09:17:32+00:00","og_image":[{"width":771,"height":514,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/Marco-Campagna.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Frosinone, Campagna con Iacovissi: rigeneriamo la citt\u00e0 con nuove idee","datePublished":"2022-05-08T08:02:22+00:00","dateModified":"2022-05-09T09:17:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/"},"wordCount":316,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/Marco-Campagna.jpg","keywords":["capoluogo","Ciociaria","Elezioni","Frosinone","marco campagna","psi","Vincenzo Iacovissi"],"articleSection":["Attualit\u00e0","Evidenza"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/","name":"Frosinone, Campagna con Iacovissi: rigeneriamo la citt\u00e0 con nuove idee - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/Marco-Campagna.jpg","datePublished":"2022-05-08T08:02:22+00:00","dateModified":"2022-05-09T09:17:32+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/Marco-Campagna.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/05\/Marco-Campagna.jpg","width":771,"height":514,"caption":"Marco Campagna"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, Campagna con Iacovissi: rigeneriamo la citt\u00e0 con nuove idee"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/05\/08\/frosinone-campagna-con-iacovissi-rigeneriamo-la-citta-con-nuove-idee\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/74975","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=74975"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/74975\/revisions"}],"predecessor-version":[{"id":74978,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/74975\/revisions\/74978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/74977"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=74975"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=74975"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=74975"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}