{"id":74289,"date":"2022-04-26T18:55:44","date_gmt":"2022-04-26T16:55:44","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=74289"},"modified":"2022-04-26T18:55:45","modified_gmt":"2022-04-26T16:55:45","slug":"progetto-shoah-a-breve-le-attivita-riservate-agli-studenti","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/","title":{"rendered":"Progetto Shoah: a breve le attivit\u00e0 riservate agli studenti"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00c8 terminata la parte del corso di formazione sulla Shoah dedicato ai docenti, mentre stanno per avere inizio le attivit\u00e0 riservate agli studenti. Il progetto, nel suo complesso, \u00e8 intitolato <strong>\u2018Luoghi della Memoria: la Shoah e l\u2019internamento in Ciociaria\u2019.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il progetto \u00e8 stato predisposto dopo la pubblicazione dell\u2019avviso pubblico della Regione Lazio denominato \u2018Valorizzazione della Memoria storica del Lazio\u2019 ed \u00e8 stato <strong>organizzato da Irase Nazionale, dal Progetto Memoria, dalla Uil-Istituto Italo Viglianesi e dalla Regione Lazio.<\/strong> Vale la pena sottolineare anche il patrocinio fornito dalla provincia di Frosinone. Continuano cos\u00ec gli eventi e le conferenze facenti parte del corso che \u00e8 volto a sensibilizzare la provincia di Frosinone, ed in particolare la Val di Comino,\u00a0 sugli internamenti,\u00a0 sugli arresti e sulle deportazioni avvenuti nelle zone interessate.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;ultimo webinar live \u00e8 stato riservato&nbsp; &#8211; come premesso &#8211; a dare contezza agli insegnanti di tutte le specificit\u00e0 di uno spaccato storico &#8211; quello territoriale &#8211; che ha rischiato purtroppo di rimanere sconosciuto per troppo tempo ma, adesso, l&#8217;Irase Nazionale e gli altri enti interessati si concentreranno sui giovani che frequentano le scuole aderenti. Sono molte le classi dei vari istituti che hanno deciso di prendere parte al progetto che prevede incontri laboratoriali inerenti alle leggi anti-ebraiche ed alla Shoah, alcuni summit con due testimoni della pi\u00f9 grande tragedia storica del &#8216;900 &#8211;&nbsp; conferenze che sono stati organizzati grazie a Progetto Memoria, che \u00e8 il capofila di \u2018Luoghi della Memoria: la Shoah e l&#8217;internamento in Ciociaria\u2019 &#8211; , una visita al ghetto di Roma e, infine, il momento pi\u00f9 importante del progetto, ossia la visita al Museo della Shoah e del &#8216;900 di San Donato Val di Comino, che \u00e8 poi il luogo attorno cui ruota &#8220;Luoghi della Memoria: la Shoah e l&#8217;internamento in Ciociaria&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tra le classi che hanno deciso di prendere parte a questa fase \u00e8 possibile annoverare: <strong>due classi del Ic San Bernardo di Casamari; cinque classi dell&#8217;Ic di Arpino; due classi dell&#8217;Itis di Cassino; cinque classi dell&#8217;Ic di Sora 3; due classi dell&#8217;Ic di Roccasecca e cinque classi dell&#8217;Ic di Aquino.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Progetto Shoah: a breve le attivit\u00e0 riservate agli studenti<\/p>\n","protected":false},"author":26,"featured_media":5599,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,38],"tags":[94,93,14756,2556,562,2053],"class_list":["post-74289","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-scuola","tag-ciociaria","tag-frosinone","tag-irase","tag-memoria","tag-regione-lazio","tag-shoah"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Progetto Shoah: a breve le attivit\u00e0 riservate agli studenti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Progetto Shoah: a breve le attivit\u00e0 riservate agli studenti\" \/>\n<meta property=\"og:description\" content=\"Progetto Shoah: a breve le attivit\u00e0 riservate agli studenti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-26T16:55:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-26T16:55:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/shoah-nazismo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"620\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Progetto Shoah: a breve le attivit\u00e0 riservate agli studenti\",\"datePublished\":\"2022-04-26T16:55:44+00:00\",\"dateModified\":\"2022-04-26T16:55:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\\\/\"},\"wordCount\":352,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/shoah-nazismo.jpg\",\"keywords\":[\"Ciociaria\",\"Frosinone\",\"irase\",\"memoria\",\"regione lazio\",\"shoah\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Scuola\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\\\/\",\"name\":\"Progetto Shoah: a breve le attivit\u00e0 riservate agli studenti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/shoah-nazismo.jpg\",\"datePublished\":\"2022-04-26T16:55:44+00:00\",\"dateModified\":\"2022-04-26T16:55:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/shoah-nazismo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/01\\\/shoah-nazismo.jpg\",\"width\":620,\"height\":425,\"caption\":\"Shoah\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Progetto Shoah: a breve le attivit\u00e0 riservate agli studenti\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Progetto Shoah: a breve le attivit\u00e0 riservate agli studenti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/","og_locale":"it_IT","og_type":"article","og_title":"Progetto Shoah: a breve le attivit\u00e0 riservate agli studenti","og_description":"Progetto Shoah: a breve le attivit\u00e0 riservate agli studenti","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-04-26T16:55:44+00:00","article_modified_time":"2022-04-26T16:55:45+00:00","og_image":[{"width":620,"height":425,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/shoah-nazismo.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Progetto Shoah: a breve le attivit\u00e0 riservate agli studenti","datePublished":"2022-04-26T16:55:44+00:00","dateModified":"2022-04-26T16:55:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/"},"wordCount":352,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/shoah-nazismo.jpg","keywords":["Ciociaria","Frosinone","irase","memoria","regione lazio","shoah"],"articleSection":["*PRIMO PIANO*","Scuola"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/","name":"Progetto Shoah: a breve le attivit\u00e0 riservate agli studenti - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/shoah-nazismo.jpg","datePublished":"2022-04-26T16:55:44+00:00","dateModified":"2022-04-26T16:55:45+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/shoah-nazismo.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/shoah-nazismo.jpg","width":620,"height":425,"caption":"Shoah"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Progetto Shoah: a breve le attivit\u00e0 riservate agli studenti"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/progetto-shoah-a-breve-le-attivita-riservate-agli-studenti\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/74289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=74289"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/74289\/revisions"}],"predecessor-version":[{"id":74290,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/74289\/revisions\/74290"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/5599"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=74289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=74289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=74289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}