{"id":74281,"date":"2022-04-26T16:55:58","date_gmt":"2022-04-26T14:55:58","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=74281"},"modified":"2022-04-26T16:57:34","modified_gmt":"2022-04-26T14:57:34","slug":"anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/","title":{"rendered":"Anagni, Ciacciarelli: mentre la Lega con Giorgetti\u00a0 finanzia Sanofi\u00a0 il PD fa scappare Catalent"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br>\u201cLa Lega al governo \u00e8 il partito delle risposte concrete. Ne \u00e8 testimonianza l\u2019operato del ministro dello Sviluppo Economico Giancarlo Giorgetti che annuncia l\u2019investimento di 27 milioni di euro sulla Sanofi tramite un accordo che mira alla crescita dello&nbsp; stabilimento farmaceutico ciociaro. In questo modo si salvaguarderanno i posti di lavoro, creando anche nuove opportunit\u00e0 lavorative in tal senso. Il PD prenda esempio! Nella nostra provincia \u00e8 stato capace solo di bloccare investimenti. Sono anni che sollecito Provincia e Regione ad accelerare sulle autorizzazioni ambientali. Il presidente della Regione Lazio ha letteralmente scaricato tutte le responsabilit\u00e0 sulla provincia di Frosinone. Quello a cui stiamo assistendo \u00e8 l\u2019ennesimo teatrino di una sinistra incapace anche di sedersi unita ad un tavolo per discutere i problemi e risolverli.<br>Un bilancio pessimo per l\u2019amministrazione regionale di Zingaretti. La Lega al governo, invece, \u00e8 sinonimo di operosit\u00e0 e concretezza.\u201d<br>Lo dichiara, in una nota, il consigliere regionale del Lazio Pasquale Ciacciarelli (Lega)&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cLa Lega al governo \u00e8 il partito delle risposte concrete. Ne \u00e8 testimonianza l\u2019operato del ministro dello Sviluppo Economico Giancarlo<\/p>\n","protected":false},"author":26,"featured_media":74282,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[1336],"class_list":["post-74281","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-pasquale-ciacciarelli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Anagni, Ciacciarelli: mentre la Lega con Giorgetti\u00a0 finanzia Sanofi\u00a0 il PD fa scappare Catalent - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Anagni, Ciacciarelli: mentre la Lega con Giorgetti\u00a0 finanzia Sanofi\u00a0 il PD fa scappare Catalent\" \/>\n<meta property=\"og:description\" content=\"\u201cLa Lega al governo \u00e8 il partito delle risposte concrete. Ne \u00e8 testimonianza l\u2019operato del ministro dello Sviluppo Economico Giancarlo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-26T14:55:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-26T14:57:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/04\/Polish_20220426_165347774.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1197\" \/>\n\t<meta property=\"og:image:height\" content=\"969\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Anagni, Ciacciarelli: mentre la Lega con Giorgetti\u00a0 finanzia Sanofi\u00a0 il PD fa scappare Catalent\",\"datePublished\":\"2022-04-26T14:55:58+00:00\",\"dateModified\":\"2022-04-26T14:57:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\\\/\"},\"wordCount\":171,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/Polish_20220426_165347774.jpg\",\"keywords\":[\"pasquale ciacciarelli\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\\\/\",\"name\":\"Anagni, Ciacciarelli: mentre la Lega con Giorgetti\u00a0 finanzia Sanofi\u00a0 il PD fa scappare Catalent - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/Polish_20220426_165347774.jpg\",\"datePublished\":\"2022-04-26T14:55:58+00:00\",\"dateModified\":\"2022-04-26T14:57:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/Polish_20220426_165347774.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/Polish_20220426_165347774.jpg\",\"width\":1197,\"height\":969},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Anagni, Ciacciarelli: mentre la Lega con Giorgetti\u00a0 finanzia Sanofi\u00a0 il PD fa scappare Catalent\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/26\\\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Anagni, Ciacciarelli: mentre la Lega con Giorgetti\u00a0 finanzia Sanofi\u00a0 il PD fa scappare Catalent - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/","og_locale":"it_IT","og_type":"article","og_title":"Anagni, Ciacciarelli: mentre la Lega con Giorgetti\u00a0 finanzia Sanofi\u00a0 il PD fa scappare Catalent","og_description":"\u201cLa Lega al governo \u00e8 il partito delle risposte concrete. Ne \u00e8 testimonianza l\u2019operato del ministro dello Sviluppo Economico Giancarlo","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-04-26T14:55:58+00:00","article_modified_time":"2022-04-26T14:57:34+00:00","og_image":[{"width":1197,"height":969,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/04\/Polish_20220426_165347774.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Anagni, Ciacciarelli: mentre la Lega con Giorgetti\u00a0 finanzia Sanofi\u00a0 il PD fa scappare Catalent","datePublished":"2022-04-26T14:55:58+00:00","dateModified":"2022-04-26T14:57:34+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/"},"wordCount":171,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/04\/Polish_20220426_165347774.jpg","keywords":["pasquale ciacciarelli"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/","name":"Anagni, Ciacciarelli: mentre la Lega con Giorgetti\u00a0 finanzia Sanofi\u00a0 il PD fa scappare Catalent - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/04\/Polish_20220426_165347774.jpg","datePublished":"2022-04-26T14:55:58+00:00","dateModified":"2022-04-26T14:57:34+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/04\/Polish_20220426_165347774.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/04\/Polish_20220426_165347774.jpg","width":1197,"height":969},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Anagni, Ciacciarelli: mentre la Lega con Giorgetti\u00a0 finanzia Sanofi\u00a0 il PD fa scappare Catalent"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/26\/anagni-ciacciarelli-mentre-la-lega-con-giorgetti-finanzia-sanofi-il-pd-fa-scappare-catalent\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/74281","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=74281"}],"version-history":[{"count":3,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/74281\/revisions"}],"predecessor-version":[{"id":74287,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/74281\/revisions\/74287"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/74282"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=74281"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=74281"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=74281"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}