{"id":7424,"date":"2019-02-28T18:21:19","date_gmt":"2019-02-28T17:21:19","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=7424"},"modified":"2020-09-25T20:13:23","modified_gmt":"2020-09-25T18:13:23","slug":"otto-aziende-ciociare-alla-milano-fashion-week","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/","title":{"rendered":"Otto aziende ciociare alla Milano Fashion Week"},"content":{"rendered":"<p>La<strong> Milano Fashion Week<\/strong> si conclude con un <strong>risultato esaltante per la provincia di Frosinone<\/strong>: le <strong>otto aziende<\/strong> arrivate nel capoluogo lombardo, <strong>affiancate da Aspiin\/Camera di Commerci<\/strong>o, grazie al progetto<strong> \u2018Moda: la grande bellezza italiana\u2019<\/strong>, cofinanziato da Unioncamere Lazio, hanno avuto la possibilit\u00e0 di mettersi in mostra nella capitale della moda, <strong>dal 21 al 23 febbraio<\/strong>, all\u2019interno di uno degli eventi fashion pi\u00f9 seguiti a livello internazionale.<\/p>\n<p>Sono riuscite ad attirare l\u2019attenzione di curiosi, esperti di moda, artisti e blogger tra i pi\u00f9 conosciuti, che hanno preso parte, in veste di ospiti, a molti degli eventi in programma nel temporary showroom di Aspiin\/Camera di Commercio.<\/p>\n<h2>In mostra dal 21 al 23 febbraio<\/h2>\n<p>Ad aprire la serie di eventi, <strong>gioved\u00ec 21 febbraio<\/strong>, \u00e8 stato il <strong>Fab Lab Frosinone<\/strong> con Digital Wearable Network: la fabbrica di idee frusinate si \u00e8 confrontata con i laboratori di OpenDot e WeMake sui temi del Fashion Design &amp; Wearable Technology, la tecnologia applicata alla moda.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7425 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano1.jpg\" alt=\"fashion week milano il corriere della provincia\" width=\"410\" height=\"615\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano1.jpg 410w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano1-200x300.jpg 200w\" sizes=\"auto, (max-width: 410px) 100vw, 410px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Durante l\u2019iniziativa sono stati presentati i lavori degli studenti dell\u2019Accademia di Belle Arti di Napoli e di Reshape, Studio Noumena di Barcellona. <strong>Venerd\u00ec 22 febbraio<\/strong> \u00e8 stata la volta di <strong>Giada Curti Resort<\/strong> con la collezione &#8216;Jackie&#8217;, dedicata all\u2019icona senza tempo di Jacqueline Kennedy Onassis. All\u2019esclusivo trunk show dell\u2019atelier ha partecipato anche la conduttrice di Real Time Csaba Dalla Zorza. Sempre nella giornata di venerd\u00ec 22 febbraio, l\u2019azienda <strong>Snc Style<\/strong> ha presentato le ultime novit\u00e0 in fatto di moda e stile durante il Friday Bartender Event.<\/p>\n<p><strong>Sabato 23 febbraio il Fab Lab Frosinone \u00e8 \u2018tornato in cattedra\u2019<\/strong> con la #FashionDigitalNight, iniziativa promossa dalla Fondazione Mondo Digitale che, dopo aver calcato le passerelle di Altaroma \u00e8 approdata alla Milano Fashion Week.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7426 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano2.jpg\" alt=\"milano fashion week il corriere della provincia\" width=\"538\" height=\"717\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano2.jpg 538w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano2-225x300.jpg 225w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano2-500x666.jpg 500w\" sizes=\"auto, (max-width: 538px) 100vw, 538px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>L\u2019abilit\u00e0 dei giovani talenti e il contributo che l\u2019innovazione tecnologica possono apportare al settore della moda sono stati gli argomenti trattati al #FashionDigitalNight, con la partecipazione di Jessica Pullo di Biotico, che ha presentato l\u2019abito vincitore del premio #DigitalMade, realizzato in tessuto ecosostenibile.<\/p>\n<h2>L&#8217;Accademia di Belle Arti<\/h2>\n<p>I riflettori dello showroom sono stati puntati anche sui lavori degli studenti dell\u2019Accademia di Belle Arti di Frosinone e sugli allestimenti delle altre aziende presenti:<strong> La Fabbri<\/strong> e <strong>Qman<\/strong> con le rispettive collezioni di borse ed accessori,<strong> Ottica Sbardella<\/strong> con l\u2019angolo dedicato all\u2019eyewear, <strong>Mariel Alta Classe<\/strong> con le creazioni della stilista <strong>Marilena Spiridigliozzi<\/strong>. L\u2019atelier di Arce ha avuto una testimonial d\u2019eccezione per valorizzare i suoi abiti: la comica televisiva Francesca Macr\u00ec.<\/p>\n<p>A curare make up e hair style durante gli eventi dello showroom sono stati <strong>Loredana Giansanti<\/strong> e <strong>Carmelo Spina<\/strong>, quest\u2019ultimo protagonista di un vero e proprio show durante la preparazione delle acconciature. Entrambe gli esperti di immagine lavorano nei backstage di spettacoli Rai e Mediaset.<\/p>\n<p>&nbsp;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-7427 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano3.jpg\" alt=\"\" width=\"706\" height=\"507\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano3.jpg 706w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano3-300x215.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano3-500x359.jpg 500w\" sizes=\"auto, (max-width: 706px) 100vw, 706px\" \/><\/p>\n<p>&nbsp;<\/p>\n<h2>I commenti di Pigliacelli e Rocca<\/h2>\n<p>&#8220;La Ciociaria \u2013 ha detto il presidente della Camera di Commercio di Frosinone, <strong>Marcello Pigliacelli<\/strong> &#8211; \u00e8 la terra dei cammini, \u00e8 la terra dei talenti, \u00e8 la terra delle imprese e dei professionisti che sanno raccogliere le sfide ed innovarsi. Questa iniziativa, dedicata alla grande bellezza italiana, ci ha permesso di mostrare la grande bellezza interpretata dal nostro settore moda, l\u2019estro degli studenti dell\u2019Accademia di Belle Arti, l\u2019ingegno del Fab Lab Frosinone. Approdare in una vetrina come la Fashion Week \u00e8 un primo risultato. Adesso, per crescere ulteriormente, bisogna prima di tutto credere nelle nostre capacit\u00e0&#8221;.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_5744\" aria-describedby=\"caption-attachment-5744\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-5744 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/pigliacelli-rocca-e1548766893704.jpg\" alt=\"pigliacelli rocca camera commercio il corriere della provincia\" width=\"632\" height=\"295\"><figcaption id=\"caption-attachment-5744\" class=\"wp-caption-text\">Da sinistra Genesio Rocca e Marcello Pigliacelli<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Soddisfatto per l\u2019andamento della manifestazione il <strong>presidente dell\u2019Aspiin, Genesio Rocca<\/strong>: &#8220;Il nostro progetto era molto ambizioso, abbiamo avuto l\u2019opportunit\u00e0 di essere presenti ad una delle manifestazioni pi\u00f9 seguite di sempre dell\u2019Alta Moda. Le nostre aziende hanno brillato per stile ed innovazione, eleganza e coraggio. Sicuramente questa esperienza non dovr\u00e0 restare isolata, e lavoreremo affinch\u00e9 la presenza del<strong> made in Ciociaria<\/strong> diventi sempre pi\u00f9 importante anche in questo tipo di eventi, che sono ossigeno per lo sviluppo, l\u2019export e l\u2019economia in generale&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Milano Fashion Week si conclude con un risultato esaltante per la provincia di Frosinone: le otto aziende arrivate nel<\/p>\n","protected":false},"author":18,"featured_media":7428,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11397],"tags":[2128,1013,2774,2773,2127,2775,2126,2776,2124],"class_list":["post-7424","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-moda","tag-aspiin","tag-camera-di-commercio","tag-fab-lab","tag-fashion-week","tag-genesio-rocca","tag-giada-curti","tag-marcello-pigliacelli","tag-mariel","tag-milano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Otto aziende ciociare alla Milano Fashion Week - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Otto aziende ciociare hanno preso parte alla Milano Fashion Week grazie al progetto di Camera di Commercio\/Aspiin &#039;Moda, la grande bellezza italiana&#039;\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Otto aziende ciociare alla Milano Fashion Week\" \/>\n<meta property=\"og:description\" content=\"Otto aziende ciociare hanno preso parte alla Milano Fashion Week grazie al progetto di Camera di Commercio\/Aspiin &#039;Moda, la grande bellezza italiana&#039;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-28T17:21:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-09-25T18:13:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano4-e1551374403823.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"356\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/28\\\/otto-aziende-ciociare-alla-milano-fashion-week\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/28\\\/otto-aziende-ciociare-alla-milano-fashion-week\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Otto aziende ciociare alla Milano Fashion Week\",\"datePublished\":\"2019-02-28T17:21:19+00:00\",\"dateModified\":\"2020-09-25T18:13:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/28\\\/otto-aziende-ciociare-alla-milano-fashion-week\\\/\"},\"wordCount\":666,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/28\\\/otto-aziende-ciociare-alla-milano-fashion-week\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/02\\\/fashion-week-milano4-e1551374403823.jpg\",\"keywords\":[\"aspiin\",\"Camera di Commercio\",\"fab lab\",\"fashion week\",\"genesio rocca\",\"giada curti\",\"marcello pigliacelli\",\"mariel\",\"milano\"],\"articleSection\":[\"Moda &amp; Mood\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/28\\\/otto-aziende-ciociare-alla-milano-fashion-week\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/28\\\/otto-aziende-ciociare-alla-milano-fashion-week\\\/\",\"name\":\"Otto aziende ciociare alla Milano Fashion Week - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/28\\\/otto-aziende-ciociare-alla-milano-fashion-week\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/28\\\/otto-aziende-ciociare-alla-milano-fashion-week\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/02\\\/fashion-week-milano4-e1551374403823.jpg\",\"datePublished\":\"2019-02-28T17:21:19+00:00\",\"dateModified\":\"2020-09-25T18:13:23+00:00\",\"description\":\"Otto aziende ciociare hanno preso parte alla Milano Fashion Week grazie al progetto di Camera di Commercio\\\/Aspiin 'Moda, la grande bellezza italiana'\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/28\\\/otto-aziende-ciociare-alla-milano-fashion-week\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/28\\\/otto-aziende-ciociare-alla-milano-fashion-week\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/28\\\/otto-aziende-ciociare-alla-milano-fashion-week\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/02\\\/fashion-week-milano4-e1551374403823.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/02\\\/fashion-week-milano4-e1551374403823.jpg\",\"width\":632,\"height\":356,\"caption\":\"milano fashion week il corriere della ciociaria\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/28\\\/otto-aziende-ciociare-alla-milano-fashion-week\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Otto aziende ciociare alla Milano Fashion Week\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/28\\\/otto-aziende-ciociare-alla-milano-fashion-week\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/28\\\/otto-aziende-ciociare-alla-milano-fashion-week\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/28\\\/otto-aziende-ciociare-alla-milano-fashion-week\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Otto aziende ciociare alla Milano Fashion Week - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Otto aziende ciociare hanno preso parte alla Milano Fashion Week grazie al progetto di Camera di Commercio\/Aspiin 'Moda, la grande bellezza italiana'","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/","og_locale":"it_IT","og_type":"article","og_title":"Otto aziende ciociare alla Milano Fashion Week","og_description":"Otto aziende ciociare hanno preso parte alla Milano Fashion Week grazie al progetto di Camera di Commercio\/Aspiin 'Moda, la grande bellezza italiana'","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-02-28T17:21:19+00:00","article_modified_time":"2020-09-25T18:13:23+00:00","og_image":[{"width":632,"height":356,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano4-e1551374403823.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Otto aziende ciociare alla Milano Fashion Week","datePublished":"2019-02-28T17:21:19+00:00","dateModified":"2020-09-25T18:13:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/"},"wordCount":666,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano4-e1551374403823.jpg","keywords":["aspiin","Camera di Commercio","fab lab","fashion week","genesio rocca","giada curti","marcello pigliacelli","mariel","milano"],"articleSection":["Moda &amp; Mood"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/","name":"Otto aziende ciociare alla Milano Fashion Week - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano4-e1551374403823.jpg","datePublished":"2019-02-28T17:21:19+00:00","dateModified":"2020-09-25T18:13:23+00:00","description":"Otto aziende ciociare hanno preso parte alla Milano Fashion Week grazie al progetto di Camera di Commercio\/Aspiin 'Moda, la grande bellezza italiana'","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano4-e1551374403823.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/fashion-week-milano4-e1551374403823.jpg","width":632,"height":356,"caption":"milano fashion week il corriere della ciociaria"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Otto aziende ciociare alla Milano Fashion Week"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/28\/otto-aziende-ciociare-alla-milano-fashion-week\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/7424","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=7424"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/7424\/revisions"}],"predecessor-version":[{"id":46193,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/7424\/revisions\/46193"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/7428"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=7424"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=7424"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=7424"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}