{"id":73873,"date":"2022-04-18T19:35:39","date_gmt":"2022-04-18T17:35:39","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=73873"},"modified":"2022-04-18T19:36:06","modified_gmt":"2022-04-18T17:36:06","slug":"frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/","title":{"rendered":"Frosinone, nuovi marciapiedi e riqualificazione del cimitero"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">L\u2019amministrazione Ottaviani, attraverso l\u2019assessorato all\u2019ambiente, coordinato da Massimiliano Tagliaferri, sta effettuando i lavori di riqualificazione esterna del sito cimiteriale di Colle Cottorino, realizzando il marciapiede lungo tutto il perimetro dell\u2019area ovest, mettendo in sicurezza, in tal modo, i pedoni in transito verso i relativi tre cancelli di entrata. Il programma dei lavori, inoltre, prevede la riqualificazione del muro perimetrale con il convogliamento dei discendenti delle cappelle e delle tombe esterne che, da oltre mezzo secolo, raccoglievano le acque pluvie con una dispersione diffusa, tale da danneggiare l\u2019intera infrastruttura. Una volta terminati i lavori sul versante ovest, si passer\u00e0 alla riqualificazione del viale centrale del cimitero monumentale, migliorando ulteriormente il decoro, il contesto generale in cui viene coltivata la piet\u00e0 dei defunti.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"250\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/04\/lista-ottaviani_17-04-2022_16-45_banner300x250.jpg\" alt=\"\" class=\"wp-image-73860\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"> Le opere sono state finanziate attraverso il piano di gestione cimiteriale, il quale prevede che tutti gli introiti derivanti dai versamenti dei congiunti siano reinvestiti all\u2019interno di specifici capitoli di spesa, attinenti alla gestione dei servizi comuni e all\u2019ampliamento e ammodernamento delle strutture. A questo scopo, l\u2019amministrazione Ottaviani ha impegnato anche, nel prossimo bilancio, l\u2019importo di 70.000 euro per procedere alla redazione del piano particolareggiato di iniziativa pubblica che produrr\u00e0, tra i tanti, anche l\u2019effetto della riduzione del vincolo cimiteriale, permettendo la definizione delle numerose pratiche edilizie delle abitazioni poste a ridosso dell\u2019area.\u00a0<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"295\" height=\"252\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/04\/mastrangeli-banner.jpg\" alt=\"\" class=\"wp-image-73786\" \/><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019amministrazione Ottaviani, attraverso l\u2019assessorato all\u2019ambiente, coordinato da Massimiliano Tagliaferri, sta effettuando i lavori di riqualificazione esterna del sito cimiteriale di<\/p>\n","protected":false},"author":26,"featured_media":73874,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[93,639],"class_list":["post-73873","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-frosinone","tag-nicola-ottaviani"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, nuovi marciapiedi e riqualificazione del cimitero - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, nuovi marciapiedi e riqualificazione del cimitero\" \/>\n<meta property=\"og:description\" content=\"L\u2019amministrazione Ottaviani, attraverso l\u2019assessorato all\u2019ambiente, coordinato da Massimiliano Tagliaferri, sta effettuando i lavori di riqualificazione esterna del sito cimiteriale di\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-18T17:35:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-18T17:36:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/04\/Screenshot_20220418-193236_Gmail.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"661\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/18\\\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/18\\\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Frosinone, nuovi marciapiedi e riqualificazione del cimitero\",\"datePublished\":\"2022-04-18T17:35:39+00:00\",\"dateModified\":\"2022-04-18T17:36:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/18\\\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\\\/\"},\"wordCount\":231,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/18\\\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/Screenshot_20220418-193236_Gmail.jpg\",\"keywords\":[\"Frosinone\",\"nicola ottaviani\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/18\\\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/18\\\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\\\/\",\"name\":\"Frosinone, nuovi marciapiedi e riqualificazione del cimitero - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/18\\\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/18\\\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/Screenshot_20220418-193236_Gmail.jpg\",\"datePublished\":\"2022-04-18T17:35:39+00:00\",\"dateModified\":\"2022-04-18T17:36:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/18\\\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/18\\\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/18\\\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/Screenshot_20220418-193236_Gmail.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/04\\\/Screenshot_20220418-193236_Gmail.jpg\",\"width\":720,\"height\":661},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/18\\\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, nuovi marciapiedi e riqualificazione del cimitero\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/18\\\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/18\\\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/18\\\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, nuovi marciapiedi e riqualificazione del cimitero - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, nuovi marciapiedi e riqualificazione del cimitero","og_description":"L\u2019amministrazione Ottaviani, attraverso l\u2019assessorato all\u2019ambiente, coordinato da Massimiliano Tagliaferri, sta effettuando i lavori di riqualificazione esterna del sito cimiteriale di","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-04-18T17:35:39+00:00","article_modified_time":"2022-04-18T17:36:06+00:00","og_image":[{"width":720,"height":661,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/04\/Screenshot_20220418-193236_Gmail.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Frosinone, nuovi marciapiedi e riqualificazione del cimitero","datePublished":"2022-04-18T17:35:39+00:00","dateModified":"2022-04-18T17:36:06+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/"},"wordCount":231,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/04\/Screenshot_20220418-193236_Gmail.jpg","keywords":["Frosinone","nicola ottaviani"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/","name":"Frosinone, nuovi marciapiedi e riqualificazione del cimitero - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/04\/Screenshot_20220418-193236_Gmail.jpg","datePublished":"2022-04-18T17:35:39+00:00","dateModified":"2022-04-18T17:36:06+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/04\/Screenshot_20220418-193236_Gmail.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/04\/Screenshot_20220418-193236_Gmail.jpg","width":720,"height":661},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, nuovi marciapiedi e riqualificazione del cimitero"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/18\/frosinone-nuovi-marciapiedi-e-riqualificazione-del-cimitero\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/73873","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=73873"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/73873\/revisions"}],"predecessor-version":[{"id":73875,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/73873\/revisions\/73875"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/73874"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=73873"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=73873"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=73873"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}