{"id":73716,"date":"2022-04-14T12:34:52","date_gmt":"2022-04-14T10:34:52","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=73716"},"modified":"2022-04-14T12:34:54","modified_gmt":"2022-04-14T10:34:54","slug":"catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/","title":{"rendered":"Catalent in fuga, il presidente di Unindustria Lazio scrive al Sole24Ore"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La decisione della Catalent di spostare gli investimenti da Anagni ad Oxford ha provocato una ridda di reazioni sul territorio e, in modo particolare, tra le associazioni di categoria.<strong> Anche il presidente di Unindustria Lazio, Angelo Camilli, ha scritto al Sole24Ore sottolineando la dr<\/strong>ammatica situazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cGentile Direttore, con grande amarezza devo prendere atto che Catalent, azienda farmaceutica multinazionale attiva anche nel Lazio, <strong>si \u00e8 trovata costretta a rinunciare ad un investimento di 100 milioni di euro ad Anagni<\/strong>, per un centro di sviluppo sulla produzione innovativa di materie prime biologiche che avrebbe garantito il rinnovo del contratto di 100 brillanti giovani ricercatori che da domani non avranno pi\u00f9 un posto di lavoro.<strong>\u00a0 Tutto questo valore potenziale<\/strong>, per l\u2019inefficienza della burocrazia italiana e di tempi autorizzativi fuori da ogni logica, <strong>finir\u00e0 invece in Inghilterra.<\/strong> \u00c8 la conclusione tristissima di una vicenda che va avanti ormai da pi\u00f9 di due anni, da quando l\u2019azienda ha avviato un procedimento di caratterizzazione ambientale nel perimetro del Sito di Interesse Nazionale (SIN) \u2018Bacino del Fiume Sacco\u2019. Unindustria e Confindustria hanno seguito con attenzione il caso e incessanti sono state le azioni su tutti i livelli nazionali e locali per scongiurare questo epilogo imbarazzante per l\u2019intero sistema Paese\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/catalent-anagni.jpeg\" alt=\"\" class=\"wp-image-55033\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/catalent-anagni.jpeg 600w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/03\/catalent-anagni-300x200.jpeg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><figcaption>Lo stabilimento Catalent ad Anagni<\/figcaption><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cPurtroppo, la vicenda di Catalent \u00e8 sicuramente la pi\u00f9 eclatante, ma non \u00e8 e non sar\u00e0 l\u2019ultima finch\u00e9 non si interverr\u00e0 sulle tempistiche eccessivamente lunghe di rilascio delle autorizzazioni, in particolar modo quelle ambientali, necessarie all\u2019insediamento o anche solo alla normale continuazione dell\u2019attivit\u00e0 d\u2019impresa. <strong>A pagarne le conseguenze, infatti, \u00e8 l\u2019intero tessuto produttivo italiano<\/strong> che si trova a combattere contro una pubblica amministrazione anti impresa e a rinunciare, spesso, a nuovi investimenti che significano innovazione, lavoro di qualit\u00e0 e crescita economica. Come sistema delle imprese non possiamo pi\u00f9 tollerare una situazione di questo genere. Chiediamo con forza tempi degni di uno Stato che vanta ancora la seconda manifattura d\u2019Europa e non pu\u00f2 ritenere accettabile che una richiesta di autorizzazione rimanga ferma su una scrivania senza risposta per due anni. Queste attese non sono compatibili con la vita e lo sviluppo di un\u2019impresa, ma pi\u00f9 in generale di un paese civile e industrializzato\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cBisogna prevedere \u2013 chiude la lettera di Camilli &#8211; una radicale semplificazione delle autorizzazioni, ma soprattutto termini certi per le pratiche, superati i quali deve scattare una sanzione economica severa in caso di inadempimento. Chiediamo con forza al Presidente del Consiglio Mario Draghi e al Ministro della Transizione Ecologica Roberto Cingolani di intervenire immediatamente per evitare altre Catalent sul nostro territorio nazionale. In un momento cos\u00ec difficile come quello che stiamo attraversando, un intervento sullo sblocco delle autorizzazioni ambientali sarebbe certamente un messaggio positivo per l\u2019Italia.&nbsp; Ci sono cortei e contestazioni davanti ad una fabbrica che annuncia di chiudere. Non c\u2019\u00e8 mai nessuno davanti alle porte di un\u2019azienda che rinuncia ad aprire\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Catalent in fuga, Camilli (Unindustria Lazio) scrive al Sole24Ore<\/p>\n","protected":false},"author":26,"featured_media":46509,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[41,2236],"tags":[441,10606,12729,94,93,3722,170],"class_list":["post-73716","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","category-attualita","tag-anagni","tag-angelo-camilli","tag-catalent","tag-ciociaria","tag-frosinone","tag-investimento","tag-unindustria"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Catalent in fuga, il presidente di Unindustria Lazio scrive al Sole24Ore - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Catalent in fuga, il presidente di Unindustria Lazio scrive al Sole24Ore\" \/>\n<meta property=\"og:description\" content=\"Catalent in fuga, Camilli (Unindustria Lazio) scrive al Sole24Ore\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-14T10:34:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-14T10:34:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Angelo-Camilli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"848\" \/>\n\t<meta property=\"og:image:height\" content=\"592\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/14\\\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/14\\\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Catalent in fuga, il presidente di Unindustria Lazio scrive al Sole24Ore\",\"datePublished\":\"2022-04-14T10:34:52+00:00\",\"dateModified\":\"2022-04-14T10:34:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/14\\\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\\\/\"},\"wordCount\":489,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/14\\\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/Angelo-Camilli.jpg\",\"keywords\":[\"anagni\",\"angelo camilli\",\"catalent\",\"Ciociaria\",\"Frosinone\",\"investimento\",\"Unindustria\"],\"articleSection\":[\"*SLIDE*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/14\\\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/14\\\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\\\/\",\"name\":\"Catalent in fuga, il presidente di Unindustria Lazio scrive al Sole24Ore - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/14\\\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/14\\\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/Angelo-Camilli.jpg\",\"datePublished\":\"2022-04-14T10:34:52+00:00\",\"dateModified\":\"2022-04-14T10:34:54+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/14\\\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/14\\\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/14\\\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/Angelo-Camilli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/09\\\/Angelo-Camilli.jpg\",\"width\":848,\"height\":592},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/14\\\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Catalent in fuga, il presidente di Unindustria Lazio scrive al Sole24Ore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/14\\\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/14\\\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/04\\\/14\\\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Catalent in fuga, il presidente di Unindustria Lazio scrive al Sole24Ore - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/","og_locale":"it_IT","og_type":"article","og_title":"Catalent in fuga, il presidente di Unindustria Lazio scrive al Sole24Ore","og_description":"Catalent in fuga, Camilli (Unindustria Lazio) scrive al Sole24Ore","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-04-14T10:34:52+00:00","article_modified_time":"2022-04-14T10:34:54+00:00","og_image":[{"width":848,"height":592,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Angelo-Camilli.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Catalent in fuga, il presidente di Unindustria Lazio scrive al Sole24Ore","datePublished":"2022-04-14T10:34:52+00:00","dateModified":"2022-04-14T10:34:54+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/"},"wordCount":489,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Angelo-Camilli.jpg","keywords":["anagni","angelo camilli","catalent","Ciociaria","Frosinone","investimento","Unindustria"],"articleSection":["*SLIDE*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/","name":"Catalent in fuga, il presidente di Unindustria Lazio scrive al Sole24Ore - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Angelo-Camilli.jpg","datePublished":"2022-04-14T10:34:52+00:00","dateModified":"2022-04-14T10:34:54+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Angelo-Camilli.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/09\/Angelo-Camilli.jpg","width":848,"height":592},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Catalent in fuga, il presidente di Unindustria Lazio scrive al Sole24Ore"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/04\/14\/catalent-in-fuga-il-presidente-di-unindustria-lazio-scrive-al-sole24ore\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/73716","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=73716"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/73716\/revisions"}],"predecessor-version":[{"id":73717,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/73716\/revisions\/73717"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/46509"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=73716"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=73716"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=73716"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}