{"id":7311,"date":"2019-02-27T12:57:47","date_gmt":"2019-02-27T11:57:47","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=7311"},"modified":"2019-02-27T19:10:55","modified_gmt":"2019-02-27T18:10:55","slug":"primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/","title":{"rendered":"Primi effetti dell\u2019ecotassa: Fca investe 4,5 miliardi a Detroit"},"content":{"rendered":"<p><strong>Quattro miliardi e mezzo di euro<\/strong> e <strong>6.500 posti di lavoro<\/strong>. Ma non certo in Ciociaria, nello stabilimento di Piedimonte San Germano. <strong>A Detroit<\/strong>, invece: <strong>\u00e8 l\u00ec che Fca sta dirottando queste ingenti risorse<\/strong>.<\/p>\n<p>E subito il <strong>consigliere regionale<\/strong> di <strong>Forza Italia, Pasquale Ciacciarelli<\/strong>, lancia l\u2019allarme, rinnovando l\u2019appello ai parlamentari eletti e a Nicola Zingaretti a dialogare con il governo per scongiurare gli effetti dell\u2019ecotassa sull\u2019indotto.<\/p>\n<h2>Le parole di Ciacciarelli<\/h2>\n<p>&#8220;Avevo scritto, tempo fa, a tutti i deputati e senatori eletti nella provincia di Frosinone, di Lega e M5s, al ministro del Lavoro e dello Sviluppo Economico Luigi Di Maio, di aver presentato un<strong> ordine del giorno<\/strong> in Regione Lazio per impegnare il presidente <strong>Nicola Zingaretti<\/strong> a dialogare con il governo per scongiurare gli effetti dell\u2019ecotassa. Ma \u00e8 evidente \u2013 sottolinea Ciacciarelli &#8211; che nulla \u00e8 stato fatto.<strong> Quello di Piedimonte San Germano \u00e8 il primo stabilimento industriale del Lazio, qualcuno lo ha dimenticato&#8221;<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_1303\" aria-describedby=\"caption-attachment-1303\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-1303 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/11\/pasquale-cicciarelli-e1546167085557.jpeg\" alt=\"ciacciarelli regione lazio settefrati canneto protezione civile frosinone ciociaria il corriere della provincia\" width=\"632\" height=\"421\" \/><figcaption id=\"caption-attachment-1303\" class=\"wp-caption-text\">Il consigliere regionale di Forza Italia Pasquale Ciacciarelli<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>&#8220;Questi sono gli effetti della sciagurata legge voluta da M5s e Lega, sull\u2019ecotassa, che sta ulteriormente mettendo in ginocchio una provincia, gi\u00e0 penalizzata dal punto di vista occupazionale. Parliamo di migliaia di lavoratori, delle loro famiglie, e del futuro di un intero territorio. Rinnovo l\u2019appello ai parlamentari e senatori eletti ed al presidente Zingaretti \u2013 conclude il consigliere regionale &#8211; affinch\u00e9 dialoghino con il governo per scongiurare un triste destino per tutto l\u2019indotto&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quattro miliardi e mezzo di euro e 6.500 posti di lavoro. Ma non certo in Ciociaria, nello stabilimento di Piedimonte<\/p>\n","protected":false},"author":18,"featured_media":3502,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,17],"tags":[1187,554,330,2721,1687,1336,194,562,1620,1523],"class_list":["post-7311","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-lavoro","tag-ecotassa","tag-fca","tag-governo","tag-indotto","tag-ordine-del-giorno","tag-pasquale-ciacciarelli","tag-piedimonte-san-germano","tag-regione-lazio","tag-risorse","tag-stabilimento"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Primi effetti dell\u2019ecotassa: Fca investe 4,5 miliardi a Detroit - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Fca investe quattro miliardi e mezzo di euro a Detroit e crea 6.500 posti di lavoro: il consigliere regionale di Forza Italia Ciacciarelli lancia l&#039;allarme\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Primi effetti dell\u2019ecotassa: Fca investe 4,5 miliardi a Detroit\" \/>\n<meta property=\"og:description\" content=\"Fca investe quattro miliardi e mezzo di euro a Detroit e crea 6.500 posti di lavoro: il consigliere regionale di Forza Italia Ciacciarelli lancia l&#039;allarme\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-27T11:57:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-02-27T18:10:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/stabilimento-fca-piedimonte-e1545222074353.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"317\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/27\\\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/27\\\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Primi effetti dell\u2019ecotassa: Fca investe 4,5 miliardi a Detroit\",\"datePublished\":\"2019-02-27T11:57:47+00:00\",\"dateModified\":\"2019-02-27T18:10:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/27\\\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\\\/\"},\"wordCount\":256,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/27\\\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/stabilimento-fca-piedimonte-e1545222074353.jpg\",\"keywords\":[\"Ecotassa\",\"Fca\",\"Governo\",\"indotto\",\"ordine del giorno\",\"pasquale ciacciarelli\",\"piedimonte san germano\",\"regione lazio\",\"risorse\",\"stabilimento\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Lavoro\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/27\\\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/27\\\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\\\/\",\"name\":\"Primi effetti dell\u2019ecotassa: Fca investe 4,5 miliardi a Detroit - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/27\\\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/27\\\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/stabilimento-fca-piedimonte-e1545222074353.jpg\",\"datePublished\":\"2019-02-27T11:57:47+00:00\",\"dateModified\":\"2019-02-27T18:10:55+00:00\",\"description\":\"Fca investe quattro miliardi e mezzo di euro a Detroit e crea 6.500 posti di lavoro: il consigliere regionale di Forza Italia Ciacciarelli lancia l'allarme\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/27\\\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/27\\\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/27\\\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/stabilimento-fca-piedimonte-e1545222074353.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/12\\\/stabilimento-fca-piedimonte-e1545222074353.jpg\",\"width\":632,\"height\":317,\"caption\":\"Lo stabilimento Fca di Piedimonte San Germano\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/27\\\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Primi effetti dell\u2019ecotassa: Fca investe 4,5 miliardi a Detroit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/27\\\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/27\\\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/27\\\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Primi effetti dell\u2019ecotassa: Fca investe 4,5 miliardi a Detroit - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Fca investe quattro miliardi e mezzo di euro a Detroit e crea 6.500 posti di lavoro: il consigliere regionale di Forza Italia Ciacciarelli lancia l'allarme","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/","og_locale":"it_IT","og_type":"article","og_title":"Primi effetti dell\u2019ecotassa: Fca investe 4,5 miliardi a Detroit","og_description":"Fca investe quattro miliardi e mezzo di euro a Detroit e crea 6.500 posti di lavoro: il consigliere regionale di Forza Italia Ciacciarelli lancia l'allarme","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-02-27T11:57:47+00:00","article_modified_time":"2019-02-27T18:10:55+00:00","og_image":[{"width":632,"height":317,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/stabilimento-fca-piedimonte-e1545222074353.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Primi effetti dell\u2019ecotassa: Fca investe 4,5 miliardi a Detroit","datePublished":"2019-02-27T11:57:47+00:00","dateModified":"2019-02-27T18:10:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/"},"wordCount":256,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/stabilimento-fca-piedimonte-e1545222074353.jpg","keywords":["Ecotassa","Fca","Governo","indotto","ordine del giorno","pasquale ciacciarelli","piedimonte san germano","regione lazio","risorse","stabilimento"],"articleSection":["*PRIMO PIANO*","Lavoro"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/","name":"Primi effetti dell\u2019ecotassa: Fca investe 4,5 miliardi a Detroit - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/stabilimento-fca-piedimonte-e1545222074353.jpg","datePublished":"2019-02-27T11:57:47+00:00","dateModified":"2019-02-27T18:10:55+00:00","description":"Fca investe quattro miliardi e mezzo di euro a Detroit e crea 6.500 posti di lavoro: il consigliere regionale di Forza Italia Ciacciarelli lancia l'allarme","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/stabilimento-fca-piedimonte-e1545222074353.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/stabilimento-fca-piedimonte-e1545222074353.jpg","width":632,"height":317,"caption":"Lo stabilimento Fca di Piedimonte San Germano"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Primi effetti dell\u2019ecotassa: Fca investe 4,5 miliardi a Detroit"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/27\/primi-effetti-dellecotassa-fca-investe-45-miliardi-a-detroit\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/7311","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=7311"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/7311\/revisions"}],"predecessor-version":[{"id":7312,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/7311\/revisions\/7312"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/3502"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=7311"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=7311"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=7311"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}