{"id":71478,"date":"2022-03-06T05:00:26","date_gmt":"2022-03-06T04:00:26","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=71478"},"modified":"2022-03-06T07:34:18","modified_gmt":"2022-03-06T06:34:18","slug":"scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/","title":{"rendered":"Scontro su Solidiamo, Marzi: fa sorridere il riferimento al politiburo dagli amici di Putin"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201cFa sorridere che il riferimento al Politb\u00fcro arrivi direttamente dagli eredi naturali di Vladimir Putin, ovvero coloro che hanno come riferimento politico Matteo Salvini. La corsa a disconoscere chi ha iniziato una guerra assurda non inganna nessuno. O ci siamo dimenticati i video con i vari \u2018cedo due Mattarella in cambio di mezzo Putin?\u2019. Il Partito democratico ha una cultura politica e una dialettica totalmente differenti da chi oggi amministra il comune di Frosinone. E ne siamo orgogliosi\u201d. Cos\u00ec in una nota Domenico Marzi, candidato sindaco del Partito democratico per le amministrative di Frosinone. &#8220;Per il solidiamo confermo assolutamente il \u2018soldi-diamo\u2019: una citt\u00e0 ben amministrata non si limita a dare ai suoi giovani mancette e medagliette, ma si adopera per dare un futuro e una prospettiva. Invece Frosinone \u00e8 una citt\u00e0 che in dieci anni si \u00e8 totalmente impoverita. Ha perso tremila abitanti, evidenziando di non essere attrattiva bens\u00ec respingente. Ha perso la Banca di Italia, la Camera di commercio, e potrei proseguire con un elenco lungo. Ha eliminato il finanziamento di centomila euro alla universit\u00e0 di Cassino, un investimento che offriva seriamente una opportunit\u00e0 ai giovani della nostra citt\u00e0. Non ha colto l\u2019occasione del progetto della citt\u00e0 intercomunale, una proposta del Presidente Turriziani che garantisce crescita e sviluppo. Quante volte sono stati convocati i sindaci dei comuni limitrofi per analizzare e approfondire le opportunit\u00e0 derivanti da Frosinone grande capoluogo? Non si \u00e8 fatto nulla. Entrer\u00f2 maggiormente nel dettaglio rispetto a come investire per offrire prospettive ai nostri giovani. Garantiremo modalit\u00e0 e tempi per premiare i meritevoli\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cFa sorridere che il riferimento al Politb\u00fcro arrivi direttamente dagli eredi naturali di Vladimir Putin, ovvero coloro che hanno come<\/p>\n","protected":false},"author":26,"featured_media":71368,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[12424,93,14537,6105],"class_list":["post-71478","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-domenico-marzi","tag-frosinone","tag-primarie-per-la-citta","tag-solidiamo"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Scontro su Solidiamo, Marzi: fa sorridere il riferimento al politiburo dagli amici di Putin - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Scontro su Solidiamo, Marzi: fa sorridere il riferimento al politiburo dagli amici di Putin\" \/>\n<meta property=\"og:description\" content=\"\u201cFa sorridere che il riferimento al Politb\u00fcro arrivi direttamente dagli eredi naturali di Vladimir Putin, ovvero coloro che hanno come\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-06T04:00:26+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-06T06:34:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/03\/20220303_192956-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1890\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/03\\\/06\\\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/03\\\/06\\\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Scontro su Solidiamo, Marzi: fa sorridere il riferimento al politiburo dagli amici di Putin\",\"datePublished\":\"2022-03-06T04:00:26+00:00\",\"dateModified\":\"2022-03-06T06:34:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/03\\\/06\\\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\\\/\"},\"wordCount\":270,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/03\\\/06\\\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/03\\\/20220303_192956-scaled.jpg\",\"keywords\":[\"domenico marzi\",\"Frosinone\",\"Primarie per la Citt\u00e0\",\"Solidiamo\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/03\\\/06\\\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/03\\\/06\\\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\\\/\",\"name\":\"Scontro su Solidiamo, Marzi: fa sorridere il riferimento al politiburo dagli amici di Putin - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/03\\\/06\\\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/03\\\/06\\\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/03\\\/20220303_192956-scaled.jpg\",\"datePublished\":\"2022-03-06T04:00:26+00:00\",\"dateModified\":\"2022-03-06T06:34:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/03\\\/06\\\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/03\\\/06\\\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/03\\\/06\\\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/03\\\/20220303_192956-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/03\\\/20220303_192956-scaled.jpg\",\"width\":2560,\"height\":1890},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/03\\\/06\\\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Scontro su Solidiamo, Marzi: fa sorridere il riferimento al politiburo dagli amici di Putin\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/03\\\/06\\\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/03\\\/06\\\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/03\\\/06\\\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Scontro su Solidiamo, Marzi: fa sorridere il riferimento al politiburo dagli amici di Putin - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/","og_locale":"it_IT","og_type":"article","og_title":"Scontro su Solidiamo, Marzi: fa sorridere il riferimento al politiburo dagli amici di Putin","og_description":"\u201cFa sorridere che il riferimento al Politb\u00fcro arrivi direttamente dagli eredi naturali di Vladimir Putin, ovvero coloro che hanno come","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-03-06T04:00:26+00:00","article_modified_time":"2022-03-06T06:34:18+00:00","og_image":[{"width":2560,"height":1890,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/03\/20220303_192956-scaled.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Scontro su Solidiamo, Marzi: fa sorridere il riferimento al politiburo dagli amici di Putin","datePublished":"2022-03-06T04:00:26+00:00","dateModified":"2022-03-06T06:34:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/"},"wordCount":270,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/03\/20220303_192956-scaled.jpg","keywords":["domenico marzi","Frosinone","Primarie per la Citt\u00e0","Solidiamo"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/","name":"Scontro su Solidiamo, Marzi: fa sorridere il riferimento al politiburo dagli amici di Putin - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/03\/20220303_192956-scaled.jpg","datePublished":"2022-03-06T04:00:26+00:00","dateModified":"2022-03-06T06:34:18+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/03\/20220303_192956-scaled.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/03\/20220303_192956-scaled.jpg","width":2560,"height":1890},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Scontro su Solidiamo, Marzi: fa sorridere il riferimento al politiburo dagli amici di Putin"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/03\/06\/scontro-su-solidiamo-marzi-fa-sorridere-il-riferimento-al-politiburo-dagli-amici-di-putin\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/71478","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=71478"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/71478\/revisions"}],"predecessor-version":[{"id":71481,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/71478\/revisions\/71481"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/71368"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=71478"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=71478"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=71478"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}