{"id":70976,"date":"2022-02-25T15:17:17","date_gmt":"2022-02-25T14:17:17","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=70976"},"modified":"2022-02-25T15:18:03","modified_gmt":"2022-02-25T14:18:03","slug":"tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/","title":{"rendered":"Tra passato e futuro, tavola rotonda su Papa Ormisda con il vescovo Spreafico e il direttore del Corriere della Sera"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u201cTra passato e futuro \u2013 Una terra in grado di esprimere grandi talenti\u201d \u00e8 il titolo dell\u2019iniziativa in programma domenica 27 febbraio, a partire dalle 14.30, presso l\u2019Auditorium diocesano San Paolo Apostolo, in viale Madrid a Frosinone.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un appuntamento voluto ed organizzato dalla <strong>Banca Popolare del Frusinate<\/strong> e che si svilupper\u00e0 in due tempi distinti, appunto tra passato e futuro, ma che avranno un comune denominatore, quello dei grandi talenti della terra di Ciociaria. Quelli che ci sono stati e quelli che verranno.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"620\" height=\"340\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/polselli-e-scaccia.jpg\" alt=\"\" class=\"wp-image-3660\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/polselli-e-scaccia.jpg 620w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/polselli-e-scaccia-300x165.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/12\/polselli-e-scaccia-500x274.jpg 500w\" sizes=\"auto, (max-width: 620px) 100vw, 620px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<em>Quest&#8217;anno il nostro istituto celebra i trent&#8217;anni della sua fondazione<\/em>&#8221; \u00e8 stata la dichiarazione del <strong>Presidente della Banca Domenico Polselli<\/strong> &#8220;<em>e avere ripreso la nostra attivit\u00e0 sociale e soprattutto pubblica dopo questo fermo forzato \u00e8 stato per noi un momento veramente emozionante. Sia pur in questo breve lasso di tempo, la nostra Banca ha raggiunto posizioni di eccellenza nel sistema creditizio italiano, e questi risultati rappresentano per i nostri Soci, per i nostri clienti e per noi, un momento di grande orgoglio. Ed \u00e8 proprio per queste circostanze che abbiamo ritenuto di proporre la presentazione del volume su papa Ormisda, insieme alla cerimonia di consegna delle borse di studio ai soci ed ai figli dei soci della nostra Banca<\/em>&#8220;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Saranno infatti loro, papa Ormisda e i ragazzi che saranno premiati, i veri protagonisti del pomeriggio presso l\u2019Auditorium diocesano del quartiere Cavoni. Da una parte, a cura del professor Umberto Caperna, la presentazione del volume \u201cOrmisda, Uomo di unit\u00e0\u201d, il papa del dialogo e dell\u2019incontro tra Oriente ed Occidente. Dall\u2019altra la cerimonia di consegna delle borse di studio ai soci e ai figli dei soci della Banca Popolare del Frusinate. Una cerimonia che da anni premia i giovani talenti invogliandoli a proseguire nei loro studi con passione e determinazione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quella di quest\u2019anno sar\u00e0 un\u2019edizione straordinaria, dal momento che verranno consegnate le borse di studio del 2020 e del 2021, rimandate a causa della pandemia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dopo i saluti affidati al presidente della Banca Popolare del Frusinate, Domenico Polselli; al prefetto di Frosinone Ernesto Liguori e al sindaco del capoluogo, Nicola Ottaviani, la presentazione del volume sar\u00e0 affidata al suo curatore, Umberto Caperna, ricercatore e professore emerito di latino e greco.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seguir\u00e0 una tavola rotonda alla quale parteciperanno il direttore del Corriere della Sera Luciano Fontana, frusinate di origine; il vescovo della Diocesi di Frosinone-Veroli-Ferentino, mons. Ambrogio Spreafico e il professor Francesco Tedeschi, docente di Liturgia e Sacramentaria alla Pontificia Universit\u00e0 Urbaniana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al termine della tavola rotonda si svolger\u00e0 la cerimonia di consegna delle borse di studio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<em>Di questa nostra storia, di questa cultura, di questi nostri giovani siamo profondamente orgogliosi<\/em>&#8221; commenta <strong>l&#8217;Amministratore Delegato della Banca Rinaldo Scaccia<\/strong> &#8220;<em>un appuntamento che sar\u00e0 momento di confronto, di dialogo, di partecipazione, con uno sguardo rivolto al passato, cogliendo l\u2019attualit\u00e0 del pensiero e del messaggio di Ormisda, e uno proiettato nel futuro, con la premiazione di giovani che si sono particolarmente distinti negli studi, a partire dalla licenza media e fino alla laurea magistrale. A dimostrazione che stiamo continuando a perseguire quelli che sono stati i valori fondanti del nostro istituto, ossia quello di essere una grande famiglia attenta alla storia ed alla cultura del nostro territorio ed ai giovani. E di questi nostri giovani, soci o figli di Soci della Banca molti dei quali ormai impegnati anche all&#8217;estero per lavoro o per approfondimento dei loro studi, noi siamo particolarmente orgogliosi.&#8221;<\/em><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel rispetto delle disposizioni in materia di emergenza pandemica, l\u2019ingresso sar\u00e0 consentito ai partecipanti muniti di mascherina FFP2 e in possesso del cosiddetto Green Pass rafforzato.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><a href=\"https:\/\/www.bpf.it\/\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"500\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/11\/BPF20062019_1700banner300x250-1.jpg\" alt=\"\" class=\"wp-image-66162\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/11\/BPF20062019_1700banner300x250-1.jpg 600w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/11\/BPF20062019_1700banner300x250-1-300x250.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u201cTra passato e futuro \u2013 Una terra in grado di esprimere grandi talenti\u201d \u00e8 il titolo dell\u2019iniziativa in programma domenica<\/p>\n","protected":false},"author":26,"featured_media":70977,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[504,5080],"class_list":["post-70976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-banca-popolare-del-frusinate","tag-luciano-fontana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Tra passato e futuro, tavola rotonda su Papa Ormisda con il vescovo Spreafico e il direttore del Corriere della Sera - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tra passato e futuro, tavola rotonda su Papa Ormisda con il vescovo Spreafico e il direttore del Corriere della Sera\" \/>\n<meta property=\"og:description\" content=\"\u201cTra passato e futuro \u2013 Una terra in grado di esprimere grandi talenti\u201d \u00e8 il titolo dell\u2019iniziativa in programma domenica\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-25T14:17:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-25T14:18:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/tra-passato-e-futuro.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"720\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/25\\\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/25\\\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Tra passato e futuro, tavola rotonda su Papa Ormisda con il vescovo Spreafico e il direttore del Corriere della Sera\",\"datePublished\":\"2022-02-25T14:17:17+00:00\",\"dateModified\":\"2022-02-25T14:18:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/25\\\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\\\/\"},\"wordCount\":608,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/25\\\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/tra-passato-e-futuro.jpg\",\"keywords\":[\"banca popolare del frusinate\",\"Luciano Fontana\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/25\\\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/25\\\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\\\/\",\"name\":\"Tra passato e futuro, tavola rotonda su Papa Ormisda con il vescovo Spreafico e il direttore del Corriere della Sera - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/25\\\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/25\\\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/tra-passato-e-futuro.jpg\",\"datePublished\":\"2022-02-25T14:17:17+00:00\",\"dateModified\":\"2022-02-25T14:18:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/25\\\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/25\\\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/25\\\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/tra-passato-e-futuro.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/tra-passato-e-futuro.jpg\",\"width\":720,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/25\\\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tra passato e futuro, tavola rotonda su Papa Ormisda con il vescovo Spreafico e il direttore del Corriere della Sera\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/25\\\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/25\\\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/25\\\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Tra passato e futuro, tavola rotonda su Papa Ormisda con il vescovo Spreafico e il direttore del Corriere della Sera - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/","og_locale":"it_IT","og_type":"article","og_title":"Tra passato e futuro, tavola rotonda su Papa Ormisda con il vescovo Spreafico e il direttore del Corriere della Sera","og_description":"\u201cTra passato e futuro \u2013 Una terra in grado di esprimere grandi talenti\u201d \u00e8 il titolo dell\u2019iniziativa in programma domenica","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-02-25T14:17:17+00:00","article_modified_time":"2022-02-25T14:18:03+00:00","og_image":[{"width":720,"height":445,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/tra-passato-e-futuro.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Tra passato e futuro, tavola rotonda su Papa Ormisda con il vescovo Spreafico e il direttore del Corriere della Sera","datePublished":"2022-02-25T14:17:17+00:00","dateModified":"2022-02-25T14:18:03+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/"},"wordCount":608,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/tra-passato-e-futuro.jpg","keywords":["banca popolare del frusinate","Luciano Fontana"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/","name":"Tra passato e futuro, tavola rotonda su Papa Ormisda con il vescovo Spreafico e il direttore del Corriere della Sera - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/tra-passato-e-futuro.jpg","datePublished":"2022-02-25T14:17:17+00:00","dateModified":"2022-02-25T14:18:03+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/tra-passato-e-futuro.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/tra-passato-e-futuro.jpg","width":720,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Tra passato e futuro, tavola rotonda su Papa Ormisda con il vescovo Spreafico e il direttore del Corriere della Sera"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/25\/tra-passato-e-futuro-tavola-rotonda-su-papa-ormisda-con-il-vescovo-spreafico-e-il-direttore-del-corriere-della-sera\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/70976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=70976"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/70976\/revisions"}],"predecessor-version":[{"id":70978,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/70976\/revisions\/70978"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/70977"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=70976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=70976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=70976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}