{"id":70837,"date":"2022-02-22T14:39:28","date_gmt":"2022-02-22T13:39:28","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=70837"},"modified":"2022-02-22T14:39:30","modified_gmt":"2022-02-22T13:39:30","slug":"vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/","title":{"rendered":"Vaccinazioni pediatriche: a Frosinone percentuali oltre la media nazionale e regionale"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Le vaccinazioni pediatriche in provincia di Frosinone hanno toccato quota 58%, una percentuale che va oltre la media sia nazionale che regionale. <strong>Un risultato importante per la campagna partita il 15 dicembre scorso e che, in due mesi ha gi\u00e0 messo in sicurezza pi\u00f9 della met\u00e0 dei giovani della fascia 5-11 anni<\/strong>, vincendo le resistenze anche dei pi\u00f9 scettici. Significative anche la percentuali del 98% per la fascia 12-15 e del 94% della fascia 16-19 che assicurano una protezione quasi completa della popolazione in et\u00e0 evolutiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I dati delle somministrazioni mostrano come ci siano enormi benefici dalla vaccinazione pediatrica, che evita ai pi\u00f9 piccoli, in caso di contagio, di avere pesanti ripercussioni sulla qualit\u00e0 della vita e sul loro stato di salute. Senza l\u2019adeguata protezione, <strong>il rischio \u00e8 lo sviluppo di sintomi che potrebbero anche durare a lungo: il cosiddetto \u201clong covid\u201d<\/strong>. Cefalea, disturbi del sonno, affaticamento, difficolt\u00e0 di concentrazione, dolori addominali, mialgie, dolore toracico, mal di stomaco, diarrea con conseguenze non solo fisiche ma anche dal punto di vista psicologico e sul loro sviluppo neuropsichico e sociale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa risposta della popolazione del Frusinate per la fascia 5-11 anni \u00e8 stata ottima \u2013 ha detto il <strong>dottor Luigi Di Ruzza, coordinatore del Dipartimento Materno-Infantile della Asl di Frosinone <\/strong>&#8211; grazie all\u2019importante lavoro svolto e all\u2019impegno profuso da tutti gli operatori sanitari (pediatri e personale dei centri vaccinali) nel sensibilizzare i genitori dei bambini, che sono stati particolarmente recettivi alle indicazioni chiare che venivano dal mondo medico pediatrico riguardo la sicurezza e l\u2019efficacia del vaccino ad mRNA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I pediatri ospedalieri e del territorio hanno lavorato e lavorano in sinergia tra loro e con i centri vaccinali, nell\u2019intento di dare un messaggio sempre univoco, non confondente, che ha gi\u00e0 ottenuto l\u2019effetto positivo di portare il numero dei vaccinati superiore alla media nazionale e regionale. Quando il lavoro \u00e8 sinergico i risultati che si ottengono sono sempre lusinghieri.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Resta inteso che l\u2019obiettivo che ci si prefigge \u00e8 quello di poter ottenere una copertura vaccinale ancora pi\u00f9 ampia di quella attuale, affinch\u00e9 la fascia di et\u00e0 interessata, tra le pi\u00f9 fragili, possa godere di uno stato di immunizzazione sempre pi\u00f9 elevato e rassicurante. Per questo l\u2019impegno di tutto il mondo pediatrico \u00e8 teso al raggiungimento di tale obiettivo\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vaccinazione pediatrica: a Frosinone percentuali oltre la media nazionale<\/p>\n","protected":false},"author":26,"featured_media":67255,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[94,8916,93,8898,14225],"class_list":["post-70837","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-salute","tag-ciociaria","tag-covid","tag-frosinone","tag-tampone","tag-vaccinazione-pediatrica"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Vaccinazioni pediatriche: a Frosinone percentuali oltre la media nazionale e regionale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vaccinazioni pediatriche: a Frosinone percentuali oltre la media nazionale e regionale\" \/>\n<meta property=\"og:description\" content=\"Vaccinazione pediatrica: a Frosinone percentuali oltre la media nazionale\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-22T13:39:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-22T13:39:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/12\/vaccinazione-pediatrica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"849\" \/>\n\t<meta property=\"og:image:height\" content=\"478\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/22\\\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/22\\\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Vaccinazioni pediatriche: a Frosinone percentuali oltre la media nazionale e regionale\",\"datePublished\":\"2022-02-22T13:39:28+00:00\",\"dateModified\":\"2022-02-22T13:39:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/22\\\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\\\/\"},\"wordCount\":383,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/22\\\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/12\\\/vaccinazione-pediatrica.jpg\",\"keywords\":[\"Ciociaria\",\"covid\",\"Frosinone\",\"tampone\",\"vaccinazione pediatrica\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Salute e Benessere\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/22\\\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/22\\\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\\\/\",\"name\":\"Vaccinazioni pediatriche: a Frosinone percentuali oltre la media nazionale e regionale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/22\\\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/22\\\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/12\\\/vaccinazione-pediatrica.jpg\",\"datePublished\":\"2022-02-22T13:39:28+00:00\",\"dateModified\":\"2022-02-22T13:39:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/22\\\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/22\\\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/22\\\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/12\\\/vaccinazione-pediatrica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/12\\\/vaccinazione-pediatrica.jpg\",\"width\":849,\"height\":478,\"caption\":\"Vaccinazione pediatrica\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/22\\\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vaccinazioni pediatriche: a Frosinone percentuali oltre la media nazionale e regionale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/22\\\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/22\\\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/22\\\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Vaccinazioni pediatriche: a Frosinone percentuali oltre la media nazionale e regionale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/","og_locale":"it_IT","og_type":"article","og_title":"Vaccinazioni pediatriche: a Frosinone percentuali oltre la media nazionale e regionale","og_description":"Vaccinazione pediatrica: a Frosinone percentuali oltre la media nazionale","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-02-22T13:39:28+00:00","article_modified_time":"2022-02-22T13:39:30+00:00","og_image":[{"width":849,"height":478,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/12\/vaccinazione-pediatrica.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Vaccinazioni pediatriche: a Frosinone percentuali oltre la media nazionale e regionale","datePublished":"2022-02-22T13:39:28+00:00","dateModified":"2022-02-22T13:39:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/"},"wordCount":383,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/12\/vaccinazione-pediatrica.jpg","keywords":["Ciociaria","covid","Frosinone","tampone","vaccinazione pediatrica"],"articleSection":["*PRIMO PIANO*","Salute e Benessere"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/","name":"Vaccinazioni pediatriche: a Frosinone percentuali oltre la media nazionale e regionale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/12\/vaccinazione-pediatrica.jpg","datePublished":"2022-02-22T13:39:28+00:00","dateModified":"2022-02-22T13:39:30+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/12\/vaccinazione-pediatrica.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/12\/vaccinazione-pediatrica.jpg","width":849,"height":478,"caption":"Vaccinazione pediatrica"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Vaccinazioni pediatriche: a Frosinone percentuali oltre la media nazionale e regionale"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/22\/vaccinazioni-pediatriche-a-frosinone-percentuali-oltre-la-media-nazionale-e-regionale\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/70837","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=70837"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/70837\/revisions"}],"predecessor-version":[{"id":70838,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/70837\/revisions\/70838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/67255"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=70837"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=70837"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=70837"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}