{"id":70386,"date":"2022-02-10T15:31:30","date_gmt":"2022-02-10T14:31:30","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=70386"},"modified":"2022-02-10T15:31:31","modified_gmt":"2022-02-10T14:31:31","slug":"pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/","title":{"rendered":"Pompeo nominato nel Consiglio direttivo nazionale dell\u2019albo dei segretari"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Nuovo incarico per il <strong>presidente della Provincia, Antonio Pompeo<\/strong>. Con un decreto a firma del Ministro dell\u2019Interno, Luciana Lamorgese, Pompeo, in rappresentanza delle Province, \u00e8 stato nominato c<strong>omponente del Consiglio direttivo per l\u2019Albo nazionale dei segretari comunali e provinciali per il triennio 2022-2024<\/strong>, del quale tra gli altri, fanno parte anche il ministro o il sottosegretario di Stato, il capo del Dipartimento per gli Affari interni e territoriali, quello per l\u2019amministrazione generale, i prefetti di Bari e Torino, Upi e Anci.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si tratta di un organismo che ha poteri di gestione e amministrazione oltre che di promozione delle attivit\u00e0:<strong> \u00e8 sostanzialmente l\u2019organo \u2018esecutivo\u2019 <\/strong>che, tra l\u2019altro, decide su provvedimenti disciplinari, regolamento e organizzazione interna, affari di ordine amministrativo e qualsiasi altra iniziativa inerente gli iscritti all\u2019Albo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cRingrazio il ministro dell\u2019Interno Lamorgese e l\u2019Upi per questa designazione \u2013 ha detto il presidente Pompeo \u2013 e auguro buon lavoro agli altri membri che ne sono entrati a far parte. Ancora una volta la dimostrazione che il ruolo delle Province \u00e8 centrale e operativo, anche relativamente a incarichi riguardanti figure istituzionali chiave per l\u2019Amministrazione degli Enti Locali, come quella del segretario comunale e provinciale di cui si riscontra una sensibile carenza. Continueremo il nostro lavoro, dando ogni contributo utile e concreto per una gestione corretta e trasparente della cosa pubblica\u201d.<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Il presidente Pompeo nominato nel Consiglio direttivo dell&#8217;Albo nazionale dei segretari provinciali e comunali<\/p>\n","protected":false},"author":26,"featured_media":70388,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[842,94,7625,93,9155,800,14472],"class_list":["post-70386","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-antonio-pompeo","tag-ciociaria","tag-consiglio-direttivo","tag-frosinone","tag-luciana-lamorgese","tag-ministro","tag-segretari-provinciali"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Pompeo nominato nel Consiglio direttivo nazionale dell\u2019albo dei segretari - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pompeo nominato nel Consiglio direttivo nazionale dell\u2019albo dei segretari\" \/>\n<meta property=\"og:description\" content=\"Il presidente Pompeo nominato nel Consiglio direttivo dell&#039;Albo nazionale dei segretari provinciali e comunali\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-10T14:31:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-10T14:31:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/Presidente-Pompeo.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"797\" \/>\n\t<meta property=\"og:image:height\" content=\"512\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/10\\\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/10\\\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Pompeo nominato nel Consiglio direttivo nazionale dell\u2019albo dei segretari\",\"datePublished\":\"2022-02-10T14:31:30+00:00\",\"dateModified\":\"2022-02-10T14:31:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/10\\\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\\\/\"},\"wordCount\":231,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/10\\\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/Presidente-Pompeo.jpg\",\"keywords\":[\"antonio pompeo\",\"Ciociaria\",\"consiglio direttivo\",\"Frosinone\",\"luciana lamorgese\",\"ministro\",\"segretari provinciali\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/10\\\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/10\\\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\\\/\",\"name\":\"Pompeo nominato nel Consiglio direttivo nazionale dell\u2019albo dei segretari - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/10\\\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/10\\\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/Presidente-Pompeo.jpg\",\"datePublished\":\"2022-02-10T14:31:30+00:00\",\"dateModified\":\"2022-02-10T14:31:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/10\\\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/10\\\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/10\\\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/Presidente-Pompeo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/Presidente-Pompeo.jpg\",\"width\":797,\"height\":512,\"caption\":\"Il presidente Antonio Pompeo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/10\\\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pompeo nominato nel Consiglio direttivo nazionale dell\u2019albo dei segretari\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/10\\\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/10\\\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/10\\\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pompeo nominato nel Consiglio direttivo nazionale dell\u2019albo dei segretari - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/","og_locale":"it_IT","og_type":"article","og_title":"Pompeo nominato nel Consiglio direttivo nazionale dell\u2019albo dei segretari","og_description":"Il presidente Pompeo nominato nel Consiglio direttivo dell'Albo nazionale dei segretari provinciali e comunali","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-02-10T14:31:30+00:00","article_modified_time":"2022-02-10T14:31:31+00:00","og_image":[{"width":797,"height":512,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/Presidente-Pompeo.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Pompeo nominato nel Consiglio direttivo nazionale dell\u2019albo dei segretari","datePublished":"2022-02-10T14:31:30+00:00","dateModified":"2022-02-10T14:31:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/"},"wordCount":231,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/Presidente-Pompeo.jpg","keywords":["antonio pompeo","Ciociaria","consiglio direttivo","Frosinone","luciana lamorgese","ministro","segretari provinciali"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/","name":"Pompeo nominato nel Consiglio direttivo nazionale dell\u2019albo dei segretari - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/Presidente-Pompeo.jpg","datePublished":"2022-02-10T14:31:30+00:00","dateModified":"2022-02-10T14:31:31+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/Presidente-Pompeo.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/Presidente-Pompeo.jpg","width":797,"height":512,"caption":"Il presidente Antonio Pompeo"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Pompeo nominato nel Consiglio direttivo nazionale dell\u2019albo dei segretari"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/10\/pompeo-nominato-nel-consiglio-direttivo-nazionale-dellalbo-dei-segretari\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/70386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=70386"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/70386\/revisions"}],"predecessor-version":[{"id":70391,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/70386\/revisions\/70391"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/70388"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=70386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=70386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=70386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}