{"id":70035,"date":"2022-02-03T15:00:17","date_gmt":"2022-02-03T14:00:17","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=70035"},"modified":"2022-02-03T18:27:56","modified_gmt":"2022-02-03T17:27:56","slug":"travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/","title":{"rendered":"Travolto il sella alla bici, l&#8217;ultimo saluto al professor Vitelli"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Si sono svolti alle 15 di oggi, gioved\u00ec 3 febbrario,  nella <strong>chiesa del Sacro Cuore a Frosinone<\/strong> (citt\u00e0 di cui era originario) i funerali del professor&nbsp;<strong>Roberto Vitelli. <\/strong>Tantissime le persone accorse nella chiesa e nel piazzale antistante, nella parte bassa del Capoluogo, per dare l\u2019ultimo saluto all\u2019insegnante, da tutti stimato ed amato. Tanti i ricordi ed i messaggi di cordoglio per la sua famiglia e la moglie, medico a Frosinone, insieme alla quale <strong>da qualche tempo si era trasferito nella vicina Torrice<\/strong>.  Era in sella sua bici quando, per cause ancora in via di accertamento, \u00e8 stato travolto da una Smart condotta da A.D., un 23enne di Vallecorsa ma residente a Roma.&nbsp;<strong>Il professore \u00e8 deceduto sul colpo<\/strong>&nbsp;dopo aver fatto un volo di almeno 30 metri in seguito al violento urto con la macchina condotta dal giovane.&nbsp; Il tragico espisodio si \u00e8 verificato in via Gaeta a Ceccano.  Il 23enne nell\u2019immediatezza dei fatti \u00e8 stato arrestato e condotto ai domiciliari dai carabinieri su disposizione del Pm. I suoi difensori avevano chiesto di rimetterlo in liberta, ma il Giudice per le indagini preliminari, dopo l\u2019interrogatorio cui \u00e8 stato sottoposto marted\u00ec,&nbsp;<strong>ha deciso di respingere le istanze della difesa e di confermare la misura cautelare dei domiciliari con l\u2019accusa di omicidio stradale.&nbsp;<\/strong> La posizione del 23enne si sarebbe infatti appesantita per l\u2019emergere di quello che viene definito \u201cprecedente specifico\u201d risalente a due anni fa e per il quale, sei mesi fa circa,&nbsp;<strong>aveva ottenuto l\u2019affidamento \u201cin prova\u201d ai servizi sociali<\/strong>. Inoltre, come confermato subito dopo l\u2019incidente mortale, il ragazzo sarebbe risultato<strong>&nbsp;positivo al test antidroga<\/strong>, quindi quando la sua auto ha impattato con la bici del professor Vitelli sarebbe stato sotto l\u2019effetto di sostanze stupefacenti (sembra cannabinoidi). Motivo per cui \u00e8 stato subito arrestato dai carabinieri e su disposizione del Pm condotto ai \u201cdomiciliari\u201d.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/roberto-vitelli-2-1024x576.jpg\" alt=\"\" class=\"wp-image-69998\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/roberto-vitelli-2-1024x576.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/roberto-vitelli-2-300x169.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/roberto-vitelli-2-768x432.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/roberto-vitelli-2.jpg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Si sono svolti alle 15 di oggi, gioved\u00ec 3 febbrario, nella chiesa del Sacro Cuore a Frosinone (citt\u00e0 di cui<\/p>\n","protected":false},"author":26,"featured_media":70036,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2],"tags":[93,1732,14428,14432],"class_list":["post-70035","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cronaca","tag-frosinone","tag-funerali","tag-roberto-vitelli","tag-travolto-in-bici"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Travolto il sella alla bici, l&#039;ultimo saluto al professor Vitelli - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Travolto il sella alla bici, l&#039;ultimo saluto al professor Vitelli\" \/>\n<meta property=\"og:description\" content=\"Si sono svolti alle 15 di oggi, gioved\u00ec 3 febbrario, nella chiesa del Sacro Cuore a Frosinone (citt\u00e0 di cui\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-03T14:00:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-03T17:27:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/funerali-vitelli.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Travolto il sella alla bici, l&#8217;ultimo saluto al professor Vitelli\",\"datePublished\":\"2022-02-03T14:00:17+00:00\",\"dateModified\":\"2022-02-03T17:27:56+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\\\/\"},\"wordCount\":325,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/funerali-vitelli.jpeg\",\"keywords\":[\"Frosinone\",\"funerali\",\"roberto vitelli\",\"travolto in bici\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\\\/\",\"name\":\"Travolto il sella alla bici, l'ultimo saluto al professor Vitelli - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/funerali-vitelli.jpeg\",\"datePublished\":\"2022-02-03T14:00:17+00:00\",\"dateModified\":\"2022-02-03T17:27:56+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/funerali-vitelli.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/funerali-vitelli.jpeg\",\"width\":800,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Travolto il sella alla bici, l&#8217;ultimo saluto al professor Vitelli\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Travolto il sella alla bici, l'ultimo saluto al professor Vitelli - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/","og_locale":"it_IT","og_type":"article","og_title":"Travolto il sella alla bici, l'ultimo saluto al professor Vitelli","og_description":"Si sono svolti alle 15 di oggi, gioved\u00ec 3 febbrario, nella chiesa del Sacro Cuore a Frosinone (citt\u00e0 di cui","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-02-03T14:00:17+00:00","article_modified_time":"2022-02-03T17:27:56+00:00","og_image":[{"width":800,"height":445,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/funerali-vitelli.jpeg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Travolto il sella alla bici, l&#8217;ultimo saluto al professor Vitelli","datePublished":"2022-02-03T14:00:17+00:00","dateModified":"2022-02-03T17:27:56+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/"},"wordCount":325,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/funerali-vitelli.jpeg","keywords":["Frosinone","funerali","roberto vitelli","travolto in bici"],"articleSection":["*PRIMO PIANO*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/","name":"Travolto il sella alla bici, l'ultimo saluto al professor Vitelli - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/funerali-vitelli.jpeg","datePublished":"2022-02-03T14:00:17+00:00","dateModified":"2022-02-03T17:27:56+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/funerali-vitelli.jpeg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/funerali-vitelli.jpeg","width":800,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Travolto il sella alla bici, l&#8217;ultimo saluto al professor Vitelli"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/travolto-il-sella-alla-bici-lultimo-saluto-al-professor-vitelli\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/70035","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=70035"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/70035\/revisions"}],"predecessor-version":[{"id":70038,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/70035\/revisions\/70038"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/70036"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=70035"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=70035"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=70035"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}