{"id":70023,"date":"2022-02-03T11:47:06","date_gmt":"2022-02-03T10:47:06","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=70023"},"modified":"2022-02-03T17:42:32","modified_gmt":"2022-02-03T16:42:32","slug":"arce-consolidata-sinergia-tra-comune-e-comunita-montana","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/","title":{"rendered":"Arce: consolidata sinergia tra Comune e Comunit\u00e0 Montana"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Comune e Comunit\u00e0 Montana, consolidata la storica sinergia tra i due enti. Si \u00e8 tenuto ieri pomeriggio, presso il palazzo municipale di Arce, <strong>l&#8217;incontro tra il sindaco di Arce Luigi Germani e il commissario della XV Comunit\u00e0 Montana Valle del Liri Rossella Chiusaroli<\/strong>. Il colloquio si \u00e8 svolto in un clima di estrema cordialit\u00e0 ed ha spaziato su numerosi temi che vedono impegnati in prima linea i due enti.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDesidero ringraziare di cuore la dottoressa Chiusaroli &#8211; ha detto il primo cittadino &#8211; per aver accettato il nostro invito a partecipare a questa visita istituzionale. I rapporti tra il Comune di Arce e la XV Comunit\u00e0 Montana sono stati sempre ottimi e improntati alla massima collaborazione per il bene del territorio. Ho avuto l&#8217;onore &#8211; ha aggiunto Germani &#8211; di presiedere per sette lunghi anni la giunta dell&#8217;ente montano e per due il consiglio comunitario e, grazie alla coesione con tanti altri amministratori della Valle del Liri, siamo riusciti ad attrarre numerosi finanziamenti per la realizzazione di opere pubbliche di grande rilievo\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il primo cittadino ha poi ricordato le collaborazioni attualmente in corso tra i due enti. <\/strong>A partire dal finanziamento di circa 30mila euro, parte di un vecchio progetto mai realizzato, che permetter\u00e0 al Comune di Arce di valorizzare delle strade montane in zona Fontanelle e localit\u00e0 Monte San Martino; la convenzione in atto per il personale qualificato distaccato da altri enti; il progetto del Servizio Civile Universale (le domande sono in scadenza il prossimo 10 febbraio) che prevede di assegnare ad Arce ben 32 volontari. Durante l&#8217;incontro c&#8217;\u00e8 stato spazio anche per ripercorrere le vicende amministrative che hanno riguardato la passata amministrazione comunale, il lungo periodo di commissariamento e poi l&#8217;esito elettorale dello scorso ottobre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u201cRingrazio il Sindaco Germani e tutta l&#8217;Amministrazione comunale per la calorosa accoglienza <\/strong>&#8211; ha concluso il commissario Chiusaroli &#8211; e rinnovo fin d&#8217;ora la massima collaborazione. La nostra missione \u00e8 quella di stare al fianco degli amministratori locali. Per questo stiamo lavorando a diversi progetti tra cui uno destinato ad incentivare i servizi per la raccolta dei rifiuti differenziati ed un altro finalizzato a facilitare l&#8217;accesso dei piccoli comuni ai finanziamenti del PNRR\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">All&#8217;incontro ha partecipato anche il vicesindaco Sisto Colantonio, gli assessori Alessandro Proia e Elisa Santopadre, il consigliere delegato Valeria Gemma. Insieme alla Chiusaroli anche Cinzia Delicata e Sara Simone.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Consolidata la sinergia tra il Comune di Arce e la Comunit\u00e0 Montana<\/p>\n","protected":false},"author":26,"featured_media":70024,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2236,28],"tags":[411,94,149,1181,93,3872,7884],"class_list":["post-70023","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-politica","tag-arce","tag-ciociaria","tag-comune","tag-comunita-montana","tag-frosinone","tag-luigi-germani","tag-rossella-chiusaroli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Arce: consolidata sinergia tra Comune e Comunit\u00e0 Montana - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Arce: consolidata sinergia tra Comune e Comunit\u00e0 Montana\" \/>\n<meta property=\"og:description\" content=\"Consolidata la sinergia tra il Comune di Arce e la Comunit\u00e0 Montana\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-03T10:47:06+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-02-03T16:42:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/comune-e-comunita.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"864\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Arce: consolidata sinergia tra Comune e Comunit\u00e0 Montana\",\"datePublished\":\"2022-02-03T10:47:06+00:00\",\"dateModified\":\"2022-02-03T16:42:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\\\/\"},\"wordCount\":401,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/comune-e-comunita.jpg\",\"keywords\":[\"Arce\",\"Ciociaria\",\"comune\",\"comunit\u00e0 montana\",\"Frosinone\",\"luigi germani\",\"rossella chiusaroli\"],\"articleSection\":[\"Attualit\u00e0\",\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\\\/\",\"name\":\"Arce: consolidata sinergia tra Comune e Comunit\u00e0 Montana - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/comune-e-comunita.jpg\",\"datePublished\":\"2022-02-03T10:47:06+00:00\",\"dateModified\":\"2022-02-03T16:42:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/comune-e-comunita.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/02\\\/comune-e-comunita.jpg\",\"width\":864,\"height\":486},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arce: consolidata sinergia tra Comune e Comunit\u00e0 Montana\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/02\\\/03\\\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Arce: consolidata sinergia tra Comune e Comunit\u00e0 Montana - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/","og_locale":"it_IT","og_type":"article","og_title":"Arce: consolidata sinergia tra Comune e Comunit\u00e0 Montana","og_description":"Consolidata la sinergia tra il Comune di Arce e la Comunit\u00e0 Montana","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-02-03T10:47:06+00:00","article_modified_time":"2022-02-03T16:42:32+00:00","og_image":[{"width":864,"height":486,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/comune-e-comunita.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Arce: consolidata sinergia tra Comune e Comunit\u00e0 Montana","datePublished":"2022-02-03T10:47:06+00:00","dateModified":"2022-02-03T16:42:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/"},"wordCount":401,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/comune-e-comunita.jpg","keywords":["Arce","Ciociaria","comune","comunit\u00e0 montana","Frosinone","luigi germani","rossella chiusaroli"],"articleSection":["Attualit\u00e0","Evidenza"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/","name":"Arce: consolidata sinergia tra Comune e Comunit\u00e0 Montana - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/comune-e-comunita.jpg","datePublished":"2022-02-03T10:47:06+00:00","dateModified":"2022-02-03T16:42:32+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/comune-e-comunita.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/02\/comune-e-comunita.jpg","width":864,"height":486},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Arce: consolidata sinergia tra Comune e Comunit\u00e0 Montana"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/02\/03\/arce-consolidata-sinergia-tra-comune-e-comunita-montana\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/70023","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=70023"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/70023\/revisions"}],"predecessor-version":[{"id":70025,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/70023\/revisions\/70025"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/70024"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=70023"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=70023"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=70023"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}