{"id":69816,"date":"2022-01-29T10:54:31","date_gmt":"2022-01-29T09:54:31","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=69816"},"modified":"2022-01-29T11:00:19","modified_gmt":"2022-01-29T10:00:19","slug":"comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/","title":{"rendered":"Comunali, Morelli: nessun veto e nessuna ostilit\u00e0. I socialisti  al lavoro  per un altro  progetto politico"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;Nessun veto e nessuna ostilit\u00e0 da parte dei Socialisti nei confronti di Mauro Vicano. La verit\u00e0 \u00e8 che noi Socialisti abbiamo iniziato il 9 ottobre scorso, con la creazione del tavolo per un Nuovo Centrosinistra coordinato da Ivano Alteri, un altro percorso politico, e questo perch\u00e9 non crediamo nel progetto di coalizione trasversale ideato dal leader del Pd, Francesco De Angelis, di cui \u00e8 appunto protagonista Vicano. <strong>Cos\u00ec Gerardina Morelli, segretario Sezione Psi di Frosinone. \u00a0\u00a0<\/strong>&#8220;Ci\u00f2 che \u00e8 definito elegantemente \u201ccampo largo\u201d, in realt\u00e0, \u00e8 un coacervo privo di coesione, come la cronaca di questi giorni conferma, e mancante di una chiara prospettiva per il futuro della nostra citt\u00e0, se non quella di tentare di vincere a tutti i costi, cercando di assemblare tutto e il contrario di tutto. Peraltro, ammesso e non concesso che si vinca, sarebbe impossibile governare. Noi Socialisti abbiamo un\u2019altra idea della politica e vogliamo metterla in pratica, anche perch\u00e9 in citt\u00e0, nonostante l\u2019emergenza ambientale, si comincia a respirare un\u2019aria nuova, come il recente successo della lista ispirata dai Giovani Socialisti alle elezioni del Consiglio Comunale dei Giovani sta a confermare. Noi Socialisti, quindi, abbiamo la ferma intenzione di proseguire nel lavoro iniziato da mesi per un Nuovo Centrosinistra e per avviare una prospettiva di effettivo cambiamento nei metodi e nel merito, marcando una chiara discontinuit\u00e0, con l\u2019obiettivo di offrire ai cittadini di Frosinone una proposta politica e programmatica alternativa e altamente innovativa. Una prima iniziativa al riguardo \u00e8 costituita dal convegno sul tema \u201cFrosinoneCementoZero. L\u2019alternativa del Riuso, della Riqualificazione e della Ricostruzione\u201d in programma per i primi di marzo. L\u2019unit\u00e0 \u00e8 certamente un valore, ma la chiarezza politica \u00e8 ancor pi\u00f9 importante. Ed in tutta sincerit\u00e0 per noi Socialisti la strada delle alleanze trasversali \u00e8 una strada sbagliata, anche perch\u00e9 \u00e8 di ostacolo ad un reale rinnovamento&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Nessun veto e nessuna ostilit\u00e0 da parte dei Socialisti nei confronti di Mauro Vicano. La verit\u00e0 \u00e8 che noi Socialisti<\/p>\n","protected":false},"author":26,"featured_media":20203,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[4497,7415],"class_list":["post-69816","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","tag-gerardina-morelli","tag-mauro-vicano"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Comunali, Morelli: nessun veto e nessuna ostilit\u00e0. I socialisti al lavoro per un altro progetto politico - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunali, Morelli: nessun veto e nessuna ostilit\u00e0. I socialisti al lavoro per un altro progetto politico\" \/>\n<meta property=\"og:description\" content=\"&#8220;Nessun veto e nessuna ostilit\u00e0 da parte dei Socialisti nei confronti di Mauro Vicano. La verit\u00e0 \u00e8 che noi Socialisti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-29T09:54:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-29T10:00:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/gerardina-morelli.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"681\" \/>\n\t<meta property=\"og:image:height\" content=\"501\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/29\\\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/29\\\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Comunali, Morelli: nessun veto e nessuna ostilit\u00e0. I socialisti al lavoro per un altro progetto politico\",\"datePublished\":\"2022-01-29T09:54:31+00:00\",\"dateModified\":\"2022-01-29T10:00:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/29\\\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\\\/\"},\"wordCount\":314,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/29\\\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/gerardina-morelli.jpg\",\"keywords\":[\"Gerardina Morelli\",\"Mauro Vicano\"],\"articleSection\":[\"*PRIMO PIANO*\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/29\\\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/29\\\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\\\/\",\"name\":\"Comunali, Morelli: nessun veto e nessuna ostilit\u00e0. I socialisti al lavoro per un altro progetto politico - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/29\\\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/29\\\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/gerardina-morelli.jpg\",\"datePublished\":\"2022-01-29T09:54:31+00:00\",\"dateModified\":\"2022-01-29T10:00:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/29\\\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/29\\\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/29\\\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/gerardina-morelli.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/10\\\/gerardina-morelli.jpg\",\"width\":681,\"height\":501,\"caption\":\"Gerardina Morelli\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/29\\\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunali, Morelli: nessun veto e nessuna ostilit\u00e0. I socialisti al lavoro per un altro progetto politico\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/29\\\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/29\\\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/29\\\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Comunali, Morelli: nessun veto e nessuna ostilit\u00e0. I socialisti al lavoro per un altro progetto politico - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/","og_locale":"it_IT","og_type":"article","og_title":"Comunali, Morelli: nessun veto e nessuna ostilit\u00e0. I socialisti al lavoro per un altro progetto politico","og_description":"&#8220;Nessun veto e nessuna ostilit\u00e0 da parte dei Socialisti nei confronti di Mauro Vicano. La verit\u00e0 \u00e8 che noi Socialisti","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-01-29T09:54:31+00:00","article_modified_time":"2022-01-29T10:00:19+00:00","og_image":[{"width":681,"height":501,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/gerardina-morelli.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Comunali, Morelli: nessun veto e nessuna ostilit\u00e0. I socialisti al lavoro per un altro progetto politico","datePublished":"2022-01-29T09:54:31+00:00","dateModified":"2022-01-29T10:00:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/"},"wordCount":314,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/gerardina-morelli.jpg","keywords":["Gerardina Morelli","Mauro Vicano"],"articleSection":["*PRIMO PIANO*"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/","name":"Comunali, Morelli: nessun veto e nessuna ostilit\u00e0. I socialisti al lavoro per un altro progetto politico - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/gerardina-morelli.jpg","datePublished":"2022-01-29T09:54:31+00:00","dateModified":"2022-01-29T10:00:19+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/gerardina-morelli.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/10\/gerardina-morelli.jpg","width":681,"height":501,"caption":"Gerardina Morelli"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Comunali, Morelli: nessun veto e nessuna ostilit\u00e0. I socialisti al lavoro per un altro progetto politico"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/29\/comunali-morelli-nessun-veto-e-nessuna-ostilita-i-socialisti-al-lavoro-per-un-altro-progetto-politico\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/69816","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=69816"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/69816\/revisions"}],"predecessor-version":[{"id":69818,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/69816\/revisions\/69818"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/20203"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=69816"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=69816"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=69816"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}