{"id":69443,"date":"2022-01-21T15:11:29","date_gmt":"2022-01-21T14:11:29","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=69443"},"modified":"2022-01-21T20:53:18","modified_gmt":"2022-01-21T19:53:18","slug":"ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/","title":{"rendered":"Ceccano, incontro tra Comune e Uepe per il rinnovo  della convenzione"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Si \u00e8 svolto l\u2019incontro propedeutico per rinnovare la convenzione, che avr\u00e0 durata di cinque anni, tra il Comune di Ceccano e l\u2019Uepe (Ufficio Esecuzione Penale Esterna) di Frosinone per lo svolgimento di lavori di pubblica utilit\u00e0 nel procedimento di messa alla prova.<br>Si tratta di una serie di prestazioni di lavoro per finalit\u00e0 di tipo sociale e socio-sanitarie nei confronti di persone con disabilit\u00e0, malati, anziani, minori, stranieri; di protezione civile anche mediante soccorso alla popolazione in caso di calamit\u00e0 naturali; di lavoro per fruibilit\u00e0 e la tutela del patrimonio ambientale, compresa la collaborazione ad opere di prevenzioni incendi, di salvaguardia del patrimonio boschivo e forestale; di lavoro per fruibilit\u00e0 e la tutela del patrimonio culturale e artistico, inclusa la custodia di biblioteche, musei ecc.; di lavoro nella manutenzione di strade, marciapiedi, verde pubblico e per il decoro di edifici pubblici, ivi compresi giardini, parchi e strutture ricreative\/culturali. Ma vi \u00e8 anche compresa l\u2019attivit\u00e0 amministrativa (anche informatica) per l\u2019archiviazione, il riordino e l\u2019elaborazione dati e quella di supporto al personale addetto a servizi relativo al centralino e ufficio URP, senza escludere prestazioni di lavoro inerenti a specifiche competenze o professionalit\u00e0 del soggetto messo alla prova.<br>Presenti, oltre al sindaco Roberto Caligiore, l\u2019assessore alla Pubblica Istruzione Mario Sodani e il consigliere Mauro Staccone, Patrizia Romano dell\u2019Uepe in rappresentanza di Mariantonia Vitulano responsabile dell\u2019Ufficio di Frosinone.<br>La collaborazione nasce sette anni fa da un progetto dell\u2019assessore Sodani e del consigliere Marco Mizzoni di Patto Civico e dell\u2019assessore Stefano Gizzi della Lega. Progetto accolto subito dal primo cittadino, sempre attento alle tematiche sociali.<br>&lt; I soggetti ammessi allo svolgimento dei lavori d\u00ec pubblica utilit\u00e0  &#8211; ha affermato  Caligiore- presteranno presso le strutture dell&#8217;Ente le seguenti attivit\u00e0 rientranti nei settori di impiego indicati dall&#8217;art. 2, comma 4, del D.M. n. 88\/2015: manutenzione della Villa comunale, del verde pubblico e del cimitero &#8211; spiega Sodani \u2013 Oltre all\u2019attivit\u00e0 di custodia presso Castel Sindici e il complesso sportivo di Passo del Cardinale&gt;.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 svolto l\u2019incontro propedeutico per rinnovare la convenzione, che avr\u00e0 durata di cinque anni, tra il Comune di Ceccano<\/p>\n","protected":false},"author":26,"featured_media":69449,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,1],"tags":[],"class_list":["post-69443","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ceccano, incontro tra Comune e Uepe per il rinnovo della convenzione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ceccano, incontro tra Comune e Uepe per il rinnovo della convenzione\" \/>\n<meta property=\"og:description\" content=\"Si \u00e8 svolto l\u2019incontro propedeutico per rinnovare la convenzione, che avr\u00e0 durata di cinque anni, tra il Comune di Ceccano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-21T14:11:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-21T19:53:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/IMG-20220121-WA0006.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/21\\\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/21\\\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Ceccano, incontro tra Comune e Uepe per il rinnovo della convenzione\",\"datePublished\":\"2022-01-21T14:11:29+00:00\",\"dateModified\":\"2022-01-21T19:53:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/21\\\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\\\/\"},\"wordCount\":347,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/21\\\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/IMG-20220121-WA0006.jpg\",\"articleSection\":[\"Evidenza\",\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/21\\\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/21\\\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\\\/\",\"name\":\"Ceccano, incontro tra Comune e Uepe per il rinnovo della convenzione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/21\\\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/21\\\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/IMG-20220121-WA0006.jpg\",\"datePublished\":\"2022-01-21T14:11:29+00:00\",\"dateModified\":\"2022-01-21T19:53:18+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/21\\\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/21\\\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/21\\\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/IMG-20220121-WA0006.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/IMG-20220121-WA0006.jpg\",\"width\":1536,\"height\":2048},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/21\\\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ceccano, incontro tra Comune e Uepe per il rinnovo della convenzione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/21\\\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/21\\\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/21\\\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ceccano, incontro tra Comune e Uepe per il rinnovo della convenzione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/","og_locale":"it_IT","og_type":"article","og_title":"Ceccano, incontro tra Comune e Uepe per il rinnovo della convenzione","og_description":"Si \u00e8 svolto l\u2019incontro propedeutico per rinnovare la convenzione, che avr\u00e0 durata di cinque anni, tra il Comune di Ceccano","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-01-21T14:11:29+00:00","article_modified_time":"2022-01-21T19:53:18+00:00","og_image":[{"width":1536,"height":2048,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/IMG-20220121-WA0006.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Ceccano, incontro tra Comune e Uepe per il rinnovo della convenzione","datePublished":"2022-01-21T14:11:29+00:00","dateModified":"2022-01-21T19:53:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/"},"wordCount":347,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/IMG-20220121-WA0006.jpg","articleSection":["Evidenza","News"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/","name":"Ceccano, incontro tra Comune e Uepe per il rinnovo della convenzione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/IMG-20220121-WA0006.jpg","datePublished":"2022-01-21T14:11:29+00:00","dateModified":"2022-01-21T19:53:18+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/IMG-20220121-WA0006.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/IMG-20220121-WA0006.jpg","width":1536,"height":2048},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ceccano, incontro tra Comune e Uepe per il rinnovo della convenzione"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/21\/ceccano-incontro-tra-comune-e-uepe-per-il-rinnovo-della-convenzione\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/69443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=69443"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/69443\/revisions"}],"predecessor-version":[{"id":69450,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/69443\/revisions\/69450"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/69449"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=69443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=69443"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=69443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}