{"id":68640,"date":"2022-01-03T18:05:40","date_gmt":"2022-01-03T17:05:40","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=68640"},"modified":"2022-01-04T14:26:58","modified_gmt":"2022-01-04T13:26:58","slug":"frosinone-gru-e-cantieri-in-tutto-il-capoluogo","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/","title":{"rendered":"Frosinone, gru e cantieri in tutto il capoluogo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Anche in un periodo di ristagno dell&#8217;edilizia, a seguito delle evidenti difficolt\u00e0 generate dall\u2019emergenza sanitaria, gli uffici comunali, su indicazione del sindaco, Nicola Ottaviani, hanno continuato a sbloccare una serie di investimenti privati che produrranno nuova occupazione<\/strong> e attrazione economica e sociale sul capoluogo negli anni a venire, unitamente ai nuovi cantieri pubblici in corso di approvazione e allestimento. Nell\u2019ambito degli interventi di rigenerazione e recupero dell\u2019edilizia, si stanno attuando demolizioni e ricostruzioni con ampliamento degli edifici in via Valle Fioretta, via Vetiche, via Artemisia Gentileschi, via Fabi, via Mascagni; demolizione e ricostruzione in viale Normandia; ampliamento in via Le rase e via Cavoni; nell\u2019ambito del piano di recupero, sono previste anche due distinte operazioni di demolizione e ricostruzione in via Landolfi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A questo elenco, vanno aggiunti gli ulteriori cantieri di operatori privati per trasformazioni urbanistiche ed edilizie per circa 30 milioni di euro in via Aldo Moro, via San Giuseppe, Sacro Cuore e zona CDR\/CDU, cui vanno ad aggiungersi altri 10\/15 milioni di euro a ridosso della zona De Matthaeis. Grazie&nbsp;all\u2019utilizzo&nbsp;del permesso di costruire convenzionato, infatti, il Comune e l&#8217;operatore privato possono stipulare una convenzione che contiene la regolamentazione degli obblighi di realizzazione di standard e servizi a carico del titolare del permesso. In particolare,&nbsp;l\u2019amministrazione&nbsp;Ottaviani si \u00e8 dotata di questo strumento previsto dal Testo Unico al fine di rendere possibile la ricucitura e la riqualificazione del contesto urbano e sociale delle aree oggetto di intervento, mediante&nbsp;un\u2019attenta&nbsp;pianificazione urbanistica che mette al centro una visione uniformante e unitaria del territorio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In piazza Ferrante (Sacro Cuore), sono previsti lavori per una volumetria di 9059,47 metri cubi (superficie in cessione pubblica di 700 metri cubi): tra le opere compensative a carico del privato, vi sono la sistemazione dell&#8217;area in cessione e la realizzazione dello spazio pubblico di collegamento tra piazza Domenico Ferrante e piazza Salvo D&#8217;Acquisto, con, inoltre, la realizzazione del percorso ciclo-pedonale di collegamento tra Viale Michelangelo e Piazza AnnaLena Tonelli.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"712\" height=\"449\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/via-tiburtina-cantiere.jpg\" alt=\"\" class=\"wp-image-68642\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/via-tiburtina-cantiere.jpg 712w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/via-tiburtina-cantiere-300x189.jpg 300w\" sizes=\"auto, (max-width: 712px) 100vw, 712px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">In via San Giuseppe, la convenzione con un privato, per una volumetria di 4467,95 metri cubi (superficie in cessione di 354 metri cubi) prevede, a compensazione, la costituzione di una servit\u00f9 di passaggio pubblica su area privata al fine di garantire il collegamento pedonale tra via S. Giuseppe e gli argini del fiume Cosa, con la relativa sistemazione della stessa a carico del richiedente, oltre alla sistemazione, a cura e spese del richiedente, dell\u2019area per standard pubblici con destinazione a parcheggi&nbsp; da cedere all\u2019Amministrazione comunale, comportando pertanto la realizzazione diretta di opere di urbanizzazione primaria.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sempre in via San Giuseppe, per una volumetria di 6680,88 metri cubi (in cessione, 507) la convenzione da stipulare prevede la realizzazione standard a parcheggio nell&#8217;ambito delle aree cedute e la previsione di collegamento tra Via San Giuseppe e Via Aldo Moro. Proprio in via Aldo Moro (volumetria di 3250,12 metri cubi; 285,46 in cessione), l\u2019accordo tramite 28 bis prevede uno spazio pubblico (nell&#8217;ambito delle aree cedute) con collegamento tra via Aldo Moro e Via San Giuseppe, che permette il raggiungimento del fiume Cosa, con realizzazione e sistemazione percorso ciclo-pedonale di collegamento tra parcheggio Questura e Via Grappelli. In zona via Cosenza, su un intervento di 3874,64 metri cubi (294 in cessione), la convenzione prevede la realizzazione di standard nell&#8217;ambito delle aree cedute, con collegamento tra Viale Mazzini e il Parco Matusa. In Via De Matthaeis (intervento da 34.847,90 metri cubi, con 3.583 in cessione), si proceder\u00e0 alla cessione di ulteriore area oltre al 22,50%, assicurando il collegamento tra Via De Matthaeis e la Villa Comunale, con la realizzazione dello standard in cessione con parcheggio pubblico. In via Tiburtina, su un intervento di 5053,09 metri cubi (390 in cessione) il privato realizzer\u00e0 gli standard a parcheggio nell&#8217;ambito delle aree cedute. In via Landolfi, sono previsti lavori su una volumetria di 23.500 metri cubi (5.700 in cessione), con la realizzazione di standard a parcheggio, anche su via Po, con relativi standard, unitamente alla sistemazione di parte di piazza Ferrante.<\/p>\n\n\n\n<div class=\"wp-block-image\"><figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"915\" height=\"569\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/cantiere.jpg\" alt=\"\" class=\"wp-image-68643\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/cantiere.jpg 915w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/cantiere-300x187.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/cantiere-768x478.jpg 768w\" sizes=\"auto, (max-width: 915px) 100vw, 915px\" \/><\/figure><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">In via Marittima, su una volumetria di 14.330 metri cubi (1.542 in cessione), le opere compensative includono la cessione gratuita al Comune di Frosinone di una ulteriore area di circa mq 100, sempre da destinare a parcheggio pubblico unitamente alla sistemazione parziale a sosta di una porzione dell\u2019area verde. A ci\u00f2 si aggiunga la realizzazione di un percorso ciclo-pedonale di collegamento tra via Marittima e via Mola Vecchia e di un tratto di pista ciclabile.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Infine, sempre su via Marittima, un ulteriore intervento privato prevede la cessione gratuita al Comune di Frosinone e sistemazione parziale a parcheggio pubblico di una un&#8217;altra area di circa mq 300, migliorando nell\u2019insieme le condizioni di fruibilit\u00e0 dello standard pubblico, con realizzazione di un tratto del percorso e della pista ciclo-pedonale lungo via Mola Vecchia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nell\u2019ambito dell\u2019edilizia residenziale pubblica (come, ad esempio, nel caso delle costruzioni realizzate nella zona di via Maria\/Ponte della Fontana), l\u2019amministrazione ha ottenuto dai privati una serie di opere, finalizzate alla riqualificazione e alla ricucitura del tessuto urbano (parcheggi, strade di collegamento e verde), a beneficio di tutto il contesto pubblico dell\u2019intera zona.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Nel complesso, il Comune di Frosinone ha incassato, negli ultimi mesi, per gli interventi in attuazione, un importo derivante dagli oneri concessori pari a 700.000 euro, reinvestiti in progetti di manutenzione ordinaria e straordinaria per scuole, strade ed edifici pubblici.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Anche in un periodo di ristagno dell&#8217;edilizia, a seguito delle evidenti difficolt\u00e0 generate dall\u2019emergenza sanitaria, gli uffici comunali, su indicazione<\/p>\n","protected":false},"author":26,"featured_media":68641,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2236,28],"tags":[6372,94,788,93,639],"class_list":["post-68640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-politica","tag-cantieri","tag-ciociaria","tag-edilizia","tag-frosinone","tag-nicola-ottaviani"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone, gru e cantieri in tutto il capoluogo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone, gru e cantieri in tutto il capoluogo\" \/>\n<meta property=\"og:description\" content=\"Anche in un periodo di ristagno dell&#8217;edilizia, a seguito delle evidenti difficolt\u00e0 generate dall\u2019emergenza sanitaria, gli uffici comunali, su indicazione\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2022-01-03T17:05:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-01-04T13:26:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/sacrocuore2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"896\" \/>\n\t<meta property=\"og:image:height\" content=\"671\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/03\\\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/03\\\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Frosinone, gru e cantieri in tutto il capoluogo\",\"datePublished\":\"2022-01-03T17:05:40+00:00\",\"dateModified\":\"2022-01-04T13:26:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/03\\\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\\\/\"},\"wordCount\":896,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/03\\\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/sacrocuore2.jpg\",\"keywords\":[\"cantieri\",\"Ciociaria\",\"edilizia\",\"Frosinone\",\"nicola ottaviani\"],\"articleSection\":[\"Attualit\u00e0\",\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2022\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/03\\\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/03\\\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\\\/\",\"name\":\"Frosinone, gru e cantieri in tutto il capoluogo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/03\\\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/03\\\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/sacrocuore2.jpg\",\"datePublished\":\"2022-01-03T17:05:40+00:00\",\"dateModified\":\"2022-01-04T13:26:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/03\\\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/03\\\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/03\\\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/sacrocuore2.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/01\\\/sacrocuore2.jpg\",\"width\":896,\"height\":671},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/03\\\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone, gru e cantieri in tutto il capoluogo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/03\\\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/03\\\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2022\\\/01\\\/03\\\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone, gru e cantieri in tutto il capoluogo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone, gru e cantieri in tutto il capoluogo","og_description":"Anche in un periodo di ristagno dell&#8217;edilizia, a seguito delle evidenti difficolt\u00e0 generate dall\u2019emergenza sanitaria, gli uffici comunali, su indicazione","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2022-01-03T17:05:40+00:00","article_modified_time":"2022-01-04T13:26:58+00:00","og_image":[{"width":896,"height":671,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/sacrocuore2.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Frosinone, gru e cantieri in tutto il capoluogo","datePublished":"2022-01-03T17:05:40+00:00","dateModified":"2022-01-04T13:26:58+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/"},"wordCount":896,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/sacrocuore2.jpg","keywords":["cantieri","Ciociaria","edilizia","Frosinone","nicola ottaviani"],"articleSection":["Attualit\u00e0","Evidenza"],"inLanguage":"it-IT","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/","name":"Frosinone, gru e cantieri in tutto il capoluogo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/sacrocuore2.jpg","datePublished":"2022-01-03T17:05:40+00:00","dateModified":"2022-01-04T13:26:58+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/sacrocuore2.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/01\/sacrocuore2.jpg","width":896,"height":671},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone, gru e cantieri in tutto il capoluogo"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2022\/01\/03\/frosinone-gru-e-cantieri-in-tutto-il-capoluogo\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/68640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=68640"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/68640\/revisions"}],"predecessor-version":[{"id":68644,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/68640\/revisions\/68644"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/68641"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=68640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=68640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=68640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}