{"id":67742,"date":"2021-12-15T16:28:12","date_gmt":"2021-12-15T15:28:12","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=67742"},"modified":"2021-12-15T16:30:30","modified_gmt":"2021-12-15T15:30:30","slug":"direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/","title":{"rendered":"Direttivo FdI di Frosinone, istituiti i dipartimenti tematici"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Nella serata di ieri, presso i locali della Federazione Provinciale di Fratelli di Italia di Frosinone , si \u00e8 riunito il direttivo cittadino del partito<\/strong>. Durante la riunione,sono stati istituti i dipartimenti tematici che avranno l&#8217;obiettivo di lavorare fin dai prossimi giorni alla composizione di un programma elettorale da condividere con l&#8217;intero centro destra, ed essere quindi pronti alle elezioni comunali della prossima primavera.<strong> I dipartimenti assegnati sono i seguenti: <\/strong>Urbanistica e lavori pubblici (Tonino De Luca) , Politiche giovanili ed Universit\u00e0 (Alessandro Cimaroli), Finanza e Personale (Stefano Sergio), Politiche Sociali (Pierfrancesco Cinelli, Paola Fratangeli), Informatizzazione e Trasporti (Luigi Carfora), Ambiente (Paolo Gabrielli) , Cultura (Silvia Shniderich, Daniela Chiappini ), Pari opportunit\u00e0 ( Simona Geralico) Sport e tempo libero (Franco Carfagna , Franco Napoli, David Boni, Ivan Iannarilli), Commercio (Daniele Colasanti e Fernando incitti), affari generali (Mauro Paniccia), Sicurezza (Sergio Arduini). Nelle prossime settimane sar\u00e0 incrementato il numero dei dipartimenti con i nuovi iscritti che sempre pi\u00f9 numerosi si stanno aggiungendo in queste ore attraverso un tesseramento che, anche durante la riunione, ha visto la raccolta di numerose tessere di adesione al partito. Tanti infatti, sono i cittadini che chiedono di partecipare attivamente a Fratelli di Italia offrendo ciascuno il proprio contributo. In occasione della prossima riunione, che si terr\u00e0 il prossimo marted\u00ec, verr\u00e0 nominato l&#8217;esecutivo che affiancher\u00e0 il presidente Fabio Tagliaferri nella gestione del partito da qui ai prossimi anni, con particolare riguardo ed attenzione alle prossime elezioni comunali. Fratelli di Italia continua incessantemente il percorso di crescita e sviluppo all&#8217;interno della citt\u00e0 capoluogo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nella serata di ieri, presso i locali della Federazione Provinciale di Fratelli di Italia di Frosinone , si \u00e8 riunito<\/p>\n","protected":false},"author":26,"featured_media":10061,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,1],"tags":[3689,2961,93,10162],"class_list":["post-67742","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-news","tag-fabio-tagliaferri","tag-fdi","tag-frosinone","tag-paolo-trancassini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Direttivo FdI di Frosinone, istituiti i dipartimenti tematici - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Direttivo FdI di Frosinone, istituiti i dipartimenti tematici\" \/>\n<meta property=\"og:description\" content=\"Nella serata di ieri, presso i locali della Federazione Provinciale di Fratelli di Italia di Frosinone , si \u00e8 riunito\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-15T15:28:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-12-15T15:30:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Fabio-Tagliaferri.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"670\" \/>\n\t<meta property=\"og:image:height\" content=\"400\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/12\\\/15\\\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/12\\\/15\\\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Direttivo FdI di Frosinone, istituiti i dipartimenti tematici\",\"datePublished\":\"2021-12-15T15:28:12+00:00\",\"dateModified\":\"2021-12-15T15:30:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/12\\\/15\\\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\\\/\"},\"wordCount\":261,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/12\\\/15\\\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/Fabio-Tagliaferri.jpg\",\"keywords\":[\"Fabio Tagliaferri\",\"fdI\",\"Frosinone\",\"Paolo Trancassini\"],\"articleSection\":[\"Evidenza\",\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/12\\\/15\\\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/12\\\/15\\\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\\\/\",\"name\":\"Direttivo FdI di Frosinone, istituiti i dipartimenti tematici - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/12\\\/15\\\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/12\\\/15\\\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/Fabio-Tagliaferri.jpg\",\"datePublished\":\"2021-12-15T15:28:12+00:00\",\"dateModified\":\"2021-12-15T15:30:30+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/12\\\/15\\\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/12\\\/15\\\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/12\\\/15\\\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/Fabio-Tagliaferri.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/04\\\/Fabio-Tagliaferri.jpg\",\"width\":670,\"height\":400},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/12\\\/15\\\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Direttivo FdI di Frosinone, istituiti i dipartimenti tematici\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/12\\\/15\\\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/12\\\/15\\\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/12\\\/15\\\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Direttivo FdI di Frosinone, istituiti i dipartimenti tematici - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/","og_locale":"it_IT","og_type":"article","og_title":"Direttivo FdI di Frosinone, istituiti i dipartimenti tematici","og_description":"Nella serata di ieri, presso i locali della Federazione Provinciale di Fratelli di Italia di Frosinone , si \u00e8 riunito","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-12-15T15:28:12+00:00","article_modified_time":"2021-12-15T15:30:30+00:00","og_image":[{"width":670,"height":400,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Fabio-Tagliaferri.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Direttivo FdI di Frosinone, istituiti i dipartimenti tematici","datePublished":"2021-12-15T15:28:12+00:00","dateModified":"2021-12-15T15:30:30+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/"},"wordCount":261,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Fabio-Tagliaferri.jpg","keywords":["Fabio Tagliaferri","fdI","Frosinone","Paolo Trancassini"],"articleSection":["Evidenza","News"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/","name":"Direttivo FdI di Frosinone, istituiti i dipartimenti tematici - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Fabio-Tagliaferri.jpg","datePublished":"2021-12-15T15:28:12+00:00","dateModified":"2021-12-15T15:30:30+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Fabio-Tagliaferri.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/04\/Fabio-Tagliaferri.jpg","width":670,"height":400},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Direttivo FdI di Frosinone, istituiti i dipartimenti tematici"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/12\/15\/direttivo-fdi-di-frosinone-istituiti-i-dipartimenti-tematici\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/67742","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=67742"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/67742\/revisions"}],"predecessor-version":[{"id":67744,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/67742\/revisions\/67744"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/10061"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=67742"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=67742"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=67742"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}