{"id":67027,"date":"2021-11-29T17:30:44","date_gmt":"2021-11-29T16:30:44","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=67027"},"modified":"2021-11-29T17:42:55","modified_gmt":"2021-11-29T16:42:55","slug":"dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/","title":{"rendered":"Dispositivi sanificazione dell&#8217;aria nelle scuole, Maura presenta una mozione"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;L\u2019Organizzazione Mondiale della Sanit\u00e0(OMS), gi\u00e0 a partire dall\u2019inizio dello scorso anno, ha dichiarato l\u2019emergenza di sanit\u00e0 pubblica di rilevanza internazionale. Lo stato di emergenza dichiarato sul territorio nazionale con Delibera del Consiglio dei Ministri del 31gennaio 2020, inizialmente previsto per sei mesi, \u00e8 stato prorogato pi\u00f9 volte e da ultimo fino al 31 dicembre 2021 (Delibera del Consiglio dei Ministri 21 aprile 2021). Cos\u00ec come accaduto in tutti i settori e pi\u00f9 ingenerale nell\u2019intero contesto socio-economico, la pandemia da Covid 19, ha significativamente modificato l\u2019operativit\u00e0 del sistema di istruzione tradizionalmente inteso&#8221;. <strong> Inizia cos\u00ec la mozione che Danile Maura (Fdi), ha presentato al presidente della Provincia Antonio Pompeo. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Si \u00e8 dovuto ricorrere al distanziamento, quale strumento necessario ed utile al fine del contenimento e della gestione del contagio, con conseguente sospensione delle principali attivit\u00e0 svolte in presenza, comprese le lezioni scolastiche. La didattica a distanza, attivata nell\u2019emergenza per non interrompere la continuit\u00e0 dei processi di apprendimento degli studenti, quale modalit\u00e0 compatibile con le esigenze del contenimento del virus, ha rappresentato uno strumento utile ma non sufficiente. Il ritorno alle modalit\u00e0 in presenza \u00e8 diventato quindi una necessit\u00e0 al fine della ripresa delle attivit\u00e0 scolastiche in modo stabile, auspicato da tutti: studenti, docenti e famiglie. Per il rientro in aula insicurezza degli studenti e di quanti operano in tale contesto, sono stati messi in campo diversi interventi (per aumentare la sicurezza dei trasporti, per l\u2019acquisto di nuovi arredi scolastici come banchi e sedute, per l\u2019affitto di nuovi spazi ed altro) che per\u00f2 non sono stati sufficienti a migliorare radicalmente la salubrit\u00e0 e la sicurezza degli spazi deputati all\u2019insegnamento scolastico&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Dopo la sospensione delle lezioni, in fase di rientro, sono state altres\u00ec intraprese, a diversi livelli e sono tuttora in corso, misure straordinarie di sanificazione e disinfezione degli istituti scolastici, per rendere il pi\u00f9 possibile sicuri gli ambienti e le aule nelle quali potrebbero crearsi occasioni di contagio. Tale sanificazione straordinaria, vista l\u2019emergenza epidemiologica in corso, \u00e8 indubbiamente una misura preventiva molto importante per ridurre il rischio di contagio, ma non \u00e8 di perse sufficiente per limitare la diffusione del COVID-19 ; c\u2019\u00e8 bisogno di abbattere in modo \u201cstabile\u201d nel tempo, la carica virale e batterica negli ambienti scolastici, per rendere, per quanto possibile, pi\u00f9 sicuro lo svolgimento dell\u2019attivit\u00e0 didattica in presenza&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>&#8221; L\u2019ambito, pertanto, su cui c\u2019\u00e8 urgenza di intervento, all\u2019interno delle strutture scolastiche, \u00e8 quello della qualit\u00e0 dell\u2019aria. La sanificazione ambientale \u00e8 divenuta il nuovo imprescindibile elemento di sicurezza (microbiologica e di salubrit\u00e0 degli ambienti), a salvaguardia della salute di quanti trascorrono gran parte della loro giornata in tali strutture.<\/strong> L&#8217;attuale emergenza sanitaria ha messo in evidenza come la qualit\u00e0 dell\u2019aria non debba pi\u00f9 essere considerata alla stregua di un parametro di \u201ccomfort\u201d, ma come importante indicatore di salubrit\u00e0, anche in considerazione dell\u2019elevato tempo trascorso negli ambienti scolastici. La scuola \u00e8 una comunit\u00e0 e, come gli altri luoghi ad alta frequentazione, racchiude in se una molteplicit\u00e0 di rischi, tra i quali quello biologico: la condivisione degli spazi, la prossimit\u00e0 fisica e l&#8217;elevato numero di persone che vi soggiornano, favoriscono la proliferazione di germi e virus che, circolando liberamente nell&#8217;aria, espongono i bambini, gli studenti, i docenti, i collaboratori scolastici e, pi\u00f9 in generale, tutti coloro che operano all\u2019interno di tali strutture, al rischio di infezioni e contagi&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Vivere in ambienti scolastici pi\u00f9 salubri, soprattutto in questo delicato periodo, \u00e8 pertanto una priorit\u00e0 ed un obiettivo costante da perseguire. Per far ci\u00f2 \u00e8 necessario garantire un\u2019aria igienizzata, attraverso l\u2019utilizzo di apparecchiature in grado di contrastare, per quanto possibile, il Covid-19 oltre ad altri virus, batteri e muffe. Gli istituti scolastici provinciali non hanno, in larga parte, anche a causa della oggettiva scarsit\u00e0 di risorse finanziarie, avuto la possibilit\u00e0 di accedere all\u2019utilizzo di attrezzature di recente produzione, in grado, attraverso diversi sistemi e diverse modalit\u00e0, di abbattere virus e sostanze potenzialmente inquinanti e nocive&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;<strong>Con la mia mozione si  impegna l\u2019amministrazione Provinciale di Frosinone ad ovviare alle carenze nella dotazione di tali dispositivi di sanificazione dell\u2019aria, riscontrate in ambito scolastico,<\/strong> con azioni di sostegno all\u2019acquisto di tali macchinari, indispensabili ai fini di prevenire il contagio da Covid 19 ed il rischio di un ritorno alla didattica a distanza, in modo da preservare la sicurezza dell\u2019attivit\u00e0 didattica in presenza da svolgersi in ambienti adeguatamente sanificati.  Quindi ad avviare, specifiche linee di indirizzo per acquistare direttamente e fornire tali dispositivi alle scuole secondarie della nostra Provincia o in alternativa a concedere contributi straordinari a favore degli Istituti scolastici Ciociari per l\u2019acquisto di dispositivi di sanificazione dell\u2019aria, al fine di favorire lo svolgimento in sicurezza delle attivit\u00e0 didattiche in presenza, a seguito dell\u2019emergenza sanitaria da pandemia Covid-19&#8243;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;L\u2019Organizzazione Mondiale della Sanit\u00e0(OMS), gi\u00e0 a partire dall\u2019inizio dello scorso anno, ha dichiarato l\u2019emergenza di sanit\u00e0 pubblica di rilevanza internazionale.<\/p>\n","protected":false},"author":26,"featured_media":28826,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28,38],"tags":[8916,3807,2961],"class_list":["post-67027","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","category-scuola","tag-covid","tag-daniele-maura","tag-fdi"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Dispositivi sanificazione dell&#039;aria nelle scuole, Maura presenta una mozione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dispositivi sanificazione dell&#039;aria nelle scuole, Maura presenta una mozione\" \/>\n<meta property=\"og:description\" content=\"&#8220;L\u2019Organizzazione Mondiale della Sanit\u00e0(OMS), gi\u00e0 a partire dall\u2019inizio dello scorso anno, ha dichiarato l\u2019emergenza di sanit\u00e0 pubblica di rilevanza internazionale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-29T16:30:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-29T16:42:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Daniele-Maura..-751x440-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"751\" \/>\n\t<meta property=\"og:image:height\" content=\"440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/29\\\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/29\\\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Dispositivi sanificazione dell&#8217;aria nelle scuole, Maura presenta una mozione\",\"datePublished\":\"2021-11-29T16:30:44+00:00\",\"dateModified\":\"2021-11-29T16:42:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/29\\\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\\\/\"},\"wordCount\":793,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/29\\\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/Daniele-Maura..-751x440-1.jpg\",\"keywords\":[\"covid\",\"Daniele Maura\",\"fdI\"],\"articleSection\":[\"Evidenza\",\"Scuola\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/29\\\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/29\\\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\\\/\",\"name\":\"Dispositivi sanificazione dell'aria nelle scuole, Maura presenta una mozione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/29\\\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/29\\\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/Daniele-Maura..-751x440-1.jpg\",\"datePublished\":\"2021-11-29T16:30:44+00:00\",\"dateModified\":\"2021-11-29T16:42:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/29\\\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/29\\\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/29\\\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/Daniele-Maura..-751x440-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/02\\\/Daniele-Maura..-751x440-1.jpg\",\"width\":751,\"height\":440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/29\\\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dispositivi sanificazione dell&#8217;aria nelle scuole, Maura presenta una mozione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/29\\\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/29\\\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/29\\\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dispositivi sanificazione dell'aria nelle scuole, Maura presenta una mozione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/","og_locale":"it_IT","og_type":"article","og_title":"Dispositivi sanificazione dell'aria nelle scuole, Maura presenta una mozione","og_description":"&#8220;L\u2019Organizzazione Mondiale della Sanit\u00e0(OMS), gi\u00e0 a partire dall\u2019inizio dello scorso anno, ha dichiarato l\u2019emergenza di sanit\u00e0 pubblica di rilevanza internazionale.","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-11-29T16:30:44+00:00","article_modified_time":"2021-11-29T16:42:55+00:00","og_image":[{"width":751,"height":440,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Daniele-Maura..-751x440-1.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Dispositivi sanificazione dell&#8217;aria nelle scuole, Maura presenta una mozione","datePublished":"2021-11-29T16:30:44+00:00","dateModified":"2021-11-29T16:42:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/"},"wordCount":793,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Daniele-Maura..-751x440-1.jpg","keywords":["covid","Daniele Maura","fdI"],"articleSection":["Evidenza","Scuola"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/","name":"Dispositivi sanificazione dell'aria nelle scuole, Maura presenta una mozione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Daniele-Maura..-751x440-1.jpg","datePublished":"2021-11-29T16:30:44+00:00","dateModified":"2021-11-29T16:42:55+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Daniele-Maura..-751x440-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/02\/Daniele-Maura..-751x440-1.jpg","width":751,"height":440},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Dispositivi sanificazione dell&#8217;aria nelle scuole, Maura presenta una mozione"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/29\/dispositivi-sanificazione-dellaria-nelle-scuole-maura-presenta-una-mozione\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/67027","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=67027"}],"version-history":[{"count":5,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/67027\/revisions"}],"predecessor-version":[{"id":67033,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/67027\/revisions\/67033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/28826"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=67027"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=67027"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=67027"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}