{"id":6691,"date":"2019-02-15T19:03:47","date_gmt":"2019-02-15T18:03:47","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=6691"},"modified":"2019-02-15T19:03:47","modified_gmt":"2019-02-15T18:03:47","slug":"mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/","title":{"rendered":"Mobilit\u00e0 in deroga, l\u2019Inps conferma: spettanze a met\u00e0 marzo"},"content":{"rendered":"<p>Buone notizie per gli <strong>ex lavoratori espulsi di cicli produttivi<\/strong> arrivano dall&#8217;incontro che questa mattina<strong> i sindacati<\/strong> hanno tenuto con i <strong>vertici dell&#8217;Inps<\/strong>.<\/p>\n<p><strong>Cgil, Cisl, Uil e Ugl<\/strong> rappresentati rispettivamente da<strong> Anselmo Briganti, Pasquale Legnante, Anita Tarquini ed Enzo Valente<\/strong> hanno avuto una riunione con il <strong>direttore dell&#8217;istituto di previdenza<\/strong> frusinate <strong>Siddi<\/strong> e alcuni funzionari tra cui il v<strong>ice direttore Mirra<\/strong>, il <strong>dirigente Caruso<\/strong> e il <strong>responsabile prestazioni Radice<\/strong>. Per la Uil presente anche <strong>Carlo Campagna<\/strong> in qualit\u00e0 sia di dipendente Inps che di responsabile provinciale della Uilpa. Una riunione promossa da <strong>Pietro Maceroni<\/strong>, attuale presidente del Comitato Provinciale Inps.<\/p>\n<h2>Tempi e risorse<\/h2>\n<p>L&#8217;ente ha dettato quelli che saranno i tempi per arrivare al <strong>pagamento dei 780 dipendenti<\/strong> interessati dal provvedimento di mobilit\u00e0 in deroga. <strong>L&#8217;intero iter dovrebbe concludersi entro il 6 marzo<\/strong> per poi dare il via, a partire dalla met\u00e0 dello stesso mese, ai pagamenti delle spettanze arretrate a copertura dell&#8217;intera seconda e terza finestra fino al 9 marzo.<\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_4686\" aria-describedby=\"caption-attachment-4686\" style=\"width: 632px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-4686 size-full\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/01\/pietro-maceroni-frosinone-e1547219989830.jpg\" alt=\"pietro maceroni presidente inps frosinone il corriere della ciociaria\" width=\"632\" height=\"356\" \/><figcaption id=\"caption-attachment-4686\" class=\"wp-caption-text\">Pietro Maceroni \u00e8 il nuovo presidente comitato provinciale Inps<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n<p>Siddi ha spiegato ai sindacati nel dettaglio<strong> il piano di azione che porter\u00e0 a lavorare 300 pratiche a settimana<\/strong> garantendo il massimo impegno della struttura nonostante la forte alla carenza di personale lamentata dall&#8217;ente di previdenza. Date quindi certe che sono state poi confermate all&#8217;uscita da parte delle organizzazioni sindacali ai lavoratori che erano all&#8217;esterno del piazzale antistante l&#8217;Inps in attesa di avere notizie. Successivamente si aprir\u00e0 anche la discussione, sempre entro marzo, legata alla quarta a finestra in virt\u00f9 di quelle che sono le risorse che il Ministero ha messo a disposizione.<\/p>\n<p>La <strong>Regione Lazio ha chiesto 35 milioni di cui 32 per il 2019<\/strong> e 3 per far fronte ai mesi di marzo, aprile e maggio relativi al 2018. Il direttore dell&#8217;Inps ha spiegato che verr\u00e0 informato anche il prefetto di Frosinone che sta seguendo da vicino questa situazione.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Buone notizie per gli ex lavoratori espulsi di cicli produttivi arrivano dall&#8217;incontro che questa mattina i sindacati hanno tenuto con<\/p>\n","protected":false},"author":18,"featured_media":6694,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,17],"tags":[1299,93,2139,2514,1529,2512,687,2513],"class_list":["post-6691","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-lavoro","tag-dipendenti","tag-frosinone","tag-inps","tag-istituto-di-previdenza","tag-lavoratori","tag-mobilita-in-deroga","tag-sindacati","tag-spettanze"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mobilit\u00e0 in deroga, l\u2019Inps conferma: spettanze a met\u00e0 marzo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"Stamattina i sindacati hanno avuto una riunione con i vertici Inps che ha comunicato che a met\u00e0 marzo saranno erogate le spettanze agli ex lavoratori\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mobilit\u00e0 in deroga, l\u2019Inps conferma: spettanze a met\u00e0 marzo\" \/>\n<meta property=\"og:description\" content=\"Stamattina i sindacati hanno avuto una riunione con i vertici Inps che ha comunicato che a met\u00e0 marzo saranno erogate le spettanze agli ex lavoratori\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"www.facebook.com\/tunews24\" \/>\n<meta property=\"article:published_time\" content=\"2019-02-15T18:03:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/inps-frosinone-e1550253544542.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"632\" \/>\n\t<meta property=\"og:image:height\" content=\"439\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redazione\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redazione\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/15\\\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/15\\\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\\\/\"},\"author\":{\"name\":\"Redazione\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\"},\"headline\":\"Mobilit\u00e0 in deroga, l\u2019Inps conferma: spettanze a met\u00e0 marzo\",\"datePublished\":\"2019-02-15T18:03:47+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/15\\\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\\\/\"},\"wordCount\":331,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/15\\\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/02\\\/inps-frosinone-e1550253544542.jpg\",\"keywords\":[\"dipendenti\",\"Frosinone\",\"inps\",\"istituto di previdenza\",\"lavoratori\",\"mobilit\u00e0 in deroga\",\"sindacati\",\"spettanze\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Lavoro\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2019\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/15\\\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/15\\\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\\\/\",\"name\":\"Mobilit\u00e0 in deroga, l\u2019Inps conferma: spettanze a met\u00e0 marzo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/15\\\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/15\\\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/02\\\/inps-frosinone-e1550253544542.jpg\",\"datePublished\":\"2019-02-15T18:03:47+00:00\",\"description\":\"Stamattina i sindacati hanno avuto una riunione con i vertici Inps che ha comunicato che a met\u00e0 marzo saranno erogate le spettanze agli ex lavoratori\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/15\\\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/15\\\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/15\\\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/02\\\/inps-frosinone-e1550253544542.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/02\\\/inps-frosinone-e1550253544542.jpg\",\"width\":632,\"height\":439,\"caption\":\"La sede Inps di Frosinone\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/15\\\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mobilit\u00e0 in deroga, l\u2019Inps conferma: spettanze a met\u00e0 marzo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/15\\\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/15\\\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/6d7f0a9120d0c03d0c552e9fdf49ed7d\",\"name\":\"Redazione\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g\",\"caption\":\"Redazione\"},\"description\":\"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE\",\"sameAs\":[\"http:\\\/\\\/www.tunews24.it\",\"www.facebook.com\\\/tunews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/senzafirma\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2019\\\/02\\\/15\\\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mobilit\u00e0 in deroga, l\u2019Inps conferma: spettanze a met\u00e0 marzo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"Stamattina i sindacati hanno avuto una riunione con i vertici Inps che ha comunicato che a met\u00e0 marzo saranno erogate le spettanze agli ex lavoratori","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/","og_locale":"it_IT","og_type":"article","og_title":"Mobilit\u00e0 in deroga, l\u2019Inps conferma: spettanze a met\u00e0 marzo","og_description":"Stamattina i sindacati hanno avuto una riunione con i vertici Inps che ha comunicato che a met\u00e0 marzo saranno erogate le spettanze agli ex lavoratori","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"www.facebook.com\/tunews24","article_published_time":"2019-02-15T18:03:47+00:00","og_image":[{"width":632,"height":439,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/inps-frosinone-e1550253544542.jpg","type":"image\/jpeg"}],"author":"Redazione","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Redazione","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/"},"author":{"name":"Redazione","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d"},"headline":"Mobilit\u00e0 in deroga, l\u2019Inps conferma: spettanze a met\u00e0 marzo","datePublished":"2019-02-15T18:03:47+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/"},"wordCount":331,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/inps-frosinone-e1550253544542.jpg","keywords":["dipendenti","Frosinone","inps","istituto di previdenza","lavoratori","mobilit\u00e0 in deroga","sindacati","spettanze"],"articleSection":["*PRIMO PIANO*","Lavoro"],"inLanguage":"it-IT","copyrightYear":"2019","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/","name":"Mobilit\u00e0 in deroga, l\u2019Inps conferma: spettanze a met\u00e0 marzo - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/inps-frosinone-e1550253544542.jpg","datePublished":"2019-02-15T18:03:47+00:00","description":"Stamattina i sindacati hanno avuto una riunione con i vertici Inps che ha comunicato che a met\u00e0 marzo saranno erogate le spettanze agli ex lavoratori","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/inps-frosinone-e1550253544542.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/02\/inps-frosinone-e1550253544542.jpg","width":632,"height":439,"caption":"La sede Inps di Frosinone"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Mobilit\u00e0 in deroga, l\u2019Inps conferma: spettanze a met\u00e0 marzo"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/6d7f0a9120d0c03d0c552e9fdf49ed7d","name":"Redazione","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a40eeacccdcad861f831dde73317f63a542e738f0dc4b79b9f47062d3d4bd1d2?s=96&d=mm&r=g","caption":"Redazione"},"description":"SEGUICI ANCHE SUI SOCIAL Facebook: TuNews24 e TuSport24 Instagram: TuNews24 e TuSport24 Youtube: TuNews24 Telegram: TuNews24 Puoi leggerci anche in formato cartaceo: il settimanale viene pubblicato e distribuito gratuitamente ogni venerd\u00ec in edicole, bar, centri commerciali e svariati esercizi. Ma \u00e8 possibile anche sfogliarlo comodamente online, cliccando su TU NEWS sfogliabile TU NEWS, PASSIONE PER L\u2019INFORMAZIONE","sameAs":["http:\/\/www.tunews24.it","www.facebook.com\/tunews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/senzafirma\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2019\/02\/15\/mobilita-in-deroga-linps-conferma-spettanze-a-meta-marzo\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/6691","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/18"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=6691"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/6691\/revisions"}],"predecessor-version":[{"id":6695,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/6691\/revisions\/6695"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/6694"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=6691"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=6691"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=6691"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}