{"id":66862,"date":"2021-11-27T14:26:53","date_gmt":"2021-11-27T13:26:53","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=66862"},"modified":"2021-11-28T11:22:38","modified_gmt":"2021-11-28T10:22:38","slug":"sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/","title":{"rendered":"Sanit\u00e0, Battisti:  11 milioni per potenziare l&#8217;offerta sanitaria del Cassinate"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br>\u201cCon la Direttrice Generale della ASL Frosinone, Pierpaola D\u2019Alessandro, abbiamo presentato ai sindaci la sanit\u00e0 che verr\u00e0 grazie al PNRR, per quanto concerne il Distretto D della nostra provincia. Quasi undici milioni e mezzo di interventi, per ramificare sul territorio pi\u00f9 servizi a misura di cittadino\u201d.<br>Cos\u00ec in una nota Sara Battisti, presidente commissione Affari Istituzionali.<br>\u201cA Cassino &#8211; spiega &#8211; si svilupper\u00e0 una Casa di Comunit\u00e0, un Ospedale di Comunit\u00e0 e un Centro Operativo Territoriale. A Pontecorvo una Casa di Comunit\u00e0 e un Ospedale di Comunit\u00e0.Ad Aquino una Casa di Comunit\u00e0. A San Giorgio a Liri una Casa di Comunit\u00e0.Nel Distretto D, inoltre, gi\u00e0 sono partiti i primi investimenti: potenziati gli ambulatori cardiologici con elettrocardiografi connessi alla piattaforma di telemedicina presso la CdS di Pontecorvo; Radiologia Pontecorvo rinnovata con nuova sezione RX e ecografo multidisciplinare; nuovo servizio holter pressori; nuova dotazione defibrillatori;-nuovo riunito odontoiatrico di CdS Pontecorvo; nuovo ecocardiotomografo a Cassino ex inaim; potenziato ambulatorio oculistico a Cassino ex inaim. Cambiamo la sanit\u00e0 &#8211; conclude -come avevamo promesso, a misura di cittadino e ramificata in tutto il territorio. Il mio grazie al Presidente Zingaretti, all\u2019assessore D\u2019Amato e alla direttrice D\u2019Alessandro per il lavoro di potenziamento della sanit\u00e0 dell\u2019intera provincia di Frosinone\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cCon la Direttrice Generale della ASL Frosinone, Pierpaola D\u2019Alessandro, abbiamo presentato ai sindaci la sanit\u00e0 che verr\u00e0 grazie al PNRR,<\/p>\n","protected":false},"author":26,"featured_media":50584,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[11],"tags":[958,216,94,107,1721],"class_list":["post-66862","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-salute","tag-asl-frosinone","tag-cassino","tag-ciociaria","tag-sanita","tag-sara-battisti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Sanit\u00e0, Battisti: 11 milioni per potenziare l&#039;offerta sanitaria del Cassinate - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sanit\u00e0, Battisti: 11 milioni per potenziare l&#039;offerta sanitaria del Cassinate\" \/>\n<meta property=\"og:description\" content=\"\u201cCon la Direttrice Generale della ASL Frosinone, Pierpaola D\u2019Alessandro, abbiamo presentato ai sindaci la sanit\u00e0 che verr\u00e0 grazie al PNRR,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-27T13:26:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-28T10:22:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/sara-battisti-nuova.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"738\" \/>\n\t<meta property=\"og:image:height\" content=\"501\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/27\\\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/27\\\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Sanit\u00e0, Battisti: 11 milioni per potenziare l&#8217;offerta sanitaria del Cassinate\",\"datePublished\":\"2021-11-27T13:26:53+00:00\",\"dateModified\":\"2021-11-28T10:22:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/27\\\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\\\/\"},\"wordCount\":220,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/27\\\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/sara-battisti-nuova.jpg\",\"keywords\":[\"Asl Frosinone\",\"Cassino\",\"Ciociaria\",\"Sanit\u00e0\",\"Sara Battisti\"],\"articleSection\":[\"Salute e Benessere\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/27\\\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/27\\\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\\\/\",\"name\":\"Sanit\u00e0, Battisti: 11 milioni per potenziare l'offerta sanitaria del Cassinate - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/27\\\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/27\\\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/sara-battisti-nuova.jpg\",\"datePublished\":\"2021-11-27T13:26:53+00:00\",\"dateModified\":\"2021-11-28T10:22:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/27\\\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/27\\\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/27\\\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/sara-battisti-nuova.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/12\\\/sara-battisti-nuova.jpg\",\"width\":738,\"height\":501},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/27\\\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sanit\u00e0, Battisti: 11 milioni per potenziare l&#8217;offerta sanitaria del Cassinate\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/27\\\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/27\\\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/27\\\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sanit\u00e0, Battisti: 11 milioni per potenziare l'offerta sanitaria del Cassinate - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/","og_locale":"it_IT","og_type":"article","og_title":"Sanit\u00e0, Battisti: 11 milioni per potenziare l'offerta sanitaria del Cassinate","og_description":"\u201cCon la Direttrice Generale della ASL Frosinone, Pierpaola D\u2019Alessandro, abbiamo presentato ai sindaci la sanit\u00e0 che verr\u00e0 grazie al PNRR,","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-11-27T13:26:53+00:00","article_modified_time":"2021-11-28T10:22:38+00:00","og_image":[{"width":738,"height":501,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/sara-battisti-nuova.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Sanit\u00e0, Battisti: 11 milioni per potenziare l&#8217;offerta sanitaria del Cassinate","datePublished":"2021-11-27T13:26:53+00:00","dateModified":"2021-11-28T10:22:38+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/"},"wordCount":220,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/sara-battisti-nuova.jpg","keywords":["Asl Frosinone","Cassino","Ciociaria","Sanit\u00e0","Sara Battisti"],"articleSection":["Salute e Benessere"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/","name":"Sanit\u00e0, Battisti: 11 milioni per potenziare l'offerta sanitaria del Cassinate - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/sara-battisti-nuova.jpg","datePublished":"2021-11-27T13:26:53+00:00","dateModified":"2021-11-28T10:22:38+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/sara-battisti-nuova.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/12\/sara-battisti-nuova.jpg","width":738,"height":501},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Sanit\u00e0, Battisti: 11 milioni per potenziare l&#8217;offerta sanitaria del Cassinate"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/27\/sanita-battisti-11-milioni-per-potenziare-lofferta-sanitaria-del-cassinate\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/66862","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=66862"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/66862\/revisions"}],"predecessor-version":[{"id":66863,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/66862\/revisions\/66863"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/50584"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=66862"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=66862"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=66862"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}