{"id":66126,"date":"2021-11-15T08:00:29","date_gmt":"2021-11-15T07:00:29","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=66126"},"modified":"2021-11-15T08:09:40","modified_gmt":"2021-11-15T07:09:40","slug":"il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/","title":{"rendered":"Il ministro degli Esteri Di Maio al congresso di ConfimpreseItalia: per le aziende risorse e trasformazione digitale"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Si \u00e8 concluso con un ringraziamento del Presidente Confimprese Italia Guido D\u2019Amico il 25 Congresso di Confimprese Italia. \u201cSono state tre giornate molto utili e ringraziamo tutti gli ospiti intervenuti per le preziose indicazioni e le delucidazioni che hanno dato ai nostri imprenditori su diversi temi. Ci aspettano grandi sfide, ma noi siamo qui, forti e pieni di entusiasmo. Portare le nostre proposte ai rappresentanti del Governo \u00e8 stato importantissimo, soprattutto dopo tempi molto difficili\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/11\/FB_IMG_1636909701072-1024x768.jpg\" alt=\"\" data-id=\"66132\" data-full-url=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/11\/FB_IMG_1636909701072.jpg\" data-link=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/14\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/fb_img_1636909701072\/\" class=\"wp-image-66132\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/11\/FB_IMG_1636909701072-1024x768.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/11\/FB_IMG_1636909701072-300x225.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/11\/FB_IMG_1636909701072-768x576.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/11\/FB_IMG_1636909701072.jpg 1080w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A chiudere l\u2019evento di tre giorni il Ministro degli Esteri Luigi Di Maio intervistato sull\u2019export e non solo da Nunzia De Girolamo e dalla Vicedirettrice del Corriere della Sera Fiorenza Sarzanini. \u201cOra stiamo gestendo i bandi del Pnrr, ma c\u2019\u00e8 un problema: la digitalizzazione delle imprese. Per le prima volta non riusciamo a esaurire tutte le risorse perch\u00e9 quello \u00e8 il tallone d&#8217;Achille del nostro sistema produttivo\u201d, ha dichiarato il ministro degli Esteri invogliando gli imprenditori a compiere la trasformazione digitale che possa renderli competitivi anche all\u2019estero. &#8220;Ora il commercio estero \u00e8 in mano alla Farnesina. Il corpo diplomatico italiano non vedeva l&#8217;ora di mettersi a lavorare sulle materie economiche sistematiche perch\u00e9 hanno delle competenze in materia. Un&#8217;azienda quando va all&#8217;estero deve considerare l&#8217;ambasciata la casa delle imprese italiane e dovete chiedere all&#8217;ambasciata di assistervi\u201d. Sono stati finanziati 5 miliardi a fronte di 200 milioni degli anni passati. \u201cOra le imprese sanno che sino al 2026 ci sono ogni anni 1 miliardo e mezzo da Simest e 500 milioni a fondo perduto\u201d. E poi ancora Di Maio ha parlato del green pass, &#8220;unico strumento per tenere aperto attivit\u00e0 commerciali\u201d, di cambiamento climatico, dei due \u201cmattei\u201d, di Qurinale, Berlusconi e tanto altro. Poco prima l\u2019intervento dell\u2019imprenditore Lapo Elkann in collegamento zoom. \u201cParlo a nome di Lopo non in nome della mia famiglia o di altri, ma personalmente voglio dire che sono un fan e supporter di Mario Draghi che ha dato all\u2019Italia credibilit\u00e0 e affidabilit\u00e0 a livello internazionale. Ha gestito una fase drammatica del Paese ed \u00e8 un ottimo primo ministro, e d\u00e0 sicurezza in un contesto in cui i partiti pensano per lo pi\u00f9 a loro stessi. Questo mi permetto di dire da italiano\u201d. Il senatore del Pd Andrea Romano ha aperto una finestra sulla politica. &#8220;Con il M5S? C\u2019\u00e8 un rapporto politico fondato sulla condivisione di molti punti dai forza. Dall\u2019altro lato i partiti si alleano e perch\u00e9 noi non dovremmo? Se questa alleanza durer\u00e0 dipende dal M5S, ma l\u2019ingresso europeo nel PPE \u00e8 un passo importante\u201d.<br>Anche il Presidente Simest Pasquale Salzano al centro del palco Confimprese. \u201cAbbiamo aperto il portale con il nuovo bando una settimana fa, ma stavolta ci sono condizionalit\u00e0 per avere competitivit\u00e0 a livello internazionale e le aziende hanno paura. Io dico, non abbiate paura di trasformarvi perch\u00e9 ora ci sono i fondi per il digitale, il green, l\u2019e-commerce. Sono le chiavi per rendere competitive le aziende. Sono il futuro\u201d.<\/p>\n\n\n\n<figure class=\"wp-block-embed-wordpress wp-block-embed is-type-wp-embed is-provider-laprovinciaquotidiano-it-news-h-24-e-notizie-di-approfondimento\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"fitvids-video\"><blockquote class=\"wp-embedded-content\" data-secret=\"ZTFgJLmtuW\"><a href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/14\/confimpreseitalia-guido-damico-rieletto-presidente\/\">ConfimpreseItalia, Guido D&#8217;Amico rieletto  presidente<\/a><\/blockquote><iframe loading=\"lazy\" class=\"wp-embedded-content\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"&#8220;ConfimpreseItalia, Guido D&#8217;Amico rieletto  presidente&#8221; &#8212; LaProvinciaQuotidiano.it - News h24 e notizie di approfondimento\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/14\/confimpreseitalia-guido-damico-rieletto-presidente\/embed\/#?secret=ZTFgJLmtuW\" data-secret=\"ZTFgJLmtuW\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\"><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Si \u00e8 concluso con un ringraziamento del Presidente Confimprese Italia Guido D\u2019Amico il 25 Congresso di Confimprese Italia. \u201cSono state<\/p>\n","protected":false},"author":26,"featured_media":66130,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,1],"tags":[1014,507,217,1228],"class_list":["post-66126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-news","tag-confimpreseitalia","tag-congresso","tag-fiuggi","tag-luigi-di-maio"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Il ministro degli Esteri Di Maio al congresso di ConfimpreseItalia: per le aziende risorse e trasformazione digitale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Il ministro degli Esteri Di Maio al congresso di ConfimpreseItalia: per le aziende risorse e trasformazione digitale\" \/>\n<meta property=\"og:description\" content=\"Si \u00e8 concluso con un ringraziamento del Presidente Confimprese Italia Guido D\u2019Amico il 25 Congresso di Confimprese Italia. \u201cSono state\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-15T07:00:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-11-15T07:09:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/11\/Polish_20211114_180347461.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1037\" \/>\n\t<meta property=\"og:image:height\" content=\"678\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/15\\\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/15\\\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Il ministro degli Esteri Di Maio al congresso di ConfimpreseItalia: per le aziende risorse e trasformazione digitale\",\"datePublished\":\"2021-11-15T07:00:29+00:00\",\"dateModified\":\"2021-11-15T07:09:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/15\\\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\\\/\"},\"wordCount\":510,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/15\\\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/11\\\/Polish_20211114_180347461.jpg\",\"keywords\":[\"Confimpreseitalia\",\"congresso\",\"Fiuggi\",\"luigi di maio\"],\"articleSection\":[\"*PRIMO PIANO*\",\"News\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/15\\\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/15\\\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\\\/\",\"name\":\"Il ministro degli Esteri Di Maio al congresso di ConfimpreseItalia: per le aziende risorse e trasformazione digitale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/15\\\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/15\\\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/11\\\/Polish_20211114_180347461.jpg\",\"datePublished\":\"2021-11-15T07:00:29+00:00\",\"dateModified\":\"2021-11-15T07:09:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/15\\\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/15\\\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/15\\\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/11\\\/Polish_20211114_180347461.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/11\\\/Polish_20211114_180347461.jpg\",\"width\":1037,\"height\":678},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/15\\\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Il ministro degli Esteri Di Maio al congresso di ConfimpreseItalia: per le aziende risorse e trasformazione digitale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/15\\\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/15\\\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/11\\\/15\\\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Il ministro degli Esteri Di Maio al congresso di ConfimpreseItalia: per le aziende risorse e trasformazione digitale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/","og_locale":"it_IT","og_type":"article","og_title":"Il ministro degli Esteri Di Maio al congresso di ConfimpreseItalia: per le aziende risorse e trasformazione digitale","og_description":"Si \u00e8 concluso con un ringraziamento del Presidente Confimprese Italia Guido D\u2019Amico il 25 Congresso di Confimprese Italia. \u201cSono state","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-11-15T07:00:29+00:00","article_modified_time":"2021-11-15T07:09:40+00:00","og_image":[{"width":1037,"height":678,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/11\/Polish_20211114_180347461.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Il ministro degli Esteri Di Maio al congresso di ConfimpreseItalia: per le aziende risorse e trasformazione digitale","datePublished":"2021-11-15T07:00:29+00:00","dateModified":"2021-11-15T07:09:40+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/"},"wordCount":510,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/11\/Polish_20211114_180347461.jpg","keywords":["Confimpreseitalia","congresso","Fiuggi","luigi di maio"],"articleSection":["*PRIMO PIANO*","News"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/","name":"Il ministro degli Esteri Di Maio al congresso di ConfimpreseItalia: per le aziende risorse e trasformazione digitale - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/11\/Polish_20211114_180347461.jpg","datePublished":"2021-11-15T07:00:29+00:00","dateModified":"2021-11-15T07:09:40+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/11\/Polish_20211114_180347461.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/11\/Polish_20211114_180347461.jpg","width":1037,"height":678},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Il ministro degli Esteri Di Maio al congresso di ConfimpreseItalia: per le aziende risorse e trasformazione digitale"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/11\/15\/il-ministro-degli-esteri-di-maio-al-congresso-di-confimpreseitalia-per-le-aziende-risorse-e-trasformazione-digitale\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/66126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=66126"}],"version-history":[{"count":4,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/66126\/revisions"}],"predecessor-version":[{"id":66136,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/66126\/revisions\/66136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/66130"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=66126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=66126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=66126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}