{"id":65328,"date":"2021-10-29T15:30:00","date_gmt":"2021-10-29T13:30:00","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=65328"},"modified":"2021-10-29T15:30:02","modified_gmt":"2021-10-29T13:30:02","slug":"isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/","title":{"rendered":"Isola del Liri: apre il parcheggio di piazza Santissima Triade. A giorni attive anche le strisce blu"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Apre il parcheggio interrato di <strong>piazza Santissima Triade ad Isola del Liri<\/strong>. Una struttura di cui da anni si attendeva la messa in funzione. L\u2019apertura dell\u2019ampio parcheggio interrato, che<strong> potr\u00e0 ospitare fino a 60 autoveicoli<\/strong>, \u00e8 collegato all\u2019attivazione degli stalli di sosta a strisce blu nel centro della cittadina, attivazione prevista nei prossimi giorni.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Un importante risultato per l&#8217;amministrazione comunale guidata dal sindaco Massimiliano Quadrini che con l&#8217;attivazione delle aree blu e del parcheggio interrato conta di dare un nuovo e migliore volto alla viabilit\u00e0 cittadina e razionalizzare al meglio gli spazi di sosta a vantaggio degli utenti che desiderano recarsi in centro per svolgere commissioni o acquisti e per le numerose attivit\u00e0 commerciali e uffici presenti, che avranno cos\u00ec certezza della maggiore disponibilit\u00e0 di aree di stazionamento per i propri clienti e per gli avventori.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">I parcheggi a pagamento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">In totale, <strong>compresi i 60 spazi del parcheggio<\/strong> SS. Triade, <strong>saranno 274 gli stalli a strisce blu disponibili nel centro citt\u00e0<\/strong>, mentre altrettante saranno le aree libere (strisce bianche) garantite. Al riguardo il Comune si \u00e8 gi\u00e0 attivato per affidare i lavori di delimitazione e ritinteggiatura degli stalli&nbsp; bianchi e relativa segnaletica verticale.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&#8217;amministrazione comunale ha concluso nelle scorse settimane la gara per l\u2019affidamento della gestione delle aree blu e il servizio si appresta a partire nei prossimi giorni, non appena sar\u00e0 completato il collocamento delle necessarie apparecchiature tecnologiche e della necessaria segnaletica lungo le zone interessate <strong>(Via San Giuseppe, Via Napoli, Corso Roma, Via Pietro De l&#8217;Isola, Piazza Gregorio VIII, Via Verdi, Via Po, Via Selva, Via Roma, Via Tevere, Via Pirandello)<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"714\" height=\"822\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/strisce-blu-isola-2.jpg\" alt=\"strisce blu isola del liri\" class=\"wp-image-65330\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/strisce-blu-isola-2.jpg 714w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/strisce-blu-isola-2-261x300.jpg 261w\" sizes=\"auto, (max-width: 714px) 100vw, 714px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Le strisce blu saranno attive dalle ore 9 alle ore 13 e dalle ore 16 alle ore 20 nel periodo invernale, mentre l\u2019estate fino alle ore 24. <\/strong>Al di fuori di questi orari ed in occasione delle giornate di mercato, la sosta \u00e8 sempre libera. Il costo per la sosta \u00e8 di un euro ad ora (frazionabile) e inoltre sono previsti sconti per soste prolungate (intera mattinata\/intero pomeriggio euro 2,50; intera giornata euro 4). sar\u00e0 inoltre possibile sottoscrivere abbonamenti. Il pagamento potr\u00e0 avvenire tramite i parcometri collocati nei pressi delle aree di sosta. Sono esentati dal pagamento le auto d\u2019istituto di enti e amministrazioni e concessionari di servizi, oltre che le auto provviste di contrassegno disabili.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tornando, invece, all\u2019entrata in funzione del parcheggio interrato, la ditta appaltatrice dovr\u00e0 realizzare le piccole manutenzioni necessarie, e collocare i sistemi automatizzati di accesso\/uscita delle autovetture dall\u2019area di sosta interrata (sbarra elevatrice, pannelli informativi, cassa pagamento, ecc.) per rendere funzionale la struttura, oltre che garantirne la pulizia e la sicurezza.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Dal Comune: interventi migliorativi per soste e viabilit\u00e0<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Rendere operativo il parcheggio di SS. Triade \u2013 fanno sapere dal palazzo comunale \u2013 \u00e8 stato uno degli impegni che quest&#8217;amministrazione ha assunto fin da subito. Siamo felici di aver trovato una soluzione che centra l\u2019obiettivo e che presto vedr\u00e0 funzionale quell\u2019area centrale della citt\u00e0. Siamo anche convinti che l\u2019attivazione delle aree di sosta a strisce blu, una volta superate le comprensibili resistenze che potranno esserci per il cambiamento, evidenzier\u00e0 tutti gli aspetti positivi a vantaggio della razionalizzazione dei parcheggi, del miglioramento della viabilit\u00e0, dei maggiori spazi a disposizione per utenti e cittadini&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"632\" height=\"308\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/05\/municipio-isola-liri-e1559233969543.jpg\" alt=\"isola del liri giunta il corriere della provincia\" class=\"wp-image-12279\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Inoltre, l&#8217;amministrazione comunale \u00e8 costantemente impegnata per trovare soluzione anche alle criticit\u00e0 che finora stanno impedendo la funzionalit\u00e0 anche degli altri parcheggi esistenti di viale Garibaldi ed ex cartiera Boimond&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A breve aprir\u00e0 il parcheggio di piazza Santissima Triade e saranno attivate le strisce blu a Isola del Liri<\/p>\n","protected":false},"author":26,"featured_media":65329,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[94,93,865,260,1775,2358,4234,2300],"class_list":["post-65328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-ciociaria","tag-frosinone","tag-gestione","tag-isola-del-liri","tag-massimiliano-quadrini","tag-parcheggio","tag-piazza-santissima-triade","tag-strisce-blu"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Isola del Liri: apre il parcheggio di piazza Santissima Triade. A giorni attive anche le strisce blu - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Isola del Liri: apre il parcheggio di piazza Santissima Triade. A giorni attive anche le strisce blu\" \/>\n<meta property=\"og:description\" content=\"A breve aprir\u00e0 il parcheggio di piazza Santissima Triade e saranno attivate le strisce blu a Isola del Liri\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-29T13:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-29T13:30:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/strisce-blu-isola.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"791\" \/>\n\t<meta property=\"og:image:height\" content=\"486\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/29\\\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/29\\\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Isola del Liri: apre il parcheggio di piazza Santissima Triade. A giorni attive anche le strisce blu\",\"datePublished\":\"2021-10-29T13:30:00+00:00\",\"dateModified\":\"2021-10-29T13:30:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/29\\\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\\\/\"},\"wordCount\":579,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/29\\\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/strisce-blu-isola.jpg\",\"keywords\":[\"Ciociaria\",\"Frosinone\",\"gestione\",\"isola del liri\",\"massimiliano quadrini\",\"parcheggio\",\"piazza santissima triade\",\"strisce blu\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/29\\\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/29\\\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\\\/\",\"name\":\"Isola del Liri: apre il parcheggio di piazza Santissima Triade. A giorni attive anche le strisce blu - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/29\\\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/29\\\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/strisce-blu-isola.jpg\",\"datePublished\":\"2021-10-29T13:30:00+00:00\",\"dateModified\":\"2021-10-29T13:30:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/29\\\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/29\\\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/29\\\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/strisce-blu-isola.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/strisce-blu-isola.jpg\",\"width\":791,\"height\":486,\"caption\":\"I parcheggi blu a Isola del Liri\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/29\\\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Isola del Liri: apre il parcheggio di piazza Santissima Triade. A giorni attive anche le strisce blu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/29\\\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/29\\\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/29\\\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Isola del Liri: apre il parcheggio di piazza Santissima Triade. A giorni attive anche le strisce blu - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/","og_locale":"it_IT","og_type":"article","og_title":"Isola del Liri: apre il parcheggio di piazza Santissima Triade. A giorni attive anche le strisce blu","og_description":"A breve aprir\u00e0 il parcheggio di piazza Santissima Triade e saranno attivate le strisce blu a Isola del Liri","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-10-29T13:30:00+00:00","article_modified_time":"2021-10-29T13:30:02+00:00","og_image":[{"width":791,"height":486,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/strisce-blu-isola.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Isola del Liri: apre il parcheggio di piazza Santissima Triade. A giorni attive anche le strisce blu","datePublished":"2021-10-29T13:30:00+00:00","dateModified":"2021-10-29T13:30:02+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/"},"wordCount":579,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/strisce-blu-isola.jpg","keywords":["Ciociaria","Frosinone","gestione","isola del liri","massimiliano quadrini","parcheggio","piazza santissima triade","strisce blu"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/","name":"Isola del Liri: apre il parcheggio di piazza Santissima Triade. A giorni attive anche le strisce blu - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/strisce-blu-isola.jpg","datePublished":"2021-10-29T13:30:00+00:00","dateModified":"2021-10-29T13:30:02+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/strisce-blu-isola.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/strisce-blu-isola.jpg","width":791,"height":486,"caption":"I parcheggi blu a Isola del Liri"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Isola del Liri: apre il parcheggio di piazza Santissima Triade. A giorni attive anche le strisce blu"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/29\/isola-del-liri-apre-il-parcheggio-di-piazza-santissima-triade-a-giorni-attive-anche-le-strisce-blu\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/65328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=65328"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/65328\/revisions"}],"predecessor-version":[{"id":65349,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/65328\/revisions\/65349"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/65329"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=65328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=65328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=65328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}