{"id":64455,"date":"2021-10-11T07:00:36","date_gmt":"2021-10-11T05:00:36","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=64455"},"modified":"2021-10-11T07:22:59","modified_gmt":"2021-10-11T05:22:59","slug":"ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/","title":{"rendered":"Ivani Agron, presidente del Consiglio distrettuale di Lezhe in Albania, in visita alle aziende delle province di Frosinone e Latina"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>La caparbit\u00e0 e il senso di appartenenza alla sua nazione gli hanno consentito, non senza sacrifici, di diventare il Presidente del Consiglio Distrettuale di Lezhe in Albania<\/strong>. <strong>La storia di Ivani Agron<\/strong>, giovane emigrante arrivato in Italia a bordo di un gommone nel 1997, <strong>\u00e8 l&#8217;esempio di come, con l&#8217;aiuto della nostra nazione, tante persone hanno intrapreso percorsi di vita eccellenti. <\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Ivani, una volta sbarcato, \u00e8 stato accolto in Umbria, a Gubbio dove ha lavorato e studiato sodo. Per raggiungere un obiettivo: quello di tornare in Albania per aiutare i suoi connazionali a crescere socialmente e ad evolversi. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;impegno<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Oggi, questa sua esperienza italiana, \u00e8 divenuta un progetto concreto e fattivo che vede la nazione balcanica lavorare a stretto contatto con il mondo dell&#8217;imprenditoria italiano<\/strong>. Un progetto denominato gli &#8216;Amici dell&#8217;Aquila&#8217;, come tributo alla bandiera della repubblica albanese, che nei giorni scorsi ha visto ospitare nelle province di Frosinone e Latina, una delegazione capeggiata dal presidente Agron accompagnato da Sterkaj Fran, imprenditore albanese e Basha Kastriot, direttore del Comune di Lezhe. Una tre giorni di confronto e full immersion nel mondo dell&#8217;imprenditoria nostrano organizzata dai fondatori dell&#8217;associazione italiana: Giancarlo Felicioni, imprenditore e presidente &#8216;Amici dell&#8217;Aquila&#8217;, l&#8217;avvocato Antonio Valente, dagli imprenditori Luciano Gatti e Plinio Conte e da Stefano Carducci, esperto di sviluppo locale. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"767\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211010-WA0003-1024x767.jpg\" alt=\"\" class=\"wp-image-64458\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211010-WA0003-1024x767.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211010-WA0003-300x225.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211010-WA0003-768x576.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211010-WA0003-1536x1151.jpg 1536w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211010-WA0003.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il momento pi\u00f9 importante delle viaggio in Italia c&#8217;\u00e8 stato nel pomeriggio di venerd\u00ec 8 ottobre, presso la sede del Gruppo Adam di Cassino. Qui, a fare gli onori di casa, l&#8217;imprenditore Alfredo Di Nallo, presidente ed al vertice del gruppo che \u00e8 leader nel settore dell&#8217;E-Commerce.<\/strong> Una tavola rotonda, che si \u00e8 svolta nel rispetto delle norme anticovid, grazie alla quale il presidente del Consiglio Ivani Agron ha potuto ascoltare le proposte dei tanti imprenditori ed industriali presenti. A rappresentare la politica locale c&#8217;era il sindaco di Isola del Liri e consigliere provinciale Massimiliano Quadrini. L&#8217;esponente politico albanese, nel suo intervento, ha focalizzato l&#8217;attenzione sulla necessit\u00e0 di garantire al suo paese uno sviluppo economico, industriale e sociale di eccellente livello. Perch\u00e8 l&#8217;Albania intende entrare a far parte, una volta ottenuti i requisiti richiesti, dell&#8217;Unione Europea. Un passaggio che pretende una metamorfosi anche strutturale. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Per poter costruire strade, ponti, autostrade, pontili e porti (Lezhe \u00e8 una ridente citt\u00e0 di mare molto simile al basso Lazio per aspetto e clima, divisa tra mare e collina). Per poter iniziare a smaltire rifiuti come prevede la normativa europea, per poter essere al passo dei tempi con il mondo del web e quindi anche con le connessioni, c&#8217;\u00e8 bisogno di voi italiani. Io ho studiato qui, voi mi avete accolto e consentito di lavorare e creare un futuro, io intendo creare un asse Italia-Albania che possa portare a noi benefici in termini di vivibilit\u00e0 ed a voi un supporto economico in un momento di cos\u00ec grande difficolt\u00e0&#8221;. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Parole sincere, schiette che hanno coinvolto gli l&#8217;eccellente parterre dei presenti: da Rosettano Navarra, a capo dell&#8217;omonimo gruppo leader nel settore dello smaltimento e riciclo dei rifiuti in Italia, a Raffaele Di Gabriele a capo di un&#8217;industria nautica, a Domenico e Gianluca Gabrielli, rispettivamente presidente del gruppo Sysco Spa e del gruppo Aerostrutture Spa con sede a Castelliri, a William De Cesare, imprenditore specializzato nella coltivazione di capana per uso farmaceutico, a Romeo Ausoni del gruppo Digital Up ad Angelo Musumeci del gruppo Adam. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"982\" height=\"1024\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/20211010_222645-982x1024.jpg\" alt=\"\" class=\"wp-image-64479\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/20211010_222645-982x1024.jpg 982w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/20211010_222645-288x300.jpg 288w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/20211010_222645-768x801.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/20211010_222645.jpg 1200w\" sizes=\"auto, (max-width: 982px) 100vw, 982px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">La delegazione ha poi fatto visita ai cantieri Rizzardi di Sabaudia, nome di lustro nel mondo della nautica a livello mondiale. Il tour laziale ha toccato anche cantine, aziende agricole, vinicole, frantoi, fattorie ma anche resort proprio perch\u00e8 l&#8217;intenzione del presidente del Consiglio di Lezhe \u00e8 quella di puntare anche sul rilancio della citt\u00e0 attraverso il turismo. <\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;obiettivo<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Nelle prossime settimane una delegazione di imprenditori italiani, accompagnati dai vertici dell&#8217;associazione &#8216;Amici dell&#8217;Aquila&#8217; si recher\u00e0 in Albania, a Lezhe per formalizzare un protocollo di intensa<\/strong>. Il rilancio dell&#8217;economia frusinate e pontina potrebbe ripartire anche grazie alla volont\u00e0 di un giovane di belle speranze che in Italia ha costruito il suo avvenire e quello del suo popolo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La caparbit\u00e0 e il senso di appartenenza alla sua nazione gli hanno consentito, non senza sacrifici, di diventare il Presidente<\/p>\n","protected":false},"author":26,"featured_media":64456,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,5],"tags":[13906,13907,11467,13904,13905,13908,1775],"class_list":["post-64455","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-economia","tag-albania","tag-alfredo-di-nallo","tag-gruppo-adam","tag-ivani-agron","tag-lezhe","tag-luciano-gatti","tag-massimiliano-quadrini"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Ivani Agron, presidente del Consiglio distrettuale di Lezhe in Albania, in visita alle aziende delle province di Frosinone e Latina - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ivani Agron, presidente del Consiglio distrettuale di Lezhe in Albania, in visita alle aziende delle province di Frosinone e Latina\" \/>\n<meta property=\"og:description\" content=\"La caparbit\u00e0 e il senso di appartenenza alla sua nazione gli hanno consentito, non senza sacrifici, di diventare il Presidente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-11T05:00:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-11T05:22:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211010-WA0007.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"1200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/11\\\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/11\\\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Ivani Agron, presidente del Consiglio distrettuale di Lezhe in Albania, in visita alle aziende delle province di Frosinone e Latina\",\"datePublished\":\"2021-10-11T05:00:36+00:00\",\"dateModified\":\"2021-10-11T05:22:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/11\\\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\\\/\"},\"wordCount\":702,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/11\\\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/IMG-20211010-WA0007.jpg\",\"keywords\":[\"albania\",\"alfredo di nallo\",\"gruppo adam\",\"ivani agron\",\"lezhe\",\"luciano gatti\",\"massimiliano quadrini\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Economia e Finanza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/11\\\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/11\\\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\\\/\",\"name\":\"Ivani Agron, presidente del Consiglio distrettuale di Lezhe in Albania, in visita alle aziende delle province di Frosinone e Latina - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/11\\\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/11\\\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/IMG-20211010-WA0007.jpg\",\"datePublished\":\"2021-10-11T05:00:36+00:00\",\"dateModified\":\"2021-10-11T05:22:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/11\\\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/11\\\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/11\\\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/IMG-20211010-WA0007.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/10\\\/IMG-20211010-WA0007.jpg\",\"width\":1600,\"height\":1200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/11\\\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ivani Agron, presidente del Consiglio distrettuale di Lezhe in Albania, in visita alle aziende delle province di Frosinone e Latina\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/11\\\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/11\\\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/11\\\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ivani Agron, presidente del Consiglio distrettuale di Lezhe in Albania, in visita alle aziende delle province di Frosinone e Latina - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/","og_locale":"it_IT","og_type":"article","og_title":"Ivani Agron, presidente del Consiglio distrettuale di Lezhe in Albania, in visita alle aziende delle province di Frosinone e Latina","og_description":"La caparbit\u00e0 e il senso di appartenenza alla sua nazione gli hanno consentito, non senza sacrifici, di diventare il Presidente","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-10-11T05:00:36+00:00","article_modified_time":"2021-10-11T05:22:59+00:00","og_image":[{"width":1600,"height":1200,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211010-WA0007.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Ivani Agron, presidente del Consiglio distrettuale di Lezhe in Albania, in visita alle aziende delle province di Frosinone e Latina","datePublished":"2021-10-11T05:00:36+00:00","dateModified":"2021-10-11T05:22:59+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/"},"wordCount":702,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211010-WA0007.jpg","keywords":["albania","alfredo di nallo","gruppo adam","ivani agron","lezhe","luciano gatti","massimiliano quadrini"],"articleSection":["*PRIMO PIANO*","Economia e Finanza"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/","name":"Ivani Agron, presidente del Consiglio distrettuale di Lezhe in Albania, in visita alle aziende delle province di Frosinone e Latina - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211010-WA0007.jpg","datePublished":"2021-10-11T05:00:36+00:00","dateModified":"2021-10-11T05:22:59+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211010-WA0007.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/10\/IMG-20211010-WA0007.jpg","width":1600,"height":1200},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Ivani Agron, presidente del Consiglio distrettuale di Lezhe in Albania, in visita alle aziende delle province di Frosinone e Latina"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/11\/ivani-agron-presidente-del-consiglio-distrettuale-di-lezhe-in-albania-in-visita-alle-aziende-delle-province-di-frosinone-e-latina\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/64455","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=64455"}],"version-history":[{"count":11,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/64455\/revisions"}],"predecessor-version":[{"id":64480,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/64455\/revisions\/64480"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/64456"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=64455"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=64455"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=64455"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}