{"id":64057,"date":"2021-10-03T15:39:10","date_gmt":"2021-10-03T13:39:10","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=64057"},"modified":"2021-10-03T15:39:12","modified_gmt":"2021-10-03T13:39:12","slug":"battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/","title":{"rendered":"Battisti: a Cassino  la prima giornata di eventi per dire grazie a medici, infermieri e operatori"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br>\u201c<strong>Sabato 9 ottobre nell\u2019ambito dell\u2019evento \u2018Per dirvi grazie\u2019 in collaborazione con la Asl di Frosinone<\/strong>, il Comune di Cassino, FEDAIISF, AVIS, Croce Rossa Italiana, Fondazione Exodus Cassino, Medica , Admo e l&#8217;unit\u00e0 di Pronto Soccorso dell\u2019Ospedale Santa Scolastica, EARLab APS, Su Di Tono, <strong>abbiamo realizzato una giornata dedicata interamente alla prevenzione, all\u2019arte e alla musica\u201d.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><strong>Cos\u00ec la presidente della Commissione regionale Affari Istituzionali, Sara Battisti, in merito all\u2019iniziativa \u201cPer dirvi grazie\u201d, <\/strong>che prevede due appuntamenti, il primo dei quali sabato 9 ottobre a Cassino, dedicati agli operatori sanitari della ASL di Frosinone che stanno combattendo da un anno e mezzo in prima linea contro il Covid<div>.<\/div><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><div><div><div> \u201cDalle ore 9.00 alle ore 18.00 &#8211; spiega &#8211; in Piazza Alcide De Gasperi verr\u00e0 allestito un villaggio della salute con 25 postazioni di consulenza specialistica. Alle ore 17.00, in concomitanza con \u201cOttobre rosa\u201d, ci sar\u00e0 un\u2019iniziativa a sostegno della \u201cRace for The Cure\u201d. Alle ore 18.00 presso l\u2019Ospedale Santa Scolastica di Cassino, verr\u00e0 installata un\u2019opera d\u2019arte dell\u2019artista Giuseppe Nino Rezza e sar\u00e0 inaugurato il murales realizzato da Marcello Russo di \u201cAmmuri Liberi\u201d, seguir\u00e0 la donazione da parte del Dott. Luciano Sarracino di un basso rilievo in ceramica. La giornata si concluder\u00e0 con il Concerto dei Modena City Ramblers presso il Parco Baden Powell alle ore 21.00\u201d.<\/div><\/div><\/div><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La consigliera Battisti ricorda che \u201cil concerto sar\u00e0 gratuito con un contributo volontario per la donazione di defibrillatori alla citt\u00e0 di Cassino. Sar\u00e0 possibile prenotare i biglietti inviando un messaggio alla pagina ASL&nbsp;<a href=\"https:\/\/m.facebook.com\/aslfrosinone\/\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/m.facebook.com\/aslfrosinone\/<\/a>o al numero 333 5342016, indicando COGNOME, NOME, NUMERO DI TELEFONO, NUMERO DI BIGLIETTI DA PRENOTAREoppure compilando il seguente form online&nbsp;<a href=\"https:\/\/forms.gle\/yM2bySeoAREoppWd8\" target=\"_blank\" rel=\"noreferrer noopener\">https:\/\/forms.gle\/yM2bySeoAREoppWd8<\/a>.Priorit\u00e0 sar\u00e0 data agli operatori sanitari della ASL Frosinone\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cSabato 9 ottobre nell\u2019ambito dell\u2019evento \u2018Per dirvi grazie\u2019 in collaborazione con la Asl di Frosinone, il Comune di Cassino, FEDAIISF,<\/p>\n","protected":false},"author":26,"featured_media":34689,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,11],"tags":[216,94,8916,107,1721],"class_list":["post-64057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-salute","tag-cassino","tag-ciociaria","tag-covid","tag-sanita","tag-sara-battisti"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Battisti: a Cassino la prima giornata di eventi per dire grazie a medici, infermieri e operatori - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Battisti: a Cassino la prima giornata di eventi per dire grazie a medici, infermieri e operatori\" \/>\n<meta property=\"og:description\" content=\"\u201cSabato 9 ottobre nell\u2019ambito dell\u2019evento \u2018Per dirvi grazie\u2019 in collaborazione con la Asl di Frosinone, il Comune di Cassino, FEDAIISF,\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-03T13:39:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-03T13:39:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/sara-battisti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"627\" \/>\n\t<meta property=\"og:image:height\" content=\"452\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/03\\\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/03\\\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Battisti: a Cassino la prima giornata di eventi per dire grazie a medici, infermieri e operatori\",\"datePublished\":\"2021-10-03T13:39:10+00:00\",\"dateModified\":\"2021-10-03T13:39:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/03\\\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\\\/\"},\"wordCount\":306,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/03\\\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/sara-battisti.jpg\",\"keywords\":[\"Cassino\",\"Ciociaria\",\"covid\",\"Sanit\u00e0\",\"Sara Battisti\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Salute e Benessere\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/03\\\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/03\\\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\\\/\",\"name\":\"Battisti: a Cassino la prima giornata di eventi per dire grazie a medici, infermieri e operatori - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/03\\\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/03\\\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/sara-battisti.jpg\",\"datePublished\":\"2021-10-03T13:39:10+00:00\",\"dateModified\":\"2021-10-03T13:39:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/03\\\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/03\\\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/03\\\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/sara-battisti.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2020\\\/05\\\/sara-battisti.jpg\",\"width\":627,\"height\":452,\"caption\":\"La consigliera regionale del Pd Sara Battisti\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/03\\\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Battisti: a Cassino la prima giornata di eventi per dire grazie a medici, infermieri e operatori\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/03\\\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/03\\\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/03\\\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Battisti: a Cassino la prima giornata di eventi per dire grazie a medici, infermieri e operatori - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/","og_locale":"it_IT","og_type":"article","og_title":"Battisti: a Cassino la prima giornata di eventi per dire grazie a medici, infermieri e operatori","og_description":"\u201cSabato 9 ottobre nell\u2019ambito dell\u2019evento \u2018Per dirvi grazie\u2019 in collaborazione con la Asl di Frosinone, il Comune di Cassino, FEDAIISF,","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-10-03T13:39:10+00:00","article_modified_time":"2021-10-03T13:39:12+00:00","og_image":[{"width":627,"height":452,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/sara-battisti.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Battisti: a Cassino la prima giornata di eventi per dire grazie a medici, infermieri e operatori","datePublished":"2021-10-03T13:39:10+00:00","dateModified":"2021-10-03T13:39:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/"},"wordCount":306,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/sara-battisti.jpg","keywords":["Cassino","Ciociaria","covid","Sanit\u00e0","Sara Battisti"],"articleSection":["*PRIMO PIANO*","Salute e Benessere"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/","name":"Battisti: a Cassino la prima giornata di eventi per dire grazie a medici, infermieri e operatori - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/sara-battisti.jpg","datePublished":"2021-10-03T13:39:10+00:00","dateModified":"2021-10-03T13:39:12+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/sara-battisti.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2020\/05\/sara-battisti.jpg","width":627,"height":452,"caption":"La consigliera regionale del Pd Sara Battisti"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Battisti: a Cassino la prima giornata di eventi per dire grazie a medici, infermieri e operatori"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/03\/battisti-a-cassino-la-prima-giornata-di-eventi-per-dire-grazie-a-medici-infermieri-e-operatori\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/64057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=64057"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/64057\/revisions"}],"predecessor-version":[{"id":64058,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/64057\/revisions\/64058"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/34689"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=64057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=64057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=64057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}