{"id":63946,"date":"2021-10-01T14:29:19","date_gmt":"2021-10-01T12:29:19","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=63946"},"modified":"2021-10-01T14:29:20","modified_gmt":"2021-10-01T12:29:20","slug":"open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/","title":{"rendered":"Open day Fondazione Bio Campus, si \u00e8 svolta a Fondi la seconda sessione"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Presso la sala convegni del Comune di Fondi si \u00e8 svolta  la seconda sessione del ciclo di \u201cOpen day\u201d della Fondazione Bio Campus, con sede a Latina, per diffondere e condividere le progettualit\u00e0 formative e rispondere alle esigenze di figureprofessionali specifiche degli imprenditori ed all\u2019occupazione di giovani e meno giovani.<br><br>L\u2019iniziativa costituisce un elemento concreto di attenzione, da parte della Fondazione, alterritorio, in termini di valorizzazione delle attivit\u00e0 imprenditoriali e di coinvolgimento di quantisono interessati alla frequenza dei corsi. La Fondazione Biocampus Latina propone corsi biennali di alta formazione per il conseguimento del Diploma di tecnico superiore nel settore agroalimentare e agroindustriale e chimico, con una forte valenza alla finalizzazione degli insegnamenti all\u2019occupazione, attraverso ore in aula, a distanza, visite guidate, attivit\u00e0 di laboratorio,<br>stage in aziende, valide anche per il conseguimento di crediti formativi universitari.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"445\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/carlo-picchi-coldiretti-800x445-1.jpg\" alt=\"\" class=\"wp-image-56683\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/carlo-picchi-coldiretti-800x445-1.jpg 800w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/carlo-picchi-coldiretti-800x445-1-300x167.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/04\/carlo-picchi-coldiretti-800x445-1-768x427.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">Gli interventi<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><br>\u201cAbbiamo posto in essere un\u2019intensa campagna divulgativa \u2013 ha dichiarato il dott. Carlo Picchi, direttore di Coldiretti di latina e Frosinone e Presidente della Fondazione \u2013 per portare i nostri contenuti e le nostre proposte formative al territorio, confidando di attivare un dialogo costante con le istituzione scolastiche, gli imprenditori ed i possibili partecipanti ai corsi\u201d-<br>La riunione \u00e8 stata caratterizzata dalla attenta ed attiva partecipazione, del sindaco di Fondi, di docenti, imprenditori e persone interessate alle diverse proposte formative, che hanno dato vita ad una proficuo approfondimento, sui temi della formazione, delle possibilit\u00e0 occupazionali e delle azioni che gli imprenditori locali, specificamente dell\u2019area agroalimentare e della gastronomia in senso lato, con un\u2019evidenza particolare alla necessit\u00e0 di trattare il tema dell\u2019orientamento in un contesto di tutela e valorizzazione delle persone.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLa Fondazione Biocampus si propone come uno strumento di crescita umana e professionale, ha dichiarato il dott. Bruno D\u2019Aniello, nominato dalla Camera Di Commercio, amministratore dell\u2019azienda Imballaggi D\u2019Aniello di Fondi, che ascolta le istanze degli imprenditori, alla ricerca<br>di figure professionali adeguate ed una possibile risposta alle istanze occupazionali dei cittadini\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Il prossimo open day si terr\u00e0 a Latina, presso la Fondazione, il 6 ottobre.<\/p>\n\n\n","protected":false},"excerpt":{"rendered":"<p>Presso la sala convegni del Comune di Fondi si \u00e8 svolta la seconda sessione del ciclo di \u201cOpen day\u201d della<\/p>\n","protected":false},"author":26,"featured_media":63668,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2236,38],"tags":[13822,2027,1375,513],"class_list":["post-63946","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-attualita","category-scuola","tag-biocampus","tag-carlo-picchi","tag-coldiretti","tag-latina"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Open day Fondazione Bio Campus, si \u00e8 svolta a Fondi la seconda sessione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Open day Fondazione Bio Campus, si \u00e8 svolta a Fondi la seconda sessione\" \/>\n<meta property=\"og:description\" content=\"Presso la sala convegni del Comune di Fondi si \u00e8 svolta la seconda sessione del ciclo di \u201cOpen day\u201d della\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-01T12:29:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-10-01T12:29:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/09\/Fondazione_Bio_Campus1-700x445-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"445\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/01\\\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/01\\\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Open day Fondazione Bio Campus, si \u00e8 svolta a Fondi la seconda sessione\",\"datePublished\":\"2021-10-01T12:29:19+00:00\",\"dateModified\":\"2021-10-01T12:29:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/01\\\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\\\/\"},\"wordCount\":349,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/01\\\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/09\\\/Fondazione_Bio_Campus1-700x445-1.jpg\",\"keywords\":[\"biocampus\",\"carlo picchi\",\"coldiretti\",\"latina\"],\"articleSection\":[\"Attualit\u00e0\",\"Scuola\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/01\\\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/01\\\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\\\/\",\"name\":\"Open day Fondazione Bio Campus, si \u00e8 svolta a Fondi la seconda sessione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/01\\\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/01\\\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/09\\\/Fondazione_Bio_Campus1-700x445-1.jpg\",\"datePublished\":\"2021-10-01T12:29:19+00:00\",\"dateModified\":\"2021-10-01T12:29:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/01\\\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/01\\\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/01\\\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/09\\\/Fondazione_Bio_Campus1-700x445-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/09\\\/Fondazione_Bio_Campus1-700x445-1.jpg\",\"width\":700,\"height\":445},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/01\\\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Open day Fondazione Bio Campus, si \u00e8 svolta a Fondi la seconda sessione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/01\\\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/01\\\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/10\\\/01\\\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Open day Fondazione Bio Campus, si \u00e8 svolta a Fondi la seconda sessione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/","og_locale":"it_IT","og_type":"article","og_title":"Open day Fondazione Bio Campus, si \u00e8 svolta a Fondi la seconda sessione","og_description":"Presso la sala convegni del Comune di Fondi si \u00e8 svolta la seconda sessione del ciclo di \u201cOpen day\u201d della","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-10-01T12:29:19+00:00","article_modified_time":"2021-10-01T12:29:20+00:00","og_image":[{"width":700,"height":445,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/09\/Fondazione_Bio_Campus1-700x445-1.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"2 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Open day Fondazione Bio Campus, si \u00e8 svolta a Fondi la seconda sessione","datePublished":"2021-10-01T12:29:19+00:00","dateModified":"2021-10-01T12:29:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/"},"wordCount":349,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/09\/Fondazione_Bio_Campus1-700x445-1.jpg","keywords":["biocampus","carlo picchi","coldiretti","latina"],"articleSection":["Attualit\u00e0","Scuola"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/","name":"Open day Fondazione Bio Campus, si \u00e8 svolta a Fondi la seconda sessione - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/09\/Fondazione_Bio_Campus1-700x445-1.jpg","datePublished":"2021-10-01T12:29:19+00:00","dateModified":"2021-10-01T12:29:20+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/09\/Fondazione_Bio_Campus1-700x445-1.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/09\/Fondazione_Bio_Campus1-700x445-1.jpg","width":700,"height":445},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Open day Fondazione Bio Campus, si \u00e8 svolta a Fondi la seconda sessione"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/10\/01\/open-day-fondazione-bio-campus-si-e-svolta-a-fondi-la-seconda-sessione\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/63946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=63946"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/63946\/revisions"}],"predecessor-version":[{"id":63947,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/63946\/revisions\/63947"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/63668"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=63946"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=63946"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=63946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}