{"id":633,"date":"2018-10-30T23:09:19","date_gmt":"2018-10-30T22:09:19","guid":{"rendered":"http:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=633"},"modified":"2018-11-01T19:57:19","modified_gmt":"2018-11-01T18:57:19","slug":"segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/","title":{"rendered":"Segneri (M5S): &#8220;Stabilizzeremo i lavoratori con le risorse del progetto Scuole Belle&#8221;"},"content":{"rendered":"<p>&#8220;Utilizzeremo per la stabilizzazione dei lavoratori storici degli appalti dei servizi nelle scuole, le risorse per la proroga del progetto<strong> &#8220;SCUOLE BELLE&#8221;<\/strong>, contenute nella bozza della Legge di Bilancio&#8221;. E quanto dichiara la deputata del MoVimento 5 Stelle<strong> Enrica Segneri<\/strong>.<\/p>\n<p>&#8220;Su questo punto tra Parlamento e Miur c&#8217;\u00e8 piena concordanza: bisogna far uscire dalla precariet\u00e0 i lavoratori delle imprese di pulizia e sicurezza nelle scuole. Il Parlamento &#8211; aggiunge &#8211; ha da poco votato una risoluzione che punta proprio a internalizzare questi servizi. <strong>Un&#8217;iniziativa che reca vantaggio sia ai lavoratori sia allo Stato<\/strong>, che in questo modo spender\u00e0 addirittura di meno per una qualit\u00e0 dei servizi maggiore. Con lo stesso impegno, si proceder\u00e0 in questa direzione con la Legge di Bilancio&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Utilizzeremo per la stabilizzazione dei lavoratori storici degli appalti dei servizi nelle scuole, le risorse per la proroga del progetto<\/p>\n","protected":false},"author":3,"featured_media":638,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,28],"tags":[131,94,274,93,129,130,132],"class_list":["post-633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-politica","tag-cinque","tag-ciociaria","tag-enrica","tag-frosinone","tag-scuole","tag-segneri","tag-stelle"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Segneri (M5S): &quot;Stabilizzeremo i lavoratori con le risorse del progetto Scuole Belle&quot; - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"description\" content=\"L&#039;obiettivo \u00e8 quello di far uscire dalla precariet\u00e0 i lavoratori delle imprese di pulizia e sicurezza. Un&#039;iniziativa che reca vantaggio anche allo Stato\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Segneri (M5S): &quot;Stabilizzeremo i lavoratori con le risorse del progetto Scuole Belle&quot;\" \/>\n<meta property=\"og:description\" content=\"L&#039;obiettivo \u00e8 quello di far uscire dalla precariet\u00e0 i lavoratori delle imprese di pulizia e sicurezza. Un&#039;iniziativa che reca vantaggio anche allo Stato\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/TuNews24\" \/>\n<meta property=\"article:published_time\" content=\"2018-10-30T22:09:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-01T18:57:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/10\/segneri-enrica.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1366\" \/>\n\t<meta property=\"og:image:height\" content=\"911\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Trento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Trento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\\\/\"},\"author\":{\"name\":\"Gianluca Trento\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\"},\"headline\":\"Segneri (M5S): &#8220;Stabilizzeremo i lavoratori con le risorse del progetto Scuole Belle&#8221;\",\"datePublished\":\"2018-10-30T22:09:19+00:00\",\"dateModified\":\"2018-11-01T18:57:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\\\/\"},\"wordCount\":134,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/segneri-enrica.jpg\",\"keywords\":[\"cinque\",\"Ciociaria\",\"enrica\",\"Frosinone\",\"scuole\",\"segneri+\",\"stelle\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2018\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\\\/\",\"name\":\"Segneri (M5S): \\\"Stabilizzeremo i lavoratori con le risorse del progetto Scuole Belle\\\" - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/segneri-enrica.jpg\",\"datePublished\":\"2018-10-30T22:09:19+00:00\",\"dateModified\":\"2018-11-01T18:57:19+00:00\",\"description\":\"L'obiettivo \u00e8 quello di far uscire dalla precariet\u00e0 i lavoratori delle imprese di pulizia e sicurezza. Un'iniziativa che reca vantaggio anche allo Stato\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/segneri-enrica.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2018\\\/10\\\/segneri-enrica.jpg\",\"width\":1366,\"height\":911,\"caption\":\"Enrica Segneri\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Segneri (M5S): &#8220;Stabilizzeremo i lavoratori con le risorse del progetto Scuole Belle&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\",\"name\":\"Gianluca Trento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"caption\":\"Gianluca Trento\"},\"description\":\"Giornalista dei quotidiani online \\\"LaProvinciaQuotidiano.it\\\" e \\\"TuNews24.it\\\" e del settimanale cartaceo \\\"Tu News\\\". In passato \u00e8 stato anche Direttore Editoriale de \\\"La Provincia\\\", Direttore Responsabile del quotidiano \\\"Ciociaria Oggi\\\", Condirettore de \\\"Il quotidiano della Ciociaria\\\", giornalista di \\\"Paese Sera\\\", del settimanale \\\"L\u2019Inchiesta\\\" e del quotidiano online \\\"Il Corriere della Provincia\\\".\",\"sameAs\":[\"https:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/TuNews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/gianluca\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2018\\\/10\\\/30\\\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Segneri (M5S): \"Stabilizzeremo i lavoratori con le risorse del progetto Scuole Belle\" - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","description":"L'obiettivo \u00e8 quello di far uscire dalla precariet\u00e0 i lavoratori delle imprese di pulizia e sicurezza. Un'iniziativa che reca vantaggio anche allo Stato","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/","og_locale":"it_IT","og_type":"article","og_title":"Segneri (M5S): \"Stabilizzeremo i lavoratori con le risorse del progetto Scuole Belle\"","og_description":"L'obiettivo \u00e8 quello di far uscire dalla precariet\u00e0 i lavoratori delle imprese di pulizia e sicurezza. Un'iniziativa che reca vantaggio anche allo Stato","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/TuNews24","article_published_time":"2018-10-30T22:09:19+00:00","article_modified_time":"2018-11-01T18:57:19+00:00","og_image":[{"width":1366,"height":911,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/10\/segneri-enrica.jpg","type":"image\/jpeg"}],"author":"Gianluca Trento","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Gianluca Trento","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/"},"author":{"name":"Gianluca Trento","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd"},"headline":"Segneri (M5S): &#8220;Stabilizzeremo i lavoratori con le risorse del progetto Scuole Belle&#8221;","datePublished":"2018-10-30T22:09:19+00:00","dateModified":"2018-11-01T18:57:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/"},"wordCount":134,"commentCount":0,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/10\/segneri-enrica.jpg","keywords":["cinque","Ciociaria","enrica","Frosinone","scuole","segneri+","stelle"],"articleSection":["*PRIMO PIANO*","Evidenza"],"inLanguage":"it-IT","copyrightYear":"2018","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/","name":"Segneri (M5S): \"Stabilizzeremo i lavoratori con le risorse del progetto Scuole Belle\" - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/10\/segneri-enrica.jpg","datePublished":"2018-10-30T22:09:19+00:00","dateModified":"2018-11-01T18:57:19+00:00","description":"L'obiettivo \u00e8 quello di far uscire dalla precariet\u00e0 i lavoratori delle imprese di pulizia e sicurezza. Un'iniziativa che reca vantaggio anche allo Stato","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/10\/segneri-enrica.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2018\/10\/segneri-enrica.jpg","width":1366,"height":911,"caption":"Enrica Segneri"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Segneri (M5S): &#8220;Stabilizzeremo i lavoratori con le risorse del progetto Scuole Belle&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd","name":"Gianluca Trento","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","caption":"Gianluca Trento"},"description":"Giornalista dei quotidiani online \"LaProvinciaQuotidiano.it\" e \"TuNews24.it\" e del settimanale cartaceo \"Tu News\". In passato \u00e8 stato anche Direttore Editoriale de \"La Provincia\", Direttore Responsabile del quotidiano \"Ciociaria Oggi\", Condirettore de \"Il quotidiano della Ciociaria\", giornalista di \"Paese Sera\", del settimanale \"L\u2019Inchiesta\" e del quotidiano online \"Il Corriere della Provincia\".","sameAs":["https:\/\/www.tunews24.it","http:\/\/www.facebook.com\/TuNews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/gianluca\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2018\/10\/30\/segneri-m5s-stabilizzeremo-i-lavoratori-con-le-risorse-del-progetto-scuole-belle\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=633"}],"version-history":[{"count":5,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/633\/revisions"}],"predecessor-version":[{"id":642,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/633\/revisions\/642"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/638"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}