{"id":62885,"date":"2021-09-07T05:08:11","date_gmt":"2021-09-07T03:08:11","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=62885"},"modified":"2021-09-07T05:08:13","modified_gmt":"2021-09-07T03:08:13","slug":"frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/","title":{"rendered":"Frosinone: pubblicato l&#8217;avviso per i buoni alimentari alle famiglie"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00c8 stato pubblicato l\u2019avviso dell\u2019amministrazione Ottaviani per <strong>l&#8217;erogazione dei buoni alimentari e dei buoni a sostegno delle spese per le utenze domestiche<\/strong> (acqua, luce, gas, telefonia, rifiuti), quali misure urgenti connesse all&#8217;emergenza Covid-19. Il Comune di Frosinone intende, cos\u00ec, rinnovare gli interventi di sostegno economico in favore di famiglie, anche mononucleari, in situazione di contingente indigenza economica derivante dall&#8217;emergenza sociosanitaria.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">I requisiti<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Possono presentare istanza per l\u2019accesso al beneficio i cittadini italiani e i cittadini stranieri non appartenenti all\u2019Unione Europea, con regolare Permesso di soggiorno in corso di validit\u00e0, in possesso dei seguenti requisiti: residenza nel Comune di Frosinone; essere in carico ai Servizi Sociali ovvero trovarsi in una situazione di bisogno a causa e per effetto dell\u2019applicazione delle norme relative al contenimento della epidemia da Covid-19, previa autocertificazione che ne attesti lo stato; avere un ISEE (ordinario, corrente ovvero \u201cminori\u201d in caso di figli di minore et\u00e0 all\u2019interno del nucleo familiare ) di valore uguale o inferiore a 13 mila euro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In caso di famiglie beneficiarie, nel mese di agosto 2021, di Reddito di cittadinanza; Reddito di emergenza; indennit\u00e0 in favore dei lavoratori stagionali o a tempo determinato del turismo, dei lavoratori dello spettacolo, dello sport e dei lavoratori intermittenti ed occasionali; ulteriori indennit\u00e0 connesse ad attivit\u00e0 lavorative da specificare nell\u2019apposito modello di domanda. L&#8217;ammissione al beneficio \u00e8 condizionata alla verifica dello stato di bisogno da parte dei Servizi Sociali competenti. Tutte le domande ammesse saranno sottoposte al controllo dell\u2019Autorit\u00e0 giudiziaria e dei soggetti istituzionalmente preposti allo scopo per il controllo della veridicit\u00e0 di quanto autocertificato.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">I buoni<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Il voucher alimentare, riconosciuto nella forma del buono spesa elettronico e spendibile esclusivamente presso gli operatori economici allo scopo accreditati, avr\u00e0 un valore unitario cos\u00ec determinato: \u20ac 70, per un nucleo composto da una sola persona: \u20ac 140, per un nucleo composto da due adulti; \u20ac 180, per un nucleo composto da un adulto ed un minore; \u20ac 210, per un nucleo composto da tre adulti; \u20ac 250, per nuclei composti da tre persone di cui almeno un minore; \u20ac 350 per nuclei con 4 o pi\u00f9 componenti. Il buono sar\u00e0 valido per l\u2019acquisto di beni di prima necessit\u00e0 (alimenti, prodotti per l\u2019igiene personale e domestica) e non potr\u00e0 essere utilizzato per l&#8217;acquisto di alcolici e superalcolici, alimenti e prodotti per animali, arredi e corredi per la casa, tabacchi, ricariche telefoniche, giochi e lotterie. Ciascun nucleo familiare, come precedentemente individuato, esclusivamente su richiesta, potr\u00e0, inoltre, beneficiare di un Buono a sostegno delle spese per il pagamento delle utenze domestiche (acqua, luce, gas, telefonia, rifiuti). Il valore complessivo sar\u00e0 pari ad \u20ac 50,00 una tantum nella forma del buono spesa elettronico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si precisa che le utenze per le quali si richiede il contributo una tantum devono essere intestate al richiedente e devono essere riferite a pagamenti effettuati nei mesi di luglio\/agosto 2021. Le ricevute dovranno essere allegate in copia alla domanda.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">Come presentare domanda<\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Gli interessati dovranno presentare l\u2019istanza in formato elettronico mediante la piattaforma informatica messa a disposizione dal Comune di Frosinone raggiungibile dal Sito istituzionale www.comune.frosinone.it o collegandosi direttamente al seguente link per i cittadini: <a href=\"https:\/\/voucher.sicare.it\/sicare\/buonispesa_login.php\">https:\/\/voucher.sicare.it\/sicare\/buonispesa_login.php<\/a>. <strong>L\u2019istanza potr\u00e0 essere presentata a partire dalle 9 di luned\u00ec 13 settembre<\/strong> fino a esaurimento delle risorse disponibili.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Non sar\u00e0 possibile presentare domande in formato cartaceo. L\u2019istanza dovr\u00e0 essere presentata solo ed esclusivamente da uno dei componenti del nucleo familiare. Per le domande non correttamente compilate o prive dei documenti obbligatoriamente previsti verr\u00e0 chiesta un&#8217;integrazione documentale, che verr\u00e0 richiesta solo dopo l\u2019analisi delle domande correttamente presentate.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pertanto, le domande pervenute incomplete verranno istruite in coda e fino a esaurimento dei fondi assegnati. Presso lo Sportello per la Famiglia del Comune di Frosinone sar\u00e0 attivo un servizio di supporto telefonico (0775\/2656264), che fornir\u00e0 tutte le informazioni relative alla compilazione online della domanda, dal luned\u00ec al venerd\u00ec, dalle ore 10:00 alle ore 12:00.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Il buono sar\u00e0 spendibile fino al 31 dicembre 2021<\/strong>. La scadenza potr\u00e0 essere prorogata in considerazione di eventuali disposizioni normative nazionali o regionali in tema di gestione dell\u2019emergenza epidemiologica.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il Comune di Frosinone ha pubblicato l&#8217;avviso per i bonus alle famiglie<\/p>\n","protected":false},"author":26,"featured_media":62887,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2236],"tags":[139,9243,94,149,1326,93,5710],"class_list":["post-62885","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-attualita","tag-bando","tag-buoni-alimentari","tag-ciociaria","tag-comune","tag-famiglie","tag-frosinone","tag-voucher"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Frosinone: pubblicato l&#039;avviso per i buoni alimentari alle famiglie - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Frosinone: pubblicato l&#039;avviso per i buoni alimentari alle famiglie\" \/>\n<meta property=\"og:description\" content=\"Il Comune di Frosinone ha pubblicato l&#039;avviso per i bonus alle famiglie\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-07T03:08:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-07T03:08:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/09\/bonus-famiglie.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"679\" \/>\n\t<meta property=\"og:image:height\" content=\"452\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/09\\\/07\\\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/09\\\/07\\\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Frosinone: pubblicato l&#8217;avviso per i buoni alimentari alle famiglie\",\"datePublished\":\"2021-09-07T03:08:11+00:00\",\"dateModified\":\"2021-09-07T03:08:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/09\\\/07\\\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\\\/\"},\"wordCount\":680,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/09\\\/07\\\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/09\\\/bonus-famiglie.jpg\",\"keywords\":[\"bando\",\"buoni alimentari\",\"Ciociaria\",\"comune\",\"famiglie\",\"Frosinone\",\"voucher\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Attualit\u00e0\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/09\\\/07\\\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/09\\\/07\\\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\\\/\",\"name\":\"Frosinone: pubblicato l'avviso per i buoni alimentari alle famiglie - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/09\\\/07\\\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/09\\\/07\\\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/09\\\/bonus-famiglie.jpg\",\"datePublished\":\"2021-09-07T03:08:11+00:00\",\"dateModified\":\"2021-09-07T03:08:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/09\\\/07\\\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/09\\\/07\\\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/09\\\/07\\\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/09\\\/bonus-famiglie.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/09\\\/bonus-famiglie.jpg\",\"width\":679,\"height\":452,\"caption\":\"bonus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/09\\\/07\\\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Frosinone: pubblicato l&#8217;avviso per i buoni alimentari alle famiglie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/09\\\/07\\\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/09\\\/07\\\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/09\\\/07\\\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Frosinone: pubblicato l'avviso per i buoni alimentari alle famiglie - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/","og_locale":"it_IT","og_type":"article","og_title":"Frosinone: pubblicato l'avviso per i buoni alimentari alle famiglie","og_description":"Il Comune di Frosinone ha pubblicato l'avviso per i bonus alle famiglie","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-09-07T03:08:11+00:00","article_modified_time":"2021-09-07T03:08:13+00:00","og_image":[{"width":679,"height":452,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/09\/bonus-famiglie.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"3 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Frosinone: pubblicato l&#8217;avviso per i buoni alimentari alle famiglie","datePublished":"2021-09-07T03:08:11+00:00","dateModified":"2021-09-07T03:08:13+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/"},"wordCount":680,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/09\/bonus-famiglie.jpg","keywords":["bando","buoni alimentari","Ciociaria","comune","famiglie","Frosinone","voucher"],"articleSection":["*PRIMO PIANO*","Attualit\u00e0"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/","name":"Frosinone: pubblicato l'avviso per i buoni alimentari alle famiglie - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/09\/bonus-famiglie.jpg","datePublished":"2021-09-07T03:08:11+00:00","dateModified":"2021-09-07T03:08:13+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/09\/bonus-famiglie.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/09\/bonus-famiglie.jpg","width":679,"height":452,"caption":"bonus"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Frosinone: pubblicato l&#8217;avviso per i buoni alimentari alle famiglie"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/09\/07\/frosinone-pubblicato-lavviso-per-i-buoni-alimentari-alle-famiglie\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/62885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=62885"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/62885\/revisions"}],"predecessor-version":[{"id":62888,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/62885\/revisions\/62888"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/62887"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=62885"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=62885"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=62885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}