{"id":62064,"date":"2021-08-16T16:54:28","date_gmt":"2021-08-16T14:54:28","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=62064"},"modified":"2021-08-16T16:54:29","modified_gmt":"2021-08-16T14:54:29","slug":"incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/","title":{"rendered":"Incendi, Ciacciarelli:  pi\u00f9 competenze ai cacciatori perch\u00e9 vere sentinelle del territorio"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><br>\u201cNelle ultime ore una lingua di fuoco sta attraversando la provincia di Frosinone che sta diventando sempre pi\u00f9 teatro di incendi&#8221;. <strong>Cos\u00ec, in una nota, il consigliere regionale della Lega Lazio Pasquale Ciacciarelli (Lega<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> &#8220;Un ferragosto di fuoco, con le fiamme che sono arrivate a minacciare anche diverse abitazioni del pontecorvese e di altri centri come Piedimonte San Germano. Bisogna assolutamente invertire la rotta e fornire ulteriori competenze a coloro che visitano frequentemente le montagne, come ad esempio i cacciatori, dando loro le competenze e i fondi per la sorveglianza per evitare che il fenomeno assuma in futuro tratti sempre pi\u00f9 preoccupanti.\u201d<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cNelle ultime ore una lingua di fuoco sta attraversando la provincia di Frosinone che sta diventando sempre pi\u00f9 teatro di<\/p>\n","protected":false},"author":26,"featured_media":62065,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[93,3369,295,1336],"class_list":["post-62064","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-frosinone","tag-incendi","tag-lega","tag-pasquale-ciacciarelli"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Incendi, Ciacciarelli: pi\u00f9 competenze ai cacciatori perch\u00e9 vere sentinelle del territorio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incendi, Ciacciarelli: pi\u00f9 competenze ai cacciatori perch\u00e9 vere sentinelle del territorio\" \/>\n<meta property=\"og:description\" content=\"\u201cNelle ultime ore una lingua di fuoco sta attraversando la provincia di Frosinone che sta diventando sempre pi\u00f9 teatro di\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-16T14:54:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-16T14:54:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0007.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"466\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Incendi, Ciacciarelli: pi\u00f9 competenze ai cacciatori perch\u00e9 vere sentinelle del territorio\",\"datePublished\":\"2021-08-16T14:54:28+00:00\",\"dateModified\":\"2021-08-16T14:54:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\\\/\"},\"wordCount\":113,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/IMG-20210816-WA0007.jpg\",\"keywords\":[\"Frosinone\",\"incendi\",\"Lega\",\"pasquale ciacciarelli\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\\\/\",\"name\":\"Incendi, Ciacciarelli: pi\u00f9 competenze ai cacciatori perch\u00e9 vere sentinelle del territorio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/IMG-20210816-WA0007.jpg\",\"datePublished\":\"2021-08-16T14:54:28+00:00\",\"dateModified\":\"2021-08-16T14:54:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/IMG-20210816-WA0007.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/IMG-20210816-WA0007.jpg\",\"width\":960,\"height\":466},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incendi, Ciacciarelli: pi\u00f9 competenze ai cacciatori perch\u00e9 vere sentinelle del territorio\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Incendi, Ciacciarelli: pi\u00f9 competenze ai cacciatori perch\u00e9 vere sentinelle del territorio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/","og_locale":"it_IT","og_type":"article","og_title":"Incendi, Ciacciarelli: pi\u00f9 competenze ai cacciatori perch\u00e9 vere sentinelle del territorio","og_description":"\u201cNelle ultime ore una lingua di fuoco sta attraversando la provincia di Frosinone che sta diventando sempre pi\u00f9 teatro di","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-08-16T14:54:28+00:00","article_modified_time":"2021-08-16T14:54:29+00:00","og_image":[{"width":960,"height":466,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0007.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Incendi, Ciacciarelli: pi\u00f9 competenze ai cacciatori perch\u00e9 vere sentinelle del territorio","datePublished":"2021-08-16T14:54:28+00:00","dateModified":"2021-08-16T14:54:29+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/"},"wordCount":113,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0007.jpg","keywords":["Frosinone","incendi","Lega","pasquale ciacciarelli"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/","name":"Incendi, Ciacciarelli: pi\u00f9 competenze ai cacciatori perch\u00e9 vere sentinelle del territorio - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0007.jpg","datePublished":"2021-08-16T14:54:28+00:00","dateModified":"2021-08-16T14:54:29+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0007.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0007.jpg","width":960,"height":466},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Incendi, Ciacciarelli: pi\u00f9 competenze ai cacciatori perch\u00e9 vere sentinelle del territorio"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-ciacciarelli-piu-competenze-ai-cacciatori-perche-vere-sentinelle-del-territorio\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/62064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=62064"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/62064\/revisions"}],"predecessor-version":[{"id":62066,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/62064\/revisions\/62066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/62065"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=62064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=62064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=62064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}