{"id":62058,"date":"2021-08-16T15:29:51","date_gmt":"2021-08-16T13:29:51","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=62058"},"modified":"2021-08-16T15:31:42","modified_gmt":"2021-08-16T13:31:42","slug":"democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/","title":{"rendered":"Democratiche per Frosinone, donne e bambini da salvare: sostegno a petizione per corridoi umanitari per gli afgani"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">&#8220;<strong>Le donne come kaniz (merce). Questa \u00e8 la rigida interpretazione dell&#8217;islam per i talebani<\/strong>. Dopo 20 anni sta accadendo di nuovo.Le donne che si sono suicidate all &#8216;arrivo degli eserciti a Kabul lo sapevano bene.&#8221; <strong>Cos\u00ec 5arah Griego,<br>Portavoce Democratiche provinciale di Frosinone. <\/strong><\/p>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Cosi&#8217; come lo sanno tutte quelle dai 12 ai 45 anni, il cui nominativo \u00e8 stato inserito negli elenchi da consegnare ai comandanti come bottino di guerra.In queste ore di orrore, come donne e Democratiche della provincia di Frosinone, seguiamo con grande preoccupazione la loro sorte e quella di tutto il popolo Afghano. Non ci si pu\u00f2 voltare dall&#8217;altra parte.Vanno aiutate ad uscire da quell&#8217;incubo, assieme ai loro figli. Per questo sosteniamo con forza la petizione per creare subito corridoi umanitari internazionali per mettere in salvo le donne afghane e i loro bambini, cos\u00ec come i bambini degli orfanotrofi di tutte le citt\u00e0 cadute in mano ai talebani.Bisogna agire prestto&#8221;. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Le donne come kaniz (merce). Questa \u00e8 la rigida interpretazione dell&#8217;islam per i talebani. Dopo 20 anni sta accadendo di<\/p>\n","protected":false},"author":3,"featured_media":7937,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[28],"tags":[13604,94,93,98,13603],"class_list":["post-62058","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-politica","tag-afganistan","tag-ciociaria","tag-frosinone","tag-pd","tag-sara-grieco"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Democratiche per Frosinone, donne e bambini da salvare: sostegno a petizione per corridoi umanitari per gli afgani - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Democratiche per Frosinone, donne e bambini da salvare: sostegno a petizione per corridoi umanitari per gli afgani\" \/>\n<meta property=\"og:description\" content=\"&#8220;Le donne come kaniz (merce). Questa \u00e8 la rigida interpretazione dell&#8217;islam per i talebani. Dopo 20 anni sta accadendo di\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:author\" content=\"http:\/\/www.facebook.com\/TuNews24\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-16T13:29:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-16T13:31:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Sarah-Grieco.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"543\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Gianluca Trento\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gianluca Trento\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\\\/\"},\"author\":{\"name\":\"Gianluca Trento\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\"},\"headline\":\"Democratiche per Frosinone, donne e bambini da salvare: sostegno a petizione per corridoi umanitari per gli afgani\",\"datePublished\":\"2021-08-16T13:29:51+00:00\",\"dateModified\":\"2021-08-16T13:31:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\\\/\"},\"wordCount\":174,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/Sarah-Grieco.jpeg\",\"keywords\":[\"Afganistan\",\"Ciociaria\",\"Frosinone\",\"Pd\",\"Sara grieco\"],\"articleSection\":[\"Evidenza\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\\\/\",\"name\":\"Democratiche per Frosinone, donne e bambini da salvare: sostegno a petizione per corridoi umanitari per gli afgani - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/Sarah-Grieco.jpeg\",\"datePublished\":\"2021-08-16T13:29:51+00:00\",\"dateModified\":\"2021-08-16T13:31:42+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/Sarah-Grieco.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2019\\\/03\\\/Sarah-Grieco.jpeg\",\"width\":800,\"height\":543,\"caption\":\"Sarah-Grieco\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Democratiche per Frosinone, donne e bambini da salvare: sostegno a petizione per corridoi umanitari per gli afgani\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/61ad8468fc64fa3e36d950057c9c2cbd\",\"name\":\"Gianluca Trento\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g\",\"caption\":\"Gianluca Trento\"},\"description\":\"Giornalista dei quotidiani online \\\"LaProvinciaQuotidiano.it\\\" e \\\"TuNews24.it\\\" e del settimanale cartaceo \\\"Tu News\\\". In passato \u00e8 stato anche Direttore Editoriale de \\\"La Provincia\\\", Direttore Responsabile del quotidiano \\\"Ciociaria Oggi\\\", Condirettore de \\\"Il quotidiano della Ciociaria\\\", giornalista di \\\"Paese Sera\\\", del settimanale \\\"L\u2019Inchiesta\\\" e del quotidiano online \\\"Il Corriere della Provincia\\\".\",\"sameAs\":[\"https:\\\/\\\/www.tunews24.it\",\"http:\\\/\\\/www.facebook.com\\\/TuNews24\"],\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/gianluca\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Democratiche per Frosinone, donne e bambini da salvare: sostegno a petizione per corridoi umanitari per gli afgani - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/","og_locale":"it_IT","og_type":"article","og_title":"Democratiche per Frosinone, donne e bambini da salvare: sostegno a petizione per corridoi umanitari per gli afgani","og_description":"&#8220;Le donne come kaniz (merce). Questa \u00e8 la rigida interpretazione dell&#8217;islam per i talebani. Dopo 20 anni sta accadendo di","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_author":"http:\/\/www.facebook.com\/TuNews24","article_published_time":"2021-08-16T13:29:51+00:00","article_modified_time":"2021-08-16T13:31:42+00:00","og_image":[{"width":800,"height":543,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Sarah-Grieco.jpeg","type":"image\/jpeg"}],"author":"Gianluca Trento","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Gianluca Trento","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/"},"author":{"name":"Gianluca Trento","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd"},"headline":"Democratiche per Frosinone, donne e bambini da salvare: sostegno a petizione per corridoi umanitari per gli afgani","datePublished":"2021-08-16T13:29:51+00:00","dateModified":"2021-08-16T13:31:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/"},"wordCount":174,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Sarah-Grieco.jpeg","keywords":["Afganistan","Ciociaria","Frosinone","Pd","Sara grieco"],"articleSection":["Evidenza"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/","name":"Democratiche per Frosinone, donne e bambini da salvare: sostegno a petizione per corridoi umanitari per gli afgani - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Sarah-Grieco.jpeg","datePublished":"2021-08-16T13:29:51+00:00","dateModified":"2021-08-16T13:31:42+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Sarah-Grieco.jpeg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2019\/03\/Sarah-Grieco.jpeg","width":800,"height":543,"caption":"Sarah-Grieco"},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Democratiche per Frosinone, donne e bambini da salvare: sostegno a petizione per corridoi umanitari per gli afgani"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/61ad8468fc64fa3e36d950057c9c2cbd","name":"Gianluca Trento","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/8c3ab5f4c6ed6f32f95ece33488c4ec55733fd2c584ad602d0b29746892705ab?s=96&d=mm&r=g","caption":"Gianluca Trento"},"description":"Giornalista dei quotidiani online \"LaProvinciaQuotidiano.it\" e \"TuNews24.it\" e del settimanale cartaceo \"Tu News\". In passato \u00e8 stato anche Direttore Editoriale de \"La Provincia\", Direttore Responsabile del quotidiano \"Ciociaria Oggi\", Condirettore de \"Il quotidiano della Ciociaria\", giornalista di \"Paese Sera\", del settimanale \"L\u2019Inchiesta\" e del quotidiano online \"Il Corriere della Provincia\".","sameAs":["https:\/\/www.tunews24.it","http:\/\/www.facebook.com\/TuNews24"],"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/gianluca\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/democratiche-per-frosinone-donne-e-bambini-da-salvare-sostegno-a-petizione-per-corridoi-umanitari-per-gli-afgani\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/62058","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=62058"}],"version-history":[{"count":2,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/62058\/revisions"}],"predecessor-version":[{"id":62061,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/62058\/revisions\/62061"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/7937"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=62058"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=62058"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=62058"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}