{"id":62050,"date":"2021-08-16T14:32:29","date_gmt":"2021-08-16T12:32:29","guid":{"rendered":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?p=62050"},"modified":"2021-08-16T15:35:21","modified_gmt":"2021-08-16T13:35:21","slug":"incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco","status":"publish","type":"post","link":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/","title":{"rendered":"Incendi nel Cassinate, la dura presa di posizione di Giuseppe Sacco:"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"><strong>Dramma incendi, il sindaco di Roccasecca Giuseppe Sacco<\/strong>, interviene a sostegno delle<br>comunit\u00e0 colpite.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0001-1024x576.jpg\" alt=\"\" class=\"wp-image-62052\" srcset=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0001-1024x576.jpg 1024w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0001-300x169.jpg 300w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0001-768x432.jpg 768w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0001-1536x864.jpg 1536w, https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0001.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h3 class=\"wp-block-heading\">L&#8217;intervento <\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"> &#8220;<strong>Il dramma vissuto ieri dai residenti di Piedimonte San Germano e Colle<br>San Magno \u00e8 anche il nostro dramma. Perch\u00e9 Roccasecca pi\u00f9 volte ha pagato<br>pesantemente in termini di ambiente<\/strong> e economia la scelleratezza di chi, senza alcuna moralit\u00e0, appicca incendi. Non posso non esprimere la piena solidariet\u00e0 alle comunit\u00e0 pesantemente colpite dai roghi di questi giorni e non posso non mettere a disposizione i nostri mezzi e la nostra Protezione Civile l\u00ec dove se ne dovesse presentare la necessit\u00e0&#8221;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">.<br>&#8220;Solo con un lavoro di squadra, riprendendo l&#8217;appello fatto da sua eccellenza il prefetto di<br>Frosinone Ignazio portelli, potremmo porre fine allo scempio che &#8216;persone malvagie e<br>crudeli&#8217; stanno compiendo a nostro scapito ed a scapito nostra bellissima terra&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dramma incendi, il sindaco di Roccasecca Giuseppe Sacco, interviene a sostegno dellecomunit\u00e0 colpite. L&#8217;intervento &#8220;Il dramma vissuto ieri dai residenti<\/p>\n","protected":false},"author":26,"featured_media":62051,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,2],"tags":[94,93,2413,3369,1599],"class_list":["post-62050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-primo-piano","category-cronaca","tag-ciociaria","tag-frosinone","tag-giuseppe-sacco","tag-incendi","tag-roccasecca"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.8 (Yoast SEO v27.8) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Incendi nel Cassinate, la dura presa di posizione di Giuseppe Sacco: - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incendi nel Cassinate, la dura presa di posizione di Giuseppe Sacco:\" \/>\n<meta property=\"og:description\" content=\"Dramma incendi, il sindaco di Roccasecca Giuseppe Sacco, interviene a sostegno dellecomunit\u00e0 colpite. L&#8217;intervento &#8220;Il dramma vissuto ieri dai residenti\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/\" \/>\n<meta property=\"og:site_name\" content=\"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-16T12:32:29+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-16T13:35:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0003.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"739\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"REDAZIONE LaProvinciaQuotidiano.it\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\\\/\"},\"author\":{\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\"},\"headline\":\"Incendi nel Cassinate, la dura presa di posizione di Giuseppe Sacco:\",\"datePublished\":\"2021-08-16T12:32:29+00:00\",\"dateModified\":\"2021-08-16T13:35:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\\\/\"},\"wordCount\":141,\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/IMG-20210816-WA0003.jpg\",\"keywords\":[\"Ciociaria\",\"Frosinone\",\"Giuseppe Sacco\",\"incendi\",\"Roccasecca\"],\"articleSection\":[\"*PRIMO PIANO*\",\"Cronaca\"],\"inLanguage\":\"it-IT\",\"copyrightYear\":\"2021\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\\\/\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\\\/\",\"name\":\"Incendi nel Cassinate, la dura presa di posizione di Giuseppe Sacco: - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/IMG-20210816-WA0003.jpg\",\"datePublished\":\"2021-08-16T12:32:29+00:00\",\"dateModified\":\"2021-08-16T13:35:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/IMG-20210816-WA0003.jpg\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2021\\\/08\\\/IMG-20210816-WA0003.jpg\",\"width\":1600,\"height\":739},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incendi nel Cassinate, la dura presa di posizione di Giuseppe Sacco:\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#website\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"name\":\"Il Corriere Delle Provincia\",\"description\":\"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":[\"Organization\",\"Place\"],\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#organization\",\"name\":\"Globalpress s.r.l.\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/\",\"logo\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\\\/#local-main-organization-logo\"},\"image\":{\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\\\/#local-main-organization-logo\"},\"telephone\":[],\"openingHoursSpecification\":[{\"@type\":\"OpeningHoursSpecification\",\"dayOfWeek\":[\"Monday\",\"Tuesday\",\"Wednesday\",\"Thursday\",\"Friday\",\"Saturday\",\"Sunday\"],\"opens\":\"09:00\",\"closes\":\"17:00\"}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/#\\\/schema\\\/person\\\/1835170ef005036a87455edae6571822\",\"name\":\"REDAZIONE LaProvinciaQuotidiano.it\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g\",\"caption\":\"REDAZIONE LaProvinciaQuotidiano.it\"},\"description\":\"Seguici anche su Telegram: CLICCA QUI\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/author\\\/redazione\\\/\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/2021\\\/08\\\/16\\\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\\\/#local-main-organization-logo\",\"url\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"contentUrl\":\"https:\\\/\\\/www.tunews24.it\\\/ilcorrieredellaprovincia\\\/wp-content\\\/uploads\\\/sites\\\/2\\\/2022\\\/11\\\/cropped-il-corriere-della-provincia-testata-web-scontornata.png\",\"width\":2911,\"height\":717,\"caption\":\"Globalpress s.r.l.\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Incendi nel Cassinate, la dura presa di posizione di Giuseppe Sacco: - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/","og_locale":"it_IT","og_type":"article","og_title":"Incendi nel Cassinate, la dura presa di posizione di Giuseppe Sacco:","og_description":"Dramma incendi, il sindaco di Roccasecca Giuseppe Sacco, interviene a sostegno dellecomunit\u00e0 colpite. L&#8217;intervento &#8220;Il dramma vissuto ieri dai residenti","og_url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/","og_site_name":"IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","article_published_time":"2021-08-16T12:32:29+00:00","article_modified_time":"2021-08-16T13:35:21+00:00","og_image":[{"width":1600,"height":739,"url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0003.jpg","type":"image\/jpeg"}],"author":"REDAZIONE LaProvinciaQuotidiano.it","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"REDAZIONE LaProvinciaQuotidiano.it","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/#article","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/"},"author":{"name":"REDAZIONE LaProvinciaQuotidiano.it","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822"},"headline":"Incendi nel Cassinate, la dura presa di posizione di Giuseppe Sacco:","datePublished":"2021-08-16T12:32:29+00:00","dateModified":"2021-08-16T13:35:21+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/"},"wordCount":141,"publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0003.jpg","keywords":["Ciociaria","Frosinone","Giuseppe Sacco","incendi","Roccasecca"],"articleSection":["*PRIMO PIANO*","Cronaca"],"inLanguage":"it-IT","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/www.tunews24.it\/#organization"}},{"@type":"WebPage","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/","name":"Incendi nel Cassinate, la dura presa di posizione di Giuseppe Sacco: - IlCorriereDellaProvincia.it - News h24 e notizie di approfondimento","isPartOf":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/#primaryimage"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/#primaryimage"},"thumbnailUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0003.jpg","datePublished":"2021-08-16T12:32:29+00:00","dateModified":"2021-08-16T13:35:21+00:00","breadcrumb":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/#primaryimage","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0003.jpg","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2021\/08\/IMG-20210816-WA0003.jpg","width":1600,"height":739},{"@type":"BreadcrumbList","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/"},{"@type":"ListItem","position":2,"name":"Incendi nel Cassinate, la dura presa di posizione di Giuseppe Sacco:"}]},{"@type":"WebSite","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#website","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","name":"Il Corriere Delle Provincia","description":"IlCorriereDellaProvincia.it, quotidiano web di politica, cronaca, inchiesta, lavoro, scuola, turismo, cultura e spettacolo, economia e finanza, salute e benessere. Approfondimenti e notizie aggiornate con foto e video della provincia di Frosinone ma anche news nazionali, dell\u2019Italia e del Mondo.","publisher":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":["Organization","Place"],"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#organization","name":"Globalpress s.r.l.","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/","logo":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/#local-main-organization-logo"},"image":{"@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/#local-main-organization-logo"},"telephone":[],"openingHoursSpecification":[{"@type":"OpeningHoursSpecification","dayOfWeek":["Monday","Tuesday","Wednesday","Thursday","Friday","Saturday","Sunday"],"opens":"09:00","closes":"17:00"}]},{"@type":"Person","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/#\/schema\/person\/1835170ef005036a87455edae6571822","name":"REDAZIONE LaProvinciaQuotidiano.it","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/38a062f668d575d1287faf795d85e6958e595ed693e6bd45aa886f5041703d69?s=96&d=mm&r=g","caption":"REDAZIONE LaProvinciaQuotidiano.it"},"description":"Seguici anche su Telegram: CLICCA QUI","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/author\/redazione\/"},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/2021\/08\/16\/incendi-nel-cassinate-la-dura-presa-di-posizione-di-giuseppe-sacco\/#local-main-organization-logo","url":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","contentUrl":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-content\/uploads\/sites\/2\/2022\/11\/cropped-il-corriere-della-provincia-testata-web-scontornata.png","width":2911,"height":717,"caption":"Globalpress s.r.l."}]}},"_links":{"self":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/62050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/comments?post=62050"}],"version-history":[{"count":1,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/62050\/revisions"}],"predecessor-version":[{"id":62053,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/posts\/62050\/revisions\/62053"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media\/62051"}],"wp:attachment":[{"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/media?parent=62050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/categories?post=62050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tunews24.it\/ilcorrieredellaprovincia\/wp-json\/wp\/v2\/tags?post=62050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}